{"id":96,"date":"2004-02-29T11:49:40","date_gmt":"2004-02-29T19:49:40","guid":{"rendered":"https:\/\/uruloki.org\/felipeblog\/?p=96"},"modified":"2004-02-29T11:49:40","modified_gmt":"2004-02-29T19:49:40","slug":"la-alfombra-roja-ya-est-presta-y-dispuesta","status":"publish","type":"post","link":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-alfombra-roja-ya-est-presta-y-dispuesta","title":{"rendered":"La alfombra roja ya est&aacute; presta y dispuesta&#8230;"},"content":{"rendered":"<p>Ya est&aacute; todo listo para la 76 edici&oacute;n de los Oscar&reg;. En la quiniela montada desde Uruloki.org hemos contado con la incre&iacute;ble cifra de 53 participantes! Muchos se han quedado fuera y pese a las presiones se ha decidido mantener la igualdad para todos y no ampliar el plazo, adem&aacute;s la fecha l&iacute;mite estaba establecida desde el primer d&iacute;a. <br \/><img loading=\"lazy\" decoding=\"async\" alt=\"P&oacute;ster del a&ntilde;o 2004\" title=\"P&oacute;ster del a&ntilde;o 2004\" src=\"https:\/\/uruloki.org\/felipeblog\/imagenes\/poster_76.gif\" width=\"244\" height=\"362\" border=\"1\" \/><br \/>Aqu&iacute; ten&eacute;is el p&oacute;ster oficial de la ceremonia de este a&ntilde;o, dise&ntilde;ado por el pop-artist Burton Morris. No sab&iacute;a yo que hay p&oacute;sters oficiales, pero en estos enlaces pod&eacute;is ver algunos de los a&ntilde;os anteriores: <a href=\"https:\/\/uruloki.org\/felipeblog\/imagenes\/poster_awards_2003.html\" onclick=\"window.open('https:\/\/uruloki.org\/felipeblog\/imagenes\/poster_awards_2003.html','popup','width=244,height=360,scrollbars=no,resizable=no,toolbar=no,directories=no,location=no,menubar=no,status=no,left=0,top=0'); return false\" title=\"P&oacute;ster del a&ntilde;o 2003\">2003<\/a>, <a href=\"https:\/\/uruloki.org\/felipeblog\/imagenes\/poster_awards_2002.html\" onclick=\"window.open('https:\/\/uruloki.org\/felipeblog\/imagenes\/poster_awards_2002.html','popup','width=262,height=385,scrollbars=no,resizable=no,toolbar=no,directories=no,location=no,menubar=no,status=no,left=0,top=0'); return false\" title=\"P&oacute;ster del a&ntilde;o 2002\">2002<\/a>, <a href=\"https:\/\/uruloki.org\/felipeblog\/imagenes\/poster_awards_2001.html\" onclick=\"window.open('https:\/\/uruloki.org\/felipeblog\/imagenes\/poster_awards_2001.html','popup','width=187,height=273,scrollbars=no,resizable=no,toolbar=no,directories=no,location=no,menubar=no,status=no,left=0,top=0'); return false\" title=\"P&oacute;ster del a&ntilde;o 2001\">2001<\/a> y <a href=\"https:\/\/uruloki.org\/felipeblog\/imagenes\/poster_awards_2000.html\" onclick=\"window.open('https:\/\/uruloki.org\/felipeblog\/imagenes\/poster_awards_2000.html','popup','width=177,height=232,scrollbars=no,resizable=no,toolbar=no,directories=no,location=no,menubar=no,status=no,left=0,top=0'); return false\" title=\"P&oacute;ster del a&ntilde;o 2000\">2000<\/a>.<br \/>Ahora la duda que le queda a todo el mundo, &iquest;porqu&eacute; no montan la ceremonia un viernes por la noche o un s&aacute;bado? No se cuantos de vosotros vais a verla en directo pero el lunes hay que trabajar!<br \/>Un saludo y suerte!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya est&aacute; todo listo para la 76 edici&oacute;n de los Oscar&reg;. En la quiniela montada desde Uruloki.org hemos contado con la incre&iacute;ble cifra de 53 participantes! Muchos se han quedado fuera y pese a las presiones se ha decidido mantener la igualdad para todos y no ampliar el plazo, adem&aacute;s la fecha l&iacute;mite estaba establecida [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"class_list":["post-96","post","type-post","status-publish","format-standard","hentry","category-cine"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La alfombra roja ya est&aacute; presta y dispuesta... - Uruloki :: Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-alfombra-roja-ya-est-presta-y-dispuesta\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La alfombra roja ya est&aacute; presta y dispuesta... - Uruloki :: Blog\" \/>\n<meta property=\"og:description\" content=\"Ya est&aacute; todo listo para la 76 edici&oacute;n de los Oscar&reg;. En la quiniela montada desde Uruloki.org hemos contado con la incre&iacute;ble cifra de 53 participantes! Muchos se han quedado fuera y pese a las presiones se ha decidido mantener la igualdad para todos y no ampliar el plazo, adem&aacute;s la fecha l&iacute;mite estaba establecida [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-alfombra-roja-ya-est-presta-y-dispuesta\" \/>\n<meta property=\"og:site_name\" content=\"Uruloki :: Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uruloki.org\" \/>\n<meta property=\"article:published_time\" content=\"2004-02-29T19:49:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uruloki.org\/felipeblog\/imagenes\/poster_76.gif\" \/>\n<meta name=\"author\" content=\"Uruloki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uruloki\" \/>\n<meta name=\"twitter:site\" content=\"@uruloki\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Uruloki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-alfombra-roja-ya-est-presta-y-dispuesta#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-alfombra-roja-ya-est-presta-y-dispuesta\"},\"author\":{\"name\":\"Uruloki\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"headline\":\"La alfombra roja ya est&aacute; presta y dispuesta&#8230;\",\"datePublished\":\"2004-02-29T19:49:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-alfombra-roja-ya-est-presta-y-dispuesta\"},\"wordCount\":179,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-alfombra-roja-ya-est-presta-y-dispuesta#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagenes\\\/poster_76.gif\",\"articleSection\":[\"Cine\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-alfombra-roja-ya-est-presta-y-dispuesta#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-alfombra-roja-ya-est-presta-y-dispuesta\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-alfombra-roja-ya-est-presta-y-dispuesta\",\"name\":\"La alfombra roja ya est&aacute; presta y dispuesta... - Uruloki :: Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-alfombra-roja-ya-est-presta-y-dispuesta#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-alfombra-roja-ya-est-presta-y-dispuesta#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagenes\\\/poster_76.gif\",\"datePublished\":\"2004-02-29T19:49:40+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-alfombra-roja-ya-est-presta-y-dispuesta#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-alfombra-roja-ya-est-presta-y-dispuesta\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-alfombra-roja-ya-est-presta-y-dispuesta#primaryimage\",\"url\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagenes\\\/poster_76.gif\",\"contentUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagenes\\\/poster_76.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-alfombra-roja-ya-est-presta-y-dispuesta#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La alfombra roja ya est&aacute; presta y dispuesta&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/\",\"name\":\"Uruloki :: Blog\",\"description\":\"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\",\"name\":\"Uruloki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"caption\":\"Uruloki\"},\"sameAs\":[\"https:\\\/\\\/uruloki.org\"],\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/author\\\/admin-2-2-2\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La alfombra roja ya est&aacute; presta y dispuesta... - Uruloki :: Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-alfombra-roja-ya-est-presta-y-dispuesta","og_locale":"es_ES","og_type":"article","og_title":"La alfombra roja ya est&aacute; presta y dispuesta... - Uruloki :: Blog","og_description":"Ya est&aacute; todo listo para la 76 edici&oacute;n de los Oscar&reg;. En la quiniela montada desde Uruloki.org hemos contado con la incre&iacute;ble cifra de 53 participantes! Muchos se han quedado fuera y pese a las presiones se ha decidido mantener la igualdad para todos y no ampliar el plazo, adem&aacute;s la fecha l&iacute;mite estaba establecida [&hellip;]","og_url":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-alfombra-roja-ya-est-presta-y-dispuesta","og_site_name":"Uruloki :: Blog","article_publisher":"https:\/\/www.facebook.com\/uruloki.org","article_published_time":"2004-02-29T19:49:40+00:00","og_image":[{"url":"https:\/\/uruloki.org\/felipeblog\/imagenes\/poster_76.gif","type":"","width":"","height":""}],"author":"Uruloki","twitter_card":"summary_large_image","twitter_creator":"@uruloki","twitter_site":"@uruloki","twitter_misc":{"Escrito por":"Uruloki","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-alfombra-roja-ya-est-presta-y-dispuesta#article","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-alfombra-roja-ya-est-presta-y-dispuesta"},"author":{"name":"Uruloki","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"headline":"La alfombra roja ya est&aacute; presta y dispuesta&#8230;","datePublished":"2004-02-29T19:49:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-alfombra-roja-ya-est-presta-y-dispuesta"},"wordCount":179,"commentCount":2,"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-alfombra-roja-ya-est-presta-y-dispuesta#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/imagenes\/poster_76.gif","articleSection":["Cine"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uruloki.org\/felipeblog\/cine\/la-alfombra-roja-ya-est-presta-y-dispuesta#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-alfombra-roja-ya-est-presta-y-dispuesta","url":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-alfombra-roja-ya-est-presta-y-dispuesta","name":"La alfombra roja ya est&aacute; presta y dispuesta... - Uruloki :: Blog","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-alfombra-roja-ya-est-presta-y-dispuesta#primaryimage"},"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-alfombra-roja-ya-est-presta-y-dispuesta#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/imagenes\/poster_76.gif","datePublished":"2004-02-29T19:49:40+00:00","author":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"breadcrumb":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-alfombra-roja-ya-est-presta-y-dispuesta#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uruloki.org\/felipeblog\/cine\/la-alfombra-roja-ya-est-presta-y-dispuesta"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-alfombra-roja-ya-est-presta-y-dispuesta#primaryimage","url":"https:\/\/uruloki.org\/felipeblog\/imagenes\/poster_76.gif","contentUrl":"https:\/\/uruloki.org\/felipeblog\/imagenes\/poster_76.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-alfombra-roja-ya-est-presta-y-dispuesta#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uruloki.org\/felipeblog"},{"@type":"ListItem","position":2,"name":"La alfombra roja ya est&aacute; presta y dispuesta&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.uruloki.org\/felipeblog\/#website","url":"https:\/\/www.uruloki.org\/felipeblog\/","name":"Uruloki :: Blog","description":"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uruloki.org\/felipeblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3","name":"Uruloki","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","caption":"Uruloki"},"sameAs":["https:\/\/uruloki.org"],"url":"https:\/\/www.uruloki.org\/felipeblog\/author\/admin-2-2-2"}]}},"_links":{"self":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/96","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/comments?post=96"}],"version-history":[{"count":0,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/96\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/media?parent=96"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/categories?post=96"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/tags?post=96"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}