{"id":9058,"date":"2012-11-14T20:37:26","date_gmt":"2012-11-14T19:37:26","guid":{"rendered":"https:\/\/uruloki.org\/felipeblog\/?p=9058"},"modified":"2012-11-14T20:37:26","modified_gmt":"2012-11-14T19:37:26","slug":"y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri","status":"publish","type":"post","link":"https:\/\/www.uruloki.org\/felipeblog\/cine\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri","title":{"rendered":"Y otra candidata m&aacute;s para Star Wars: Episode VII, ahora es el turno de Brenda Chapman, Christopher McQuarrie apunta a director de Mission: Impossible 5, cartel definitivo de The Last Stand, primer vistazo a Lily Collins en Cazadores de Sombras: Ciudad de Hueso y as&iacute; luce Malekith y su ej&eacute;rcito de elfos oscuros en Thor: The Dark World&#8230;"},"content":{"rendered":"<p>La verdad, comienzo a sentir eso de que si un d&iacute;a no se habla de <a href=\"http:\/\/www.imdb.es\/title\/tt2488496\/\" target=\"_blank\">Star Wars: Episode VII<\/a> (2015) pues no es d&iacute;a ni es nada. Creo que deber&iacute;amos iniciar una cuenta para anotar todos los rumores y comentarios que surgen en torno al regreso a la gran pantalla de la famosa saga parida por <a href=\"http:\/\/www.imdb.es\/name\/nm0000184\/\" target=\"_blank\">George Lucas<\/a>. Hoy <a href=\"http:\/\/www.bleedingcool.com\/2012\/11\/13\/star-wars-to-be-directed-by-former-pixarian-brenda-chapman-heres-some-evidence\/\" target=\"_blank\">Bleeding Cool, con gran apoyo de \/Films, nos descubre un tema curioso y puede que con algo de raz&oacute;n<\/a>. Resulta que <a href=\"http:\/\/www.slashfilm.com\/original-brave-director-brenda-chapman-leaves-pixar-lucasfilm-consulting-mystery-project\/\" target=\"_blank\">el pasado mes de agosto<\/a> la co-directora <a href=\"http:\/\/www.imdb.es\/name\/nm0152312\/\" target=\"_blank\">Brenda Chapman<\/a>, responsable de <a href=\"http:\/\/www.imdb.es\/title\/tt1217209\/\" target=\"_blank\">Brave<\/a> (2012) para <strong>Pixar<\/strong>, fich&oacute; por <strong>Lucasfilm<\/strong> para hacerse cargo de un misterioso proyecto del que no ha trascendido nada. Pero esta pasada madrugada surgieron unos <em>tweets<\/em> desde la cuenta de la <strong>Chapman<\/strong> en respuesta a preguntas de los fans relacionadas con una art&iacute;culo de la revista <strong>Time<\/strong>, un art&iacute;culo curiosidades de la vida, sobre <strong>Star Wars<\/strong> y 10 sugerencias de cara a dirigir el film. Por el tono de sus comentarios, da la sensaci&oacute;n de que la <strong>Chapman<\/strong> no descarta el trabajo de direcci&oacute;n, y digo yo&#8230; si ha sido co-directora de <strong>Brave<\/strong>, &iquest;ser&iacute;a posible que <strong>Lucasfilm<\/strong> nos sorprendiera con una co-direcci&oacute;n para <strong>Star Wars: Episode VII<\/strong>? Tengamos en cuenta que <a href=\"https:\/\/uruloki.org\/felipeblog\/cine-de-ciencia-ficcin\/al-final-los-mayas-van-a-tener-razn-y-si-darth-vader-reviviera-en-star-wars-episode-vii-ms-otros-curiosos-temas-galcticos-como-el-factor-guillermo-del-toro-o-los-do\">ayer Frank Marshall, marido de Kathleen Kennedy, asegur&oacute; que el trabajo estaba entre dos nombres<\/a>, aunque antes dijo que ya estaba el tema decidido, por lo que en una misma frase se contradijo a si mismo. Esto, si fuera una realidad, apuntar&iacute;a a aut&eacute;ntico WTF.<\/p>\n<blockquote class=\"twitter-tweet tw-align-center\" data-in-reply-to=\"268125256189886464\">\n<p>@<a href=\"https:\/\/twitter.com\/y6y___\" target=\"_blank\">y6y___<\/a> Thanks.We will just have to wait and see what happens \ud83d\ude42<\/p>\n<p>&mdash; Brenda Chapman (@brenda_chapman) <a href=\"https:\/\/twitter.com\/brenda_chapman\/status\/268167008099651584\" target=\"_blank\">noviembre 13, 2012<\/a><\/p><\/blockquote>\n<p><script type=\"text\/javascript\" src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p> Y por no abandonar ya el tema este, comienza a ser cansino, <a href=\"http:\/\/www.huffingtonpost.com\/2012\/11\/13\/joe-johnston-star-wars_n_2121928.html\" target=\"_blank\">en The Huffington Post charlan con Joe Johnston<\/a> y el veterano director no descarta la posibilidad de ser &eacute;l el elegido&#8230; en fin, el mundo de los rumores es tremendo.<\/p>\n<p>Ala, pues ya est&aacute; todo lo que ten&iacute;amos para hoy del interminable universo <strong>Star Wars<\/strong>. Antes de dejaros con el nuevo cartel de <a href=\"http:\/\/www.imdb.es\/title\/tt1549920\/\" target=\"_blank\">The Last Stand<\/a> (2013), comentar que <a href=\"http:\/\/www.deadline.com\/2012\/11\/paramount-eyes-chris-mcquarrie-to-helm-tom-cruise-in-next-mission-impossible\/\" target=\"_blank\">Deadline.com suelta una primicia interesante<\/a>. Resulta que <a href=\"http:\/\/www.imdb.es\/name\/nm0003160\/\" target=\"_blank\">Christopher McQuarrie<\/a>, ganador de un oscar por el gui&oacute;n de <a href=\"http:\/\/www.imdb.es\/title\/tt0114814\/\" target=\"_blank\">Sospechosos habituales<\/a> (<em>The Usual Suspects<\/em>, 1995), responsable de los escritos de <a href=\"http:\/\/www.imdb.es\/title\/tt0985699\/\" target=\"_blank\">Valkiria<\/a> (<em>Valkyrie<\/em>, 2008), <a href=\"http:\/\/www.imdb.es\/title\/tt1631867\/\" target=\"_blank\">All You Need is Kill<\/a> (2013) y director de la inminente <a href=\"http:\/\/www.imdb.es\/title\/tt0790724\/\" target=\"_blank\">Jack Reacher<\/a> (2012) con <a href=\"http:\/\/www.imdb.es\/name\/nm0000129\/\" target=\"_blank\">Tom Cruise<\/a>, apunta, para <strong>Paramount Pictures<\/strong> y <strong>Skydance Productions<\/strong>, como gran favorito para hacerse cargo de <a href=\"http:\/\/www.imdb.es\/title\/tt2381249\/\" target=\"_blank\">Mission: Impossible 5<\/a> (&iquest;?). Ojo, parece ser, por lo que deja caer el portal, que <strong>McQuarrie<\/strong> es el elegido, o al menos favorito, para <strong>Cruise<\/strong> y <a href=\"http:\/\/www.imdb.es\/name\/nm0009190\/\" target=\"_blank\">J.J. Abrams<\/a>, en estos momentos m&aacute;ximo valedor de la franquicia que resucit&oacute; hace unos a&ntilde;os y que con <a href=\"http:\/\/www.imdb.es\/name\/nm0083348\/\" target=\"_blank\">Brad Bird<\/a> recaud&oacute; pasta para hacer unas cuantas partes m&aacute;s sin preocupaciones. Y si el tema fragua, que podr&iacute;a ser, mucha atenci&oacute;n a la relaci&oacute;n entre <strong>McQuarrie<\/strong> y <strong>Cruise<\/strong>, con la tonter&iacute;a llevan ya vinculados en media decena de proyectos. Habr&aacute; que estar atentos, pero est&aacute; claro que <strong>M:I 5<\/strong> es proyecto prioritario para <strong>Paramount<\/strong>, hay que hacer partes como churros antes de que a <strong>Cruise<\/strong>, rey del cine de acci&oacute;n de la &uacute;ltima d&eacute;cada, deje de molar tanto.<\/p>\n<p class=\"centrado\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2012-2\/20121114-thelaststand.jpg\" alt=\"Nuevo cartel de The Last Stand\" width=\"500\" height=\"750\" \/><br \/>\n<em>Nuevo cartel de The Last Stand <a href=\"http:\/\/collider.com\/the-last-stand-poster\/210797\/\" target=\"_blank\">gracias a Collider.com<\/a><\/em><\/p>\n<p>Es momento de la despedida con unas cuantas im&aacute;genes. Gracias a <strong>Entertainment Weekly<\/strong> tenemos la oportunidad  de echar un primer vistazo a <a href=\"http:\/\/www.imdb.es\/name\/nm2934314\/\" target=\"_blank\">Lily Collins<\/a> como <strong>Clary Fray<\/strong> en <a href=\"http:\/\/www.imdb.es\/title\/tt1538403\/\" target=\"_blank\">Cazadores de Sombras: Ciudad de Hueso<\/a> (<em>The Mortal Instruments: City of Bones<\/em>, 2013) de <a href=\"http:\/\/www.imdb.es\/name\/nm0958969\/\" target=\"_blank\">Harald Zwart<\/a>, la adaptaci&oacute;n al cine de la primera de las novelas de fantas&iacute;a escritas por <strong>Cassandra Clare<\/strong>. En la novela <strong>Clary<\/strong> es una joven neoyorkina que descubre que es descendiente de una raza de semi-&aacute;ngeles guerreros conocidos como los <strong>Shadowhunters<\/strong>. Cuando su madre desaparece,&nbsp;<strong>Fray<\/strong>&nbsp;se ver&aacute; obligada a adentrarse en un grotesco New York alternativo llamado&nbsp;<strong>Downworld<\/strong>&nbsp;donde deber&aacute; enfrentarse a demonios, hombres lobo, brujos, vampiros y otras especies m&iacute;ticas acompa&ntilde;ada por su nueva familia de soldados. Desde luego que la obra tiene buena pinta, y por reparto tampoco va a ser. Junto a <strong>Lily Collins<\/strong> tenemos a <a href=\"http:\/\/www.imdb.es\/name\/nm0372176\/\" target=\"_blank\">Lena Headey<\/a>, <a href=\"http:\/\/www.imdb.es\/name\/nm0001667\/\" target=\"_blank\">Jonathan Rhys Meyers<\/a>, <a href=\"http:\/\/www.imdb.es\/name\/nm0364813\/\" target=\"_blank\">Jared Harris<\/a> o <a href=\"http:\/\/www.imdb.es\/name\/nm0243806\/\" target=\"_blank\">Kevin Durand<\/a>.<\/p>\n<p class=\"centrado\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2012-2\/20121114-themortalinstrumentscityofbones.jpg\" alt=\"Lilly Collins como Clary Fray en Cazadores de Sombras: Ciudad de Hueso\" width=\"625\" height=\"466\" \/><br \/><em>Lilly Collins como Clary Fray en Cazadores de Sombras: Ciudad de Hueso<\/em><\/p>\n<p>Ah, y para el que guste de <strong class=\"nota\">&nbsp;SPOILERS&nbsp;<\/strong>, <a href=\"http:\/\/splashpage.mtv.com\/2012\/11\/14\/thor-set-photos-dark-elves\/\" target=\"_blank\">que se pase por Splash Page MTV<\/a> para echar un vistazo a <strong>Malekith<\/strong> (<a href=\"http:\/\/www.imdb.es\/name\/nm0001172\/\" target=\"_blank\">Christopher Eccleston<\/a>) y sus hordas de elfos  oscuros en <a href=\"http:\/\/www.imdb.es\/title\/tt1981115\/\" target=\"_blank\">Thor: The Dark World<\/a> (2013) de <a href=\"http:\/\/www.imdb.es\/name\/nm0851930\/\" target=\"_blank\">Alan Taylor<\/a>. El rodaje sigue su curso y un avispado fan ha tenido a bien sacar un par de fotograf&iacute;as donde se puede ver los curiosos trajes, o armaduras de batalla, que <strong>Malekith<\/strong> y los suyos usar&aacute;n para zurrarse con <strong>Thor<\/strong> (<a href=\"http:\/\/www.imdb.es\/name\/nm1165110\/\" target=\"_blank\">Chris Hemsworth<\/a>).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La verdad, comienzo a sentir eso de que si un d&iacute;a no se habla de Star Wars: Episode VII (2015) pues no es d&iacute;a ni es nada. Creo que deber&iacute;amos iniciar una cuenta para anotar todos los rumores y comentarios que surgen en torno al regreso a la gran pantalla de la famosa saga parida [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,10,8,12,15],"tags":[2367,2358,2210,1734,2204],"class_list":["post-9058","post","type-post","status-publish","format-standard","hentry","category-cine","category-cine-de-comics","category-cine-de-ciencia-ficcion","category-cine-de-fantasia","category-star-wars","tag-mission-impossible-5","tag-star-wars-episode-vii","tag-the-last-stand","tag-the-mortal-instruments","tag-thor-the-dark-world"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Y otra candidata m&aacute;s para Star Wars: Episode VII, ahora es el turno de Brenda Chapman, Christopher McQuarrie apunta a director de Mission: Impossible 5, cartel definitivo de The Last Stand, primer vistazo a Lily Collins en Cazadores de Sombras: Ciudad de Hueso y as&iacute; luce Malekith y su ej&eacute;rcito de elfos oscuros en Thor: The Dark World... - Uruloki :: Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uruloki.org\/felipeblog\/cine\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Y otra candidata m&aacute;s para Star Wars: Episode VII, ahora es el turno de Brenda Chapman, Christopher McQuarrie apunta a director de Mission: Impossible 5, cartel definitivo de The Last Stand, primer vistazo a Lily Collins en Cazadores de Sombras: Ciudad de Hueso y as&iacute; luce Malekith y su ej&eacute;rcito de elfos oscuros en Thor: The Dark World... - Uruloki :: Blog\" \/>\n<meta property=\"og:description\" content=\"La verdad, comienzo a sentir eso de que si un d&iacute;a no se habla de Star Wars: Episode VII (2015) pues no es d&iacute;a ni es nada. Creo que deber&iacute;amos iniciar una cuenta para anotar todos los rumores y comentarios que surgen en torno al regreso a la gran pantalla de la famosa saga parida [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uruloki.org\/felipeblog\/cine\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri\" \/>\n<meta property=\"og:site_name\" content=\"Uruloki :: Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uruloki.org\" \/>\n<meta property=\"article:published_time\" content=\"2012-11-14T19:37:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uruloki.org\/felipeblog\/images2012-2\/20121114-thelaststand.jpg\" \/>\n<meta name=\"author\" content=\"Uruloki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uruloki\" \/>\n<meta name=\"twitter:site\" content=\"@uruloki\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Uruloki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri\"},\"author\":{\"name\":\"Uruloki\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"headline\":\"Y otra candidata m&aacute;s para Star Wars: Episode VII, ahora es el turno de Brenda Chapman, Christopher McQuarrie apunta a director de Mission: Impossible 5, cartel definitivo de The Last Stand, primer vistazo a Lily Collins en Cazadores de Sombras: Ciudad de Hueso y as&iacute; luce Malekith y su ej&eacute;rcito de elfos oscuros en Thor: The Dark World&#8230;\",\"datePublished\":\"2012-11-14T19:37:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri\"},\"wordCount\":909,\"commentCount\":5,\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2012-2\\\/20121114-thelaststand.jpg\",\"keywords\":[\"Mission: Impossible 5\",\"Star Wars: Episode VII\",\"The Last Stand\",\"The Mortal Instruments\",\"Thor: The Dark World\"],\"articleSection\":[\"Cine\",\"Cine de C\u00f3mics\",\"Cine de Ciencia Ficci\u00f3n\",\"Cine de Fantas\u00eda\",\"Star Wars\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri\",\"name\":\"Y otra candidata m&aacute;s para Star Wars: Episode VII, ahora es el turno de Brenda Chapman, Christopher McQuarrie apunta a director de Mission: Impossible 5, cartel definitivo de The Last Stand, primer vistazo a Lily Collins en Cazadores de Sombras: Ciudad de Hueso y as&iacute; luce Malekith y su ej&eacute;rcito de elfos oscuros en Thor: The Dark World... - Uruloki :: Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2012-2\\\/20121114-thelaststand.jpg\",\"datePublished\":\"2012-11-14T19:37:26+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri#primaryimage\",\"url\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2012-2\\\/20121114-thelaststand.jpg\",\"contentUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2012-2\\\/20121114-thelaststand.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Y otra candidata m&aacute;s para Star Wars: Episode VII, ahora es el turno de Brenda Chapman, Christopher McQuarrie apunta a director de Mission: Impossible 5, cartel definitivo de The Last Stand, primer vistazo a Lily Collins en Cazadores de Sombras: Ciudad de Hueso y as&iacute; luce Malekith y su ej&eacute;rcito de elfos oscuros en Thor: The Dark World&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/\",\"name\":\"Uruloki :: Blog\",\"description\":\"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\",\"name\":\"Uruloki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"caption\":\"Uruloki\"},\"sameAs\":[\"https:\\\/\\\/uruloki.org\"],\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/author\\\/admin-2-2-2\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Y otra candidata m&aacute;s para Star Wars: Episode VII, ahora es el turno de Brenda Chapman, Christopher McQuarrie apunta a director de Mission: Impossible 5, cartel definitivo de The Last Stand, primer vistazo a Lily Collins en Cazadores de Sombras: Ciudad de Hueso y as&iacute; luce Malekith y su ej&eacute;rcito de elfos oscuros en Thor: The Dark World... - Uruloki :: Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uruloki.org\/felipeblog\/cine\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri","og_locale":"es_ES","og_type":"article","og_title":"Y otra candidata m&aacute;s para Star Wars: Episode VII, ahora es el turno de Brenda Chapman, Christopher McQuarrie apunta a director de Mission: Impossible 5, cartel definitivo de The Last Stand, primer vistazo a Lily Collins en Cazadores de Sombras: Ciudad de Hueso y as&iacute; luce Malekith y su ej&eacute;rcito de elfos oscuros en Thor: The Dark World... - Uruloki :: Blog","og_description":"La verdad, comienzo a sentir eso de que si un d&iacute;a no se habla de Star Wars: Episode VII (2015) pues no es d&iacute;a ni es nada. Creo que deber&iacute;amos iniciar una cuenta para anotar todos los rumores y comentarios que surgen en torno al regreso a la gran pantalla de la famosa saga parida [&hellip;]","og_url":"https:\/\/www.uruloki.org\/felipeblog\/cine\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri","og_site_name":"Uruloki :: Blog","article_publisher":"https:\/\/www.facebook.com\/uruloki.org","article_published_time":"2012-11-14T19:37:26+00:00","og_image":[{"url":"https:\/\/uruloki.org\/felipeblog\/images2012-2\/20121114-thelaststand.jpg","type":"","width":"","height":""}],"author":"Uruloki","twitter_card":"summary_large_image","twitter_creator":"@uruloki","twitter_site":"@uruloki","twitter_misc":{"Escrito por":"Uruloki","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri#article","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri"},"author":{"name":"Uruloki","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"headline":"Y otra candidata m&aacute;s para Star Wars: Episode VII, ahora es el turno de Brenda Chapman, Christopher McQuarrie apunta a director de Mission: Impossible 5, cartel definitivo de The Last Stand, primer vistazo a Lily Collins en Cazadores de Sombras: Ciudad de Hueso y as&iacute; luce Malekith y su ej&eacute;rcito de elfos oscuros en Thor: The Dark World&#8230;","datePublished":"2012-11-14T19:37:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri"},"wordCount":909,"commentCount":5,"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/images2012-2\/20121114-thelaststand.jpg","keywords":["Mission: Impossible 5","Star Wars: Episode VII","The Last Stand","The Mortal Instruments","Thor: The Dark World"],"articleSection":["Cine","Cine de C\u00f3mics","Cine de Ciencia Ficci\u00f3n","Cine de Fantas\u00eda","Star Wars"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uruloki.org\/felipeblog\/cine\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri","url":"https:\/\/www.uruloki.org\/felipeblog\/cine\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri","name":"Y otra candidata m&aacute;s para Star Wars: Episode VII, ahora es el turno de Brenda Chapman, Christopher McQuarrie apunta a director de Mission: Impossible 5, cartel definitivo de The Last Stand, primer vistazo a Lily Collins en Cazadores de Sombras: Ciudad de Hueso y as&iacute; luce Malekith y su ej&eacute;rcito de elfos oscuros en Thor: The Dark World... - Uruloki :: Blog","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri#primaryimage"},"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/images2012-2\/20121114-thelaststand.jpg","datePublished":"2012-11-14T19:37:26+00:00","author":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"breadcrumb":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uruloki.org\/felipeblog\/cine\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri#primaryimage","url":"https:\/\/uruloki.org\/felipeblog\/images2012-2\/20121114-thelaststand.jpg","contentUrl":"https:\/\/uruloki.org\/felipeblog\/images2012-2\/20121114-thelaststand.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/y-otra-candidata-ms-para-star-wars-episode-vii-ahora-es-el-turno-de-brenda-chapman-christopher-mcquarrie-apunta-a-director-de-mission-impossible-5-cartel-definitivo-de-the-last-stand-pri#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uruloki.org\/felipeblog"},{"@type":"ListItem","position":2,"name":"Y otra candidata m&aacute;s para Star Wars: Episode VII, ahora es el turno de Brenda Chapman, Christopher McQuarrie apunta a director de Mission: Impossible 5, cartel definitivo de The Last Stand, primer vistazo a Lily Collins en Cazadores de Sombras: Ciudad de Hueso y as&iacute; luce Malekith y su ej&eacute;rcito de elfos oscuros en Thor: The Dark World&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.uruloki.org\/felipeblog\/#website","url":"https:\/\/www.uruloki.org\/felipeblog\/","name":"Uruloki :: Blog","description":"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uruloki.org\/felipeblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3","name":"Uruloki","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","caption":"Uruloki"},"sameAs":["https:\/\/uruloki.org"],"url":"https:\/\/www.uruloki.org\/felipeblog\/author\/admin-2-2-2"}]}},"_links":{"self":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/9058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/comments?post=9058"}],"version-history":[{"count":1,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/9058\/revisions"}],"predecessor-version":[{"id":9059,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/9058\/revisions\/9059"}],"wp:attachment":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/media?parent=9058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/categories?post=9058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/tags?post=9058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}