{"id":8808,"date":"2012-10-14T13:51:49","date_gmt":"2012-10-14T11:51:49","guid":{"rendered":"https:\/\/uruloki.org\/felipeblog\/?p=8808"},"modified":"2012-10-14T13:51:49","modified_gmt":"2012-10-14T11:51:49","slug":"sitges-2012-aftershock","status":"publish","type":"post","link":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-terror\/sitges-2012-aftershock","title":{"rendered":"Sitges 2012: Aftershock&#8230;"},"content":{"rendered":"<p>Hora de hablar de uno de los grandes chascos del festival, aunque hay que reconocer que tampoco es que esperara mucho de el. Como puesta en marcha de una colaboraci&oacute;n que se alargar&aacute; con la futura <strong>The Green Inferno<\/strong> (&iquest;2013?), en esta un grupo de gente  lo pasar&aacute; putas en el Amazonas, <strong>Eli Roth<\/strong> y el chileno <strong>Nicol&aacute;s L&oacute;pez<\/strong> desembarcaron en la <strong>45&ordf; edici&oacute;n del Sitges &#8211; Festival Internacional de Cinema Fant&agrave;stic de Catalunya<\/strong> con una pel&iacute;cula de corte odioso. &iquest;Por qu&eacute; digo tal? Pues por diversas razones que vengo aqu&iacute; a enumerar. Primero por el conjunto de personajes protagonistas que presenta, cero es la empat&iacute;a que se puede sentir por ninguno de ellos aunque est&aacute; bastante claro que se busca este objetivo para que as&iacute; no nos duela su truculento destino. Dan asquito en todos los aspectos de su superficial personalidad. Segundo, porque un film de  90 minutos pelados obliga a meterse durante los 40 primeros en una inexplicable presentaci&oacute;n de un grupo social de un pa&iacute;s que supura superficialidad y que deja con cara de estupefacci&oacute;n a aquel que se la pueda ver. Tercero, y esto tengo la sensaci&oacute;n que se pasa de casta&ntilde;o oscuro, por dar cierto tono c&oacute;mico ir&oacute;nico a un tema peliagudo como fue el terremoto de Chile del 2010, donde fallecieron m&aacute;s de 500 personas. Cuarto, y dejo de comentar los problemas de <strong>Aftershock<\/strong>, por preferir seguir el camino de lo incre&iacute;ble, actitudes y acciones carentes de sentido l&oacute;gico aunque est&eacute;s en una situaci&oacute;n de tensi&oacute;n y estr&eacute;s total, o lo puramente absurdo. Ojo, que seguramente todo esto est&aacute; buscado con ganas y concienzuda decisi&oacute;n, pero aun as&iacute; el producto final acaba resultando completamente fallido. Hay que v&eacute;rsela con mucho sentido del humor, del rid&iacute;culo y sin otra aspiraci&oacute;n que no sea descubrir el lado pijo rico de Chile y las posibles macabras consecuencias de un terremoto.<\/p>\n<p class=\"centrado\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2012-2\/20121014-aftershock.jpg\" alt=\"Promo de Aftershock\" width=\"500\" height=\"712\" \/><br \/><em>Promo de Aftershock<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hora de hablar de uno de los grandes chascos del festival, aunque hay que reconocer que tampoco es que esperara mucho de el. Como puesta en marcha de una colaboraci&oacute;n que se alargar&aacute; con la futura The Green Inferno (&iquest;2013?), en esta un grupo de gente lo pasar&aacute; putas en el Amazonas, Eli Roth y [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,27,2176],"tags":[1558,3373,3386],"class_list":["post-8808","post","type-post","status-publish","format-standard","hentry","category-cine-de-terror","category-opinion","category-sitges-2012","tag-aftershock","tag-opinion","tag-sitges-2012"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sitges 2012: Aftershock... - Uruloki :: Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-terror\/sitges-2012-aftershock\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sitges 2012: Aftershock... - Uruloki :: Blog\" \/>\n<meta property=\"og:description\" content=\"Hora de hablar de uno de los grandes chascos del festival, aunque hay que reconocer que tampoco es que esperara mucho de el. Como puesta en marcha de una colaboraci&oacute;n que se alargar&aacute; con la futura The Green Inferno (&iquest;2013?), en esta un grupo de gente lo pasar&aacute; putas en el Amazonas, Eli Roth y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-terror\/sitges-2012-aftershock\" \/>\n<meta property=\"og:site_name\" content=\"Uruloki :: Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uruloki.org\" \/>\n<meta property=\"article:published_time\" content=\"2012-10-14T11:51:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uruloki.org\/felipeblog\/images2012-2\/20121014-aftershock.jpg\" \/>\n<meta name=\"author\" content=\"Uruloki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uruloki\" \/>\n<meta name=\"twitter:site\" content=\"@uruloki\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Uruloki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-terror\\\/sitges-2012-aftershock#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-terror\\\/sitges-2012-aftershock\"},\"author\":{\"name\":\"Uruloki\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"headline\":\"Sitges 2012: Aftershock&#8230;\",\"datePublished\":\"2012-10-14T11:51:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-terror\\\/sitges-2012-aftershock\"},\"wordCount\":373,\"commentCount\":5,\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-terror\\\/sitges-2012-aftershock#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2012-2\\\/20121014-aftershock.jpg\",\"keywords\":[\"Aftershock\",\"Opini\u00f3n\",\"Sitges 2012\"],\"articleSection\":[\"Cine de Terror\",\"Opini\u00f3n\",\"Sitges 2012\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-terror\\\/sitges-2012-aftershock#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-terror\\\/sitges-2012-aftershock\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-terror\\\/sitges-2012-aftershock\",\"name\":\"Sitges 2012: Aftershock... - Uruloki :: Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-terror\\\/sitges-2012-aftershock#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-terror\\\/sitges-2012-aftershock#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2012-2\\\/20121014-aftershock.jpg\",\"datePublished\":\"2012-10-14T11:51:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-terror\\\/sitges-2012-aftershock#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-terror\\\/sitges-2012-aftershock\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-terror\\\/sitges-2012-aftershock#primaryimage\",\"url\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2012-2\\\/20121014-aftershock.jpg\",\"contentUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2012-2\\\/20121014-aftershock.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-terror\\\/sitges-2012-aftershock#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sitges 2012: Aftershock&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/\",\"name\":\"Uruloki :: Blog\",\"description\":\"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\",\"name\":\"Uruloki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"caption\":\"Uruloki\"},\"sameAs\":[\"https:\\\/\\\/uruloki.org\"],\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/author\\\/admin-2-2-2\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sitges 2012: Aftershock... - Uruloki :: Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-terror\/sitges-2012-aftershock","og_locale":"es_ES","og_type":"article","og_title":"Sitges 2012: Aftershock... - Uruloki :: Blog","og_description":"Hora de hablar de uno de los grandes chascos del festival, aunque hay que reconocer que tampoco es que esperara mucho de el. Como puesta en marcha de una colaboraci&oacute;n que se alargar&aacute; con la futura The Green Inferno (&iquest;2013?), en esta un grupo de gente lo pasar&aacute; putas en el Amazonas, Eli Roth y [&hellip;]","og_url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-terror\/sitges-2012-aftershock","og_site_name":"Uruloki :: Blog","article_publisher":"https:\/\/www.facebook.com\/uruloki.org","article_published_time":"2012-10-14T11:51:49+00:00","og_image":[{"url":"https:\/\/uruloki.org\/felipeblog\/images2012-2\/20121014-aftershock.jpg","type":"","width":"","height":""}],"author":"Uruloki","twitter_card":"summary_large_image","twitter_creator":"@uruloki","twitter_site":"@uruloki","twitter_misc":{"Escrito por":"Uruloki","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-terror\/sitges-2012-aftershock#article","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-terror\/sitges-2012-aftershock"},"author":{"name":"Uruloki","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"headline":"Sitges 2012: Aftershock&#8230;","datePublished":"2012-10-14T11:51:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-terror\/sitges-2012-aftershock"},"wordCount":373,"commentCount":5,"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-terror\/sitges-2012-aftershock#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/images2012-2\/20121014-aftershock.jpg","keywords":["Aftershock","Opini\u00f3n","Sitges 2012"],"articleSection":["Cine de Terror","Opini\u00f3n","Sitges 2012"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-terror\/sitges-2012-aftershock#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-terror\/sitges-2012-aftershock","url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-terror\/sitges-2012-aftershock","name":"Sitges 2012: Aftershock... - Uruloki :: Blog","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-terror\/sitges-2012-aftershock#primaryimage"},"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-terror\/sitges-2012-aftershock#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/images2012-2\/20121014-aftershock.jpg","datePublished":"2012-10-14T11:51:49+00:00","author":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"breadcrumb":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-terror\/sitges-2012-aftershock#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-terror\/sitges-2012-aftershock"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-terror\/sitges-2012-aftershock#primaryimage","url":"https:\/\/uruloki.org\/felipeblog\/images2012-2\/20121014-aftershock.jpg","contentUrl":"https:\/\/uruloki.org\/felipeblog\/images2012-2\/20121014-aftershock.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-terror\/sitges-2012-aftershock#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uruloki.org\/felipeblog"},{"@type":"ListItem","position":2,"name":"Sitges 2012: Aftershock&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.uruloki.org\/felipeblog\/#website","url":"https:\/\/www.uruloki.org\/felipeblog\/","name":"Uruloki :: Blog","description":"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uruloki.org\/felipeblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3","name":"Uruloki","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","caption":"Uruloki"},"sameAs":["https:\/\/uruloki.org"],"url":"https:\/\/www.uruloki.org\/felipeblog\/author\/admin-2-2-2"}]}},"_links":{"self":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/8808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/comments?post=8808"}],"version-history":[{"count":1,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/8808\/revisions"}],"predecessor-version":[{"id":8809,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/8808\/revisions\/8809"}],"wp:attachment":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/media?parent=8808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/categories?post=8808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/tags?post=8808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}