{"id":7937,"date":"2012-06-05T21:40:18","date_gmt":"2012-06-05T19:40:18","guid":{"rendered":"https:\/\/uruloki.org\/felipeblog\/?p=7937"},"modified":"2012-06-05T21:44:04","modified_gmt":"2012-06-05T19:44:04","slug":"la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i","status":"publish","type":"post","link":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i","title":{"rendered":"&iquest;La secuela de X-Men: Primera Generaci&oacute;n podr&iacute;a ser &quot;D&iacute;as de futuro pasado&quot;?, Guillermo del Toro habla sobre sus incursiones en el mundo del cine animado, nueva imagen y sinopsis de Dredd, Clive Barker se har&aacute; cargo de Zombies vs. Gladiators, Mads Mikkelsen ser&aacute; el nuevo Dr. Hannibal Lecter, un curioso fake trailer de Star Trek 2, &iquest;A.I.M. en Iron Man 3? y Christopher Nolan no descarta hacerse  cargo de la vida de James Bond&#8230;"},"content":{"rendered":"<p>Sigamos dando vida a esto que nunca est&aacute; de m&aacute;s. Antes de nada una noticia de &uacute;ltima hora, y que aunque <strong>es rumor<\/strong> puede molar un rato largo si se hace realidad. <a href=\"http:\/\/www.aintitcool.com\/node\/56219\" target=\"_blank\">Ain&#8217;t It Cool News indica<\/a> que <strong>20th Century Fox<\/strong> podr&iacute;a haber registrado en la <strong>MPAA<\/strong> el titulo <strong>&quot;D&iacute;as de futuro pasado&quot;<\/strong>. El tema es que los estudios est&aacute;n obligados a esto para evitar colisiones en sus t&iacute;tulos. Con la secuela de <a href=\"http:\/\/www.imdb.es\/title\/tt1270798\/\" target=\"_blank\">X-Men: primera generaci&oacute;n<\/a> (<em>X-Men: First Class<\/em>, 2011) en marcha la confirmaci&oacute;n de este dato podr&iacute;a comenzar a generar <em>hype<\/em> por todas partes. Probablemente uno de los mejores arcos argumentales de la historia de la <strong>Patrulla X<\/strong> con  las l&iacute;neas temporales alternativas como eje central de su historia. Y con Centinelas! Solo de pensarlo se me hace la boca agua&#8230; una historia magn&iacute;fica y que en formato cine puede ser una aut&eacute;ntica genialidad. Vayamos con la realidad.<\/p>\n<p>Ayer el bueno de <a href=\"http:\/\/www.variety.com\/article\/VR1118054434?refCatId=13\" target=\"_blank\">Guillermo del Toro se par&oacute; a charlar con la gente de Variety<\/a> y as&iacute; poner un poco de frescura en su ajetreada  carrera de productor \/ director \/ guionista de esa vertiente cinematogr&aacute;fica que hasta ahora no hab&iacute;a pisado&#8230; la animaci&oacute;n. <strong>Del Toro<\/strong> se para a hablar, brevemente, de algunas de sus futuras incursiones en todas sus posibles facetas. Sobre <a href=\"http:\/\/www.imdb.es\/title\/tt1734135\/\" target=\"_blank\">Trollhunters<\/a> (&iquest;?) indica el director mexicano que el &uacute;ltimo borrador de gui&oacute;n lo entreg&oacute; a <strong>Dreamworks<\/strong> el pasado mes de mayo pero que mientras que no haya aprendido todo lo que necesita saber para ponerse a lo mandos de un film de animaci&oacute;n no se embarcar&aacute; en la aventura. Eso si, contar&aacute; con <a href=\"http:\/\/www.imdb.es\/name\/nm1174214\/\" target=\"_blank\">Rodrigo Blaas<\/a> como co-director, lo que nos lleva a hablar de otro de sus proyectos. En este caso es <strong>Alma<\/strong> (&iquest;?), el largo que dirigir&aacute; <strong>Blaas<\/strong> basado en su propio corto. En este caso <strong>Del Toro<\/strong> actuar&aacute; como productor ejecutivo aunque indica que ha estado colaborando en tareas creativas y conceptuales. En cuanto a <a href=\"http:\/\/www.imdb.es\/title\/tt1488589\/\" target=\"_blank\">Pinocchio<\/a> (&iquest;?), aparentemente su verdadera primera incursi&oacute;n en el cine de animaci&oacute;n y que co-dirigir&aacute; junto a <a href=\"http:\/\/www.imdb.es\/name\/nm0348993\/\" target=\"_blank\">Mark Gustafson<\/a>, comenta que todos sus trabajos pasan antes por las manos de <a href=\"http:\/\/www.imdb.es\/name\/nm0005076\/\" target=\"_blank\">Jeffrey Katzenberg<\/a>, presidente de <strong>Dreamworks Animation<\/strong>, y que este es el que decide qu&eacute; se hace y qu&eacute; debe esperar. Hora de un par de proyectos no <strong>Dreamworks<\/strong>. El primero es <a href=\"http:\/\/www.imdb.es\/title\/tt1661203\/\" target=\"_blank\">Day of the Dead<\/a> (&iquest;?), ese cuento a lo <strong>Romeo y Julieta<\/strong> que se dec&iacute;a iba a dirigir <a href=\"http:\/\/www.imdb.es\/name\/nm1509613\/\" target=\"_blank\">Jorge R. Guti&eacute;rrez<\/a>. <strong>Del Toro<\/strong> solo comenta que como productor puede confirmar que anuncios oficiales al respecto est&aacute;n por llegar, vamos, que ni <strong>Guti&eacute;rrez<\/strong> es fijo en la direcci&oacute;n. Termina con la nueva adaptaci&oacute;n de <strong>&quot;Las Brujas&quot;<\/strong> de <strong>Roald Dahl<\/strong>, proyecto que est&aacute; en manos de <strong>Warner Bros.<\/strong> En este caso la noticia no puede ser peor&#8230; el proyecto est&aacute; muerto. Aunque indica que es el mejor gui&oacute;n que jam&aacute;s ha escrito y que la viuda del autor dio su benepl&aacute;cito, el tiempo ha acabado por hundirlo por completo y duda mucho que jam&aacute;s llegue a realizarse.<\/p>\n<p class=\"centrado\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2012-1\/20120605_dredd.jpg\" alt=\"Una nueva imagen de Dredd de Pete Travis\" width=\"625\" height=\"379\" \/><br \/>\n<em>Una nueva imagen de Dredd de Pete Travis<\/em><\/p>\n<p>Vayamos ahora con otras cosas. Por ejemplo, <a href=\"http:\/\/www.deadline.com\/2012\/06\/amazon-studios-clive-barker-see-zombies-roman-the-ancient-empire\/\" target=\"_blank\">Deadline.com nos comenta<\/a> que <a href=\"http:\/\/www.imdb.es\/name\/nm0000850\/\" target=\"_blank\">Clive Barker<\/a> ha cerrado un acuerdo con <strong>Amazon Studios<\/strong> para hacerse cargo de una de esas historias que, la verdad, no pueden sonar m&aacute;s grotescas y desquiciantes. La compa&ntilde;&iacute;a ha contratado a <strong>Barker<\/strong> para que reescriba y dirija <a href=\"http:\/\/www.imdb.es\/title\/tt2401229\/\" target=\"_blank\">Zombies vs. Gladiators<\/a> (&iquest;?). La historia os dejar&aacute; perplejos&#8230; un cham&aacute;n que est&aacute; a punto de morir en la arena invoca a los muertos vivientes que yacen en los fondos de Coliseo. Como resultado una horda de zombis surge y se arma la marimorena. Todo queda en manos de un gladiador que deber&aacute; evitar que la plaga zombi se expanda  y acabe por Roma. Alucinante, pero puede ser divertido. Ah, <strong>Zombies vs. Gladiators<\/strong> forma parte de ese plan gestado por <strong>Amazon Films<\/strong> cuando lanz&oacute; la compa&ntilde;&iacute;a y <strong>examin&oacute; la friolera del 9000 guiones de pel&iacute;cula y 1000 de series<\/strong>. Lo mejor de lo mejor. <a href=\"http:\/\/www.deadline.com\/2012\/06\/mads-mikkelsen-to-play-hannibal-lecter-in-nbc-series-hannibal\/\" target=\"_blank\">La misma Deadline.com es la que nos adelanta<\/a> que <a href=\"http:\/\/www.imdb.es\/name\/nm0586568\/\" target=\"_blank\">Mads Mikkelsen<\/a> ha sido fichado por la <strong>NBC<\/strong> para ponerse en la piel del <strong>Dr. Hannibal Lecter<\/strong> en la serie que el canal lleva preparando junto a <strong>Gaumont International Television<\/strong>. <a href=\"http:\/\/www.imdb.es\/name\/nm0199215\/\" target=\"_blank\">Hugh Dancy<\/a> encarnar&aacute; al agente del FBI <strong>Will Graham<\/strong>, encarnado por <a href=\"http:\/\/www.imdb.es\/name\/nm0676973\/\" target=\"_blank\">William Petersen<\/a> y <a href=\"http:\/\/www.imdb.es\/name\/nm0001570\/\" target=\"_blank\">Edward Norton<\/a> en las adaptaciones de la novela <strong>&quot;El Drag&oacute;n Rojo&quot;<\/strong>, que acudir&aacute; al <strong>Dr. Lecter<\/strong>, un psiquiatra especialista, sin saber el lado oscuro de este. Pinta bien. <a href=\"http:\/\/dailydead.com\/exclusive-brittany-curran-cast-in-marcus-nispels-backmask\/\" target=\"_blank\">Y hablando de fichajes, Daily Dead descubre<\/a> que <a href=\"http:\/\/www.imdb.es\/name\/nm1589004\/\" target=\"_blank\">Brittany Curran<\/a> ha sido contratada para unirse al reparto de <a href=\"http:\/\/www.imdb.es\/title\/tt1945044\/\" target=\"_blank\">Backmask<\/a> (&iquest;?) de <a href=\"http:\/\/www.imdb.es\/name\/nm1197971\/\" target=\"_blank\">Marcus Nispel<\/a>. La <strong>Curran<\/strong> ser&aacute; la protagonista femenina de esta historia donde seis teenagers de un peque&ntilde;o pueblo liberan a un mal&eacute;fico esp&iacute;ritu al poner un disco al rev&eacute;s.<\/p>\n<div class=\"video\"><iframe loading=\"lazy\" width=\"625\" height=\"380\" src=\"http:\/\/www.youtube.com\/embed\/a-13Ic19WUs\"><\/iframe><\/div>\n<p>Igualmente interesante es <a href=\"http:\/\/blogs.indiewire.com\/theplaylist\/christopher-nolan-says-his-howard-hughes-film-is-dead-but-hed-still-like-to-do-a-bond-film-at-some-point-20120604?utm_source=feedburner&amp;utm_medium=feed\" target=\"_blank\">leer en The Playlist lo que Christopher Nolan tiene que contar sobre su futuro<\/a> tras el universo <strong>Batman<\/strong>. La charla sale realmente del &uacute;ltimo n&uacute;mero de la revista <strong>Empire<\/strong> donde <strong>Nolan<\/strong> deja caer que ya en el futuro existi&oacute; la posibilidad, y que a d&iacute;a de hoy le sigue atrayendo, y mucho, la idea de hacerse cargo de la direcci&oacute;n de un film de <strong>James Bond<\/strong>. En su charla reconoce la gran influencia que ha tenido el m&iacute;tico personaje tanto en su concepci&oacute;n de <strong>Batman<\/strong> como en <a href=\"http:\/\/www.imdb.es\/title\/tt1375666\/\" target=\"_blank\">Origen<\/a> (<em>Inception<\/em>, 2010), por lo que no le har&iacute;a ascos a la oferta si se diera en el momento exacto y bajo las condiciones perfectas. Veremos. Ah, y mucha atenci&oacute;n a <a href=\"http:\/\/www.comicbookmovie.com\/fansites\/MarvelFreshman\/news\/?a=60982\" target=\"_blank\">lo que nos descubren en ComicBookMovies.com<\/a>&#8230; <strong>A.I.M.<\/strong> estar&aacute; presente en <a href=\"http:\/\/www.imdb.es\/title\/tt1300854\/\" target=\"_blank\">Iron Man 3<\/a> (2013), &iquest;cabr&iacute;a la posibilidad de ver a&#8230; <strong>Modok<\/strong>? Todo es posible. Os dejo ahora con la nueva completita sinopsis de <a href=\"http:\/\/www.imdb.es\/title\/tt1343727\/\" target=\"_blank\">Dredd<\/a> (2012) de <a href=\"http:\/\/www.imdb.es\/name\/nm0871428\/\" target=\"_blank\">Pete Travis<\/a> que ha aparecido <a href=\"https:\/\/www.facebook.com\/dreddthemovie\" target=\"_blank\">en la p&aacute;gina de Facebook de la pel&iacute;cula<\/a>.<\/p>\n<blockquote>\n<p>El futuro, Am&eacute;rica es un p&aacute;ramo. En la costa este, entre Boston y Washington DC, est&aacute; Mega City One, una gigantesca y violenta metr&oacute;polis donde los criminales dominan las ca&oacute;ticas calles. La &uacute;nica fuerza que puede ejercer algo de orden son los polic&iacute;as urbanos conocidos como &quot;Jueces&quot;, que poseen los poderes combinados de un juez, jurado y verdugo. Dredd (<a href=\"http:\/\/www.imdb.es\/name\/nm0881631\/\" target=\"_blank\">Karl Urban<\/a>) es el juez definitivo que adem&aacute;s tiene que lidiar con una peligrosa epidemia en forma de droga llamada &quot;Slo-Mo&quot; que provoca en los que la toman percibir la realidad como una fracci&oacute;n de su verdadera velocidad.<\/p>\n<p>Durante un normal d&iacute;a de trabajo, Dredd es asignado para evaluar a Cassandra Anderson (<a href=\"http:\/\/www.imdb.es\/name\/nm1880888\/\" target=\"_blank\">Olivia Thirlby<\/a>), una rookie que aspira a Juez con poderes ps&iacute;quicos gracias a una mutaci&oacute;n gen&eacute;tica. Un atroz crimen les lleva a un vecindario donde los Jueces no suelen aventurarse, un edificio de 200 pisos controlado por la prostituta convertida en se&ntilde;ora de la droga Ma-Ma (<a href=\"http:\/\/www.imdb.es\/name\/nm0372176\/\" target=\"_blank\">Lena Headey<\/a>). Cuando Dredd y Anderson capturan a uno de los cercanos a Ma-Ma se desencadenar&aacute;  una guerra brutal con idea de demostrar a los Jueces que nada puede hacerse para controlar el edificio. Con los cad&aacute;veres aumentando de forma alarmante, Dredd y Anderson deber&aacute;n enfrentarse a las cosas m&aacute;s extra&ntilde;as y tratar de sobrevivir en la batalla m&aacute;s cruda a la que jam&aacute;s han hecho frente.<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Sigamos dando vida a esto que nunca est&aacute; de m&aacute;s. Antes de nada una noticia de &uacute;ltima hora, y que aunque es rumor puede molar un rato largo si se hace realidad. Ain&#8217;t It Cool News indica que 20th Century Fox podr&iacute;a haber registrado en la MPAA el titulo &quot;D&iacute;as de futuro pasado&quot;. El tema [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,10,8,12,9,26],"tags":[1508,282,1586,1867,614,905,1720,1061,2089,2157],"class_list":["post-7937","post","type-post","status-publish","format-standard","hentry","category-cine","category-cine-de-comics","category-cine-de-ciencia-ficcion","category-cine-de-fantasia","category-cine-de-terror","category-gdt","tag-alma","tag-day-of-the-dead","tag-dredd","tag-hannibal","tag-iron-man-3","tag-star-trek-2","tag-the-witches","tag-trollhunters","tag-x-men-first-class-2","tag-zombies-vs-gladiators"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&iquest;La secuela de X-Men: Primera Generaci&oacute;n podr&iacute;a ser &quot;D&iacute;as de futuro pasado&quot;?, Guillermo del Toro habla sobre sus incursiones en el mundo del cine animado, nueva imagen y sinopsis de Dredd, Clive Barker se har&aacute; cargo de Zombies vs. Gladiators, Mads Mikkelsen ser&aacute; el nuevo Dr. Hannibal Lecter, un curioso fake trailer de Star Trek 2, &iquest;A.I.M. en Iron Man 3? y Christopher Nolan no descarta hacerse cargo de la vida de James Bond... - Uruloki :: Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&iquest;La secuela de X-Men: Primera Generaci&oacute;n podr&iacute;a ser &quot;D&iacute;as de futuro pasado&quot;?, Guillermo del Toro habla sobre sus incursiones en el mundo del cine animado, nueva imagen y sinopsis de Dredd, Clive Barker se har&aacute; cargo de Zombies vs. Gladiators, Mads Mikkelsen ser&aacute; el nuevo Dr. Hannibal Lecter, un curioso fake trailer de Star Trek 2, &iquest;A.I.M. en Iron Man 3? y Christopher Nolan no descarta hacerse cargo de la vida de James Bond... - Uruloki :: Blog\" \/>\n<meta property=\"og:description\" content=\"Sigamos dando vida a esto que nunca est&aacute; de m&aacute;s. Antes de nada una noticia de &uacute;ltima hora, y que aunque es rumor puede molar un rato largo si se hace realidad. Ain&#8217;t It Cool News indica que 20th Century Fox podr&iacute;a haber registrado en la MPAA el titulo &quot;D&iacute;as de futuro pasado&quot;. El tema [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i\" \/>\n<meta property=\"og:site_name\" content=\"Uruloki :: Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uruloki.org\" \/>\n<meta property=\"article:published_time\" content=\"2012-06-05T19:40:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2012-06-05T19:44:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uruloki.org\/felipeblog\/images2012-1\/20120605_dredd.jpg\" \/>\n<meta name=\"author\" content=\"Uruloki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uruloki\" \/>\n<meta name=\"twitter:site\" content=\"@uruloki\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Uruloki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i\"},\"author\":{\"name\":\"Uruloki\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"headline\":\"&iquest;La secuela de X-Men: Primera Generaci&oacute;n podr&iacute;a ser &quot;D&iacute;as de futuro pasado&quot;?, Guillermo del Toro habla sobre sus incursiones en el mundo del cine animado, nueva imagen y sinopsis de Dredd, Clive Barker se har&aacute; cargo de Zombies vs. Gladiators, Mads Mikkelsen ser&aacute; el nuevo Dr. Hannibal Lecter, un curioso fake trailer de Star Trek 2, &iquest;A.I.M. en Iron Man 3? y Christopher Nolan no descarta hacerse cargo de la vida de James Bond&#8230;\",\"datePublished\":\"2012-06-05T19:40:18+00:00\",\"dateModified\":\"2012-06-05T19:44:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i\"},\"wordCount\":1438,\"commentCount\":17,\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2012-1\\\/20120605_dredd.jpg\",\"keywords\":[\"Alma\",\"Day of the Dead\",\"Dredd\",\"Hannibal\",\"Iron Man 3\",\"Star Trek 2\",\"The Witches\",\"Trollhunters\",\"X-Men: First Class 2\",\"Zombies vs. Gladiators\"],\"articleSection\":[\"Cine\",\"Cine de C\u00f3mics\",\"Cine de Ciencia Ficci\u00f3n\",\"Cine de Fantas\u00eda\",\"Cine de Terror\",\"GdT\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i\",\"name\":\"&iquest;La secuela de X-Men: Primera Generaci&oacute;n podr&iacute;a ser &quot;D&iacute;as de futuro pasado&quot;?, Guillermo del Toro habla sobre sus incursiones en el mundo del cine animado, nueva imagen y sinopsis de Dredd, Clive Barker se har&aacute; cargo de Zombies vs. Gladiators, Mads Mikkelsen ser&aacute; el nuevo Dr. Hannibal Lecter, un curioso fake trailer de Star Trek 2, &iquest;A.I.M. en Iron Man 3? y Christopher Nolan no descarta hacerse cargo de la vida de James Bond... - Uruloki :: Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2012-1\\\/20120605_dredd.jpg\",\"datePublished\":\"2012-06-05T19:40:18+00:00\",\"dateModified\":\"2012-06-05T19:44:04+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i#primaryimage\",\"url\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2012-1\\\/20120605_dredd.jpg\",\"contentUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2012-1\\\/20120605_dredd.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&iquest;La secuela de X-Men: Primera Generaci&oacute;n podr&iacute;a ser &quot;D&iacute;as de futuro pasado&quot;?, Guillermo del Toro habla sobre sus incursiones en el mundo del cine animado, nueva imagen y sinopsis de Dredd, Clive Barker se har&aacute; cargo de Zombies vs. Gladiators, Mads Mikkelsen ser&aacute; el nuevo Dr. Hannibal Lecter, un curioso fake trailer de Star Trek 2, &iquest;A.I.M. en Iron Man 3? y Christopher Nolan no descarta hacerse cargo de la vida de James Bond&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/\",\"name\":\"Uruloki :: Blog\",\"description\":\"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\",\"name\":\"Uruloki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"caption\":\"Uruloki\"},\"sameAs\":[\"https:\\\/\\\/uruloki.org\"],\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/author\\\/admin-2-2-2\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"&iquest;La secuela de X-Men: Primera Generaci&oacute;n podr&iacute;a ser &quot;D&iacute;as de futuro pasado&quot;?, Guillermo del Toro habla sobre sus incursiones en el mundo del cine animado, nueva imagen y sinopsis de Dredd, Clive Barker se har&aacute; cargo de Zombies vs. Gladiators, Mads Mikkelsen ser&aacute; el nuevo Dr. Hannibal Lecter, un curioso fake trailer de Star Trek 2, &iquest;A.I.M. en Iron Man 3? y Christopher Nolan no descarta hacerse cargo de la vida de James Bond... - Uruloki :: Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i","og_locale":"es_ES","og_type":"article","og_title":"&iquest;La secuela de X-Men: Primera Generaci&oacute;n podr&iacute;a ser &quot;D&iacute;as de futuro pasado&quot;?, Guillermo del Toro habla sobre sus incursiones en el mundo del cine animado, nueva imagen y sinopsis de Dredd, Clive Barker se har&aacute; cargo de Zombies vs. Gladiators, Mads Mikkelsen ser&aacute; el nuevo Dr. Hannibal Lecter, un curioso fake trailer de Star Trek 2, &iquest;A.I.M. en Iron Man 3? y Christopher Nolan no descarta hacerse cargo de la vida de James Bond... - Uruloki :: Blog","og_description":"Sigamos dando vida a esto que nunca est&aacute; de m&aacute;s. Antes de nada una noticia de &uacute;ltima hora, y que aunque es rumor puede molar un rato largo si se hace realidad. Ain&#8217;t It Cool News indica que 20th Century Fox podr&iacute;a haber registrado en la MPAA el titulo &quot;D&iacute;as de futuro pasado&quot;. El tema [&hellip;]","og_url":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i","og_site_name":"Uruloki :: Blog","article_publisher":"https:\/\/www.facebook.com\/uruloki.org","article_published_time":"2012-06-05T19:40:18+00:00","article_modified_time":"2012-06-05T19:44:04+00:00","og_image":[{"url":"https:\/\/uruloki.org\/felipeblog\/images2012-1\/20120605_dredd.jpg","type":"","width":"","height":""}],"author":"Uruloki","twitter_card":"summary_large_image","twitter_creator":"@uruloki","twitter_site":"@uruloki","twitter_misc":{"Escrito por":"Uruloki","Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i#article","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i"},"author":{"name":"Uruloki","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"headline":"&iquest;La secuela de X-Men: Primera Generaci&oacute;n podr&iacute;a ser &quot;D&iacute;as de futuro pasado&quot;?, Guillermo del Toro habla sobre sus incursiones en el mundo del cine animado, nueva imagen y sinopsis de Dredd, Clive Barker se har&aacute; cargo de Zombies vs. Gladiators, Mads Mikkelsen ser&aacute; el nuevo Dr. Hannibal Lecter, un curioso fake trailer de Star Trek 2, &iquest;A.I.M. en Iron Man 3? y Christopher Nolan no descarta hacerse cargo de la vida de James Bond&#8230;","datePublished":"2012-06-05T19:40:18+00:00","dateModified":"2012-06-05T19:44:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i"},"wordCount":1438,"commentCount":17,"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/images2012-1\/20120605_dredd.jpg","keywords":["Alma","Day of the Dead","Dredd","Hannibal","Iron Man 3","Star Trek 2","The Witches","Trollhunters","X-Men: First Class 2","Zombies vs. Gladiators"],"articleSection":["Cine","Cine de C\u00f3mics","Cine de Ciencia Ficci\u00f3n","Cine de Fantas\u00eda","Cine de Terror","GdT"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uruloki.org\/felipeblog\/cine\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i","url":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i","name":"&iquest;La secuela de X-Men: Primera Generaci&oacute;n podr&iacute;a ser &quot;D&iacute;as de futuro pasado&quot;?, Guillermo del Toro habla sobre sus incursiones en el mundo del cine animado, nueva imagen y sinopsis de Dredd, Clive Barker se har&aacute; cargo de Zombies vs. Gladiators, Mads Mikkelsen ser&aacute; el nuevo Dr. Hannibal Lecter, un curioso fake trailer de Star Trek 2, &iquest;A.I.M. en Iron Man 3? y Christopher Nolan no descarta hacerse cargo de la vida de James Bond... - Uruloki :: Blog","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i#primaryimage"},"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/images2012-1\/20120605_dredd.jpg","datePublished":"2012-06-05T19:40:18+00:00","dateModified":"2012-06-05T19:44:04+00:00","author":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"breadcrumb":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uruloki.org\/felipeblog\/cine\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i#primaryimage","url":"https:\/\/uruloki.org\/felipeblog\/images2012-1\/20120605_dredd.jpg","contentUrl":"https:\/\/uruloki.org\/felipeblog\/images2012-1\/20120605_dredd.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/la-secuela-de-x-men-primera-generacin-podra-ser-das-de-futuro-pasado-guillermo-del-toro-habla-sobre-sus-incursiones-en-el-mundo-del-cine-animado-nueva-i#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uruloki.org\/felipeblog"},{"@type":"ListItem","position":2,"name":"&iquest;La secuela de X-Men: Primera Generaci&oacute;n podr&iacute;a ser &quot;D&iacute;as de futuro pasado&quot;?, Guillermo del Toro habla sobre sus incursiones en el mundo del cine animado, nueva imagen y sinopsis de Dredd, Clive Barker se har&aacute; cargo de Zombies vs. Gladiators, Mads Mikkelsen ser&aacute; el nuevo Dr. Hannibal Lecter, un curioso fake trailer de Star Trek 2, &iquest;A.I.M. en Iron Man 3? y Christopher Nolan no descarta hacerse cargo de la vida de James Bond&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.uruloki.org\/felipeblog\/#website","url":"https:\/\/www.uruloki.org\/felipeblog\/","name":"Uruloki :: Blog","description":"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uruloki.org\/felipeblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3","name":"Uruloki","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","caption":"Uruloki"},"sameAs":["https:\/\/uruloki.org"],"url":"https:\/\/www.uruloki.org\/felipeblog\/author\/admin-2-2-2"}]}},"_links":{"self":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/7937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/comments?post=7937"}],"version-history":[{"count":2,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/7937\/revisions"}],"predecessor-version":[{"id":7939,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/7937\/revisions\/7939"}],"wp:attachment":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/media?parent=7937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/categories?post=7937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/tags?post=7937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}