{"id":675,"date":"2006-06-01T14:54:50","date_gmt":"2006-06-01T22:54:50","guid":{"rendered":"https:\/\/uruloki.org\/felipeblog\/?p=675"},"modified":"2006-06-01T14:54:50","modified_gmt":"2006-06-01T22:54:50","slug":"a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras","status":"publish","type":"post","link":"https:\/\/www.uruloki.org\/felipeblog\/cine\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras","title":{"rendered":"A falta de pan, buenas son tortas: p&oacute;sters de Apocalypto, m&aacute;s Superman Returns y otras noticias comiqueras&#8230;"},"content":{"rendered":"<p>Ya se que no tienen nada que ver a nivel de g&eacute;nero, pero de nuevo ha salido otro p&oacute;ster de <a href=\"http:\/\/www.imdb.com\/title\/tt0348150\/\" target=\"_blank\" title=\"Info de Superman Returns\">Superman Returns<\/a> (2006) y en alg&uacute;n lado hay que ponerlo. En fin, la otra novedad es el p&oacute;ster de <a href=\"http:\/\/www.imdb.com\/title\/tt0472043\/\" target=\"_blank\" title=\"Info de Apocalypto\">Apocalypto<\/a> (2006), la nueva epopeya maya del histri&oacute;nico <a href=\"http:\/\/www.imdb.com\/name\/nm0000154\/\" target=\"_blank\" title=\"Filmograf&iacute;A de Mel Gibson\">Mel Gibson<\/a>&#8230; si, el que tiene problemas con el tama&ntilde;o de su cabeza como se demostr&oacute; en un <a href=\"https:\/\/uruloki.org\/felipeblog\/archives\/000456.html\">estudio preliminar emp&iacute;rico<\/a> y que m&aacute;s tarde <a href=\"https:\/\/uruloki.org\/felipeblog\/archives\/000807.html\">se confirm&oacute; en una famosa rueda de prensa en M&eacute;xico<\/a>. El film debe estar a puntito de salir a escena y seguro dar&aacute; que hablar, uno por que no entenderemos ni jota, cosa que no deber&iacute;a importar, <a href=\"http:\/\/www.imdb.com\/title\/tt0335345\/\" target=\"_blank\" title=\"Info de La Pasi&oacute;n\">La Pasi&oacute;n de Cristo <\/a> (2004) fue particularmente llamativa por este detalle, y otro por la violencia desmedida que supongo contendr&aacute; el film.<\/p>\n<p><a href=\"http:\/\/www.flickr.com\/photos\/27286063@N00\/157915284\/\" title=\"P&oacute;ster de Apocalypto\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/static.flickr.com\/62\/157915282_b75620e7f2_o.jpg\" width=\"240\" height=\"356\" alt=\"P&oacute;ster de Apocalypto\" border=\"1\" \/><\/a>&nbsp;<a href=\"http:\/\/www.flickr.com\/photos\/27286063@N00\/157915286\/\" title=\"Otro m&aacute;s de Superman Returns\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/static.flickr.com\/78\/157915283_397e6156c6_o.jpg\" width=\"240\" height=\"356\" alt=\"Otro m&aacute;s de Superman Returns\" border=\"1\" \/><\/a><\/p>\n<p>En fin, <a href=\"http:\/\/www.imdb.com\/name\/nm0004695\/\" target=\"_blank\" title=\"Filmograf&iacute;a de Jessica Alba\">Jessica &quot;Sue Storm&quot; Alba<\/a> ha <a href=\"http:\/\/superherohype.com\/news\/fantasticfournews.php?id=4323\" target=\"_blank\" title=\"Noticia en Superherohype\">declarado recientemente a la MTV<\/a> que el rodaje de la secuela de <a href=\"http:\/\/www.imdb.com\/title\/tt0120667\/\" target=\"_blank\" title=\"Info de Los 4 Fant&aacute;sticos\">Los 4 Fant&aacute;sticos<\/a> (2005) comenzar&aacute; en agosto de este a&ntilde;o, adem&aacute;s h<a href=\"https:\/\/uruloki.org\/felipeblog\/archives\/000934.html\" title=\"Primeros rumores del temita Silver Surfer\">a confirmado la aparici&oacute;n de Silver Surfer como h&eacute;roe \/ villano<\/a>&#8230; eso si, seg&uacute;n <strong>Alba<\/strong> esta no ser&aacute; la &uacute;nica aparici&oacute;n estelar del film, alguien permanecer&aacute; oculto en la sombra, &iquest;lo dejar&aacute;n preparado para una tercera parte? Para rematar las declaraciones coment&oacute; que su personaje se debatir&aacute; en un tri&aacute;ngulo amoroso (???) y demostrar&aacute; que es la m&aacute;s poderosa del grupo&#8230; &iquest;o la m&aacute;s famosa?<\/p>\n<p>Bueno, lo que no me esperaba es la noticia de que el CEO de la <strong>Marvel<\/strong> <a href=\"http:\/\/www.imdb.com\/name\/nm0032696\/\" target=\"_blank\" title=\"Producciones de Avi Arad\">Avi Arad<\/a>, uno de los art&iacute;fices del renacimiento del cine moderno de c&oacute;mics, <a href=\"http:\/\/www.aintitcool.com\/display.cgi?id=23471\" target=\"_blank\" title=\"Noticia y documento de la Marvel sobre la baja de Avi Arad\">abandona el sello de unas de las factor&iacute;as de superh&eacute;roes m&aacute;s importantes del mundo<\/a>&#8230; su nuevo destino, la producci&oacute;n como sello independiente bajo el sello <strong>Avi Arad Productions<\/strong>! Eso si, contin&uacute;a como productor de <a href=\"http:\/\/www.imdb.com\/title\/tt0413300\/\" target=\"_blank\" title=\"Info de Spiderman 3\">Spiderman 3<\/a> (2007) y sus posibles secuelas, <a href=\"http:\/\/www.imdb.com\/title\/tt0371746\/\" target=\"_blank\" title=\"Info de Ironman\">Ironman<\/a> (2008) y <strong>The Incredible Hulk<\/strong> (20??), t&iacute;tulo en el que <a href=\"http:\/\/www.cinematical.com\/2006\/05\/29\/avi-arad-admits-to-silver-surfer\/\" target=\"_blank\" title=\"Comentarios de Avi Arad acerca de la secuela de Hulk\">Avi Arad ya ha comentado<\/a> que <a href=\"http:\/\/www.imdb.com\/name\/nm0051509\/\" target=\"_blank\" title=\"Filmograf&iacute;a de Eric Bana\">Eric Bana<\/a> volver&iacute;a a interpretar a gigante verde.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ya se que no tienen nada que ver a nivel de g&eacute;nero, pero de nuevo ha salido otro p&oacute;ster de Superman Returns (2006) y en alg&uacute;n lado hay que ponerlo. En fin, la otra novedad es el p&oacute;ster de Apocalypto (2006), la nueva epopeya maya del histri&oacute;nico Mel Gibson&#8230; si, el que tiene problemas con [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,10],"tags":[],"class_list":["post-675","post","type-post","status-publish","format-standard","hentry","category-cine","category-cine-de-comics"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A falta de pan, buenas son tortas: p&oacute;sters de Apocalypto, m&aacute;s Superman Returns y otras noticias comiqueras... - Uruloki :: Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uruloki.org\/felipeblog\/cine\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A falta de pan, buenas son tortas: p&oacute;sters de Apocalypto, m&aacute;s Superman Returns y otras noticias comiqueras... - Uruloki :: Blog\" \/>\n<meta property=\"og:description\" content=\"Ya se que no tienen nada que ver a nivel de g&eacute;nero, pero de nuevo ha salido otro p&oacute;ster de Superman Returns (2006) y en alg&uacute;n lado hay que ponerlo. En fin, la otra novedad es el p&oacute;ster de Apocalypto (2006), la nueva epopeya maya del histri&oacute;nico Mel Gibson&#8230; si, el que tiene problemas con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uruloki.org\/felipeblog\/cine\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras\" \/>\n<meta property=\"og:site_name\" content=\"Uruloki :: Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uruloki.org\" \/>\n<meta property=\"article:published_time\" content=\"2006-06-01T22:54:50+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/static.flickr.com\/62\/157915282_b75620e7f2_o.jpg\" \/>\n<meta name=\"author\" content=\"Uruloki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uruloki\" \/>\n<meta name=\"twitter:site\" content=\"@uruloki\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Uruloki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras\"},\"author\":{\"name\":\"Uruloki\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"headline\":\"A falta de pan, buenas son tortas: p&oacute;sters de Apocalypto, m&aacute;s Superman Returns y otras noticias comiqueras&#8230;\",\"datePublished\":\"2006-06-01T22:54:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras\"},\"wordCount\":409,\"commentCount\":13,\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/static.flickr.com\\\/62\\\/157915282_b75620e7f2_o.jpg\",\"articleSection\":[\"Cine\",\"Cine de C\u00f3mics\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras\",\"name\":\"A falta de pan, buenas son tortas: p&oacute;sters de Apocalypto, m&aacute;s Superman Returns y otras noticias comiqueras... - Uruloki :: Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/static.flickr.com\\\/62\\\/157915282_b75620e7f2_o.jpg\",\"datePublished\":\"2006-06-01T22:54:50+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras#primaryimage\",\"url\":\"http:\\\/\\\/static.flickr.com\\\/62\\\/157915282_b75620e7f2_o.jpg\",\"contentUrl\":\"http:\\\/\\\/static.flickr.com\\\/62\\\/157915282_b75620e7f2_o.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A falta de pan, buenas son tortas: p&oacute;sters de Apocalypto, m&aacute;s Superman Returns y otras noticias comiqueras&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/\",\"name\":\"Uruloki :: Blog\",\"description\":\"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\",\"name\":\"Uruloki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"caption\":\"Uruloki\"},\"sameAs\":[\"https:\\\/\\\/uruloki.org\"],\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/author\\\/admin-2-2-2\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A falta de pan, buenas son tortas: p&oacute;sters de Apocalypto, m&aacute;s Superman Returns y otras noticias comiqueras... - Uruloki :: Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uruloki.org\/felipeblog\/cine\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras","og_locale":"es_ES","og_type":"article","og_title":"A falta de pan, buenas son tortas: p&oacute;sters de Apocalypto, m&aacute;s Superman Returns y otras noticias comiqueras... - Uruloki :: Blog","og_description":"Ya se que no tienen nada que ver a nivel de g&eacute;nero, pero de nuevo ha salido otro p&oacute;ster de Superman Returns (2006) y en alg&uacute;n lado hay que ponerlo. En fin, la otra novedad es el p&oacute;ster de Apocalypto (2006), la nueva epopeya maya del histri&oacute;nico Mel Gibson&#8230; si, el que tiene problemas con [&hellip;]","og_url":"https:\/\/www.uruloki.org\/felipeblog\/cine\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras","og_site_name":"Uruloki :: Blog","article_publisher":"https:\/\/www.facebook.com\/uruloki.org","article_published_time":"2006-06-01T22:54:50+00:00","og_image":[{"url":"http:\/\/static.flickr.com\/62\/157915282_b75620e7f2_o.jpg","type":"","width":"","height":""}],"author":"Uruloki","twitter_card":"summary_large_image","twitter_creator":"@uruloki","twitter_site":"@uruloki","twitter_misc":{"Escrito por":"Uruloki","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras#article","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras"},"author":{"name":"Uruloki","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"headline":"A falta de pan, buenas son tortas: p&oacute;sters de Apocalypto, m&aacute;s Superman Returns y otras noticias comiqueras&#8230;","datePublished":"2006-06-01T22:54:50+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras"},"wordCount":409,"commentCount":13,"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras#primaryimage"},"thumbnailUrl":"http:\/\/static.flickr.com\/62\/157915282_b75620e7f2_o.jpg","articleSection":["Cine","Cine de C\u00f3mics"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uruloki.org\/felipeblog\/cine\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras","url":"https:\/\/www.uruloki.org\/felipeblog\/cine\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras","name":"A falta de pan, buenas son tortas: p&oacute;sters de Apocalypto, m&aacute;s Superman Returns y otras noticias comiqueras... - Uruloki :: Blog","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras#primaryimage"},"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras#primaryimage"},"thumbnailUrl":"http:\/\/static.flickr.com\/62\/157915282_b75620e7f2_o.jpg","datePublished":"2006-06-01T22:54:50+00:00","author":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"breadcrumb":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uruloki.org\/felipeblog\/cine\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras#primaryimage","url":"http:\/\/static.flickr.com\/62\/157915282_b75620e7f2_o.jpg","contentUrl":"http:\/\/static.flickr.com\/62\/157915282_b75620e7f2_o.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/a-falta-de-pan-buenas-son-tortas-psters-de-apocalypto-ms-superman-returns-y-otras-noticias-comiqueras#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uruloki.org\/felipeblog"},{"@type":"ListItem","position":2,"name":"A falta de pan, buenas son tortas: p&oacute;sters de Apocalypto, m&aacute;s Superman Returns y otras noticias comiqueras&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.uruloki.org\/felipeblog\/#website","url":"https:\/\/www.uruloki.org\/felipeblog\/","name":"Uruloki :: Blog","description":"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uruloki.org\/felipeblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3","name":"Uruloki","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","caption":"Uruloki"},"sameAs":["https:\/\/uruloki.org"],"url":"https:\/\/www.uruloki.org\/felipeblog\/author\/admin-2-2-2"}]}},"_links":{"self":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/comments?post=675"}],"version-history":[{"count":0,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/675\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/media?parent=675"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/categories?post=675"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/tags?post=675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}