{"id":5335,"date":"2011-02-21T22:56:28","date_gmt":"2011-02-21T21:56:28","guid":{"rendered":"https:\/\/uruloki.org\/felipeblog\/?p=5335"},"modified":"2011-02-21T22:56:28","modified_gmt":"2011-02-21T21:56:28","slug":"kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac","status":"publish","type":"post","link":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac","title":{"rendered":"Kevin Costner podr&iacute;a incorporarse a Superman: Man of Steel, nuevo din&aacute;mico spot de Transformers: Dark of the Moon, Rob Zombie deja claro que el remake de El terror no tiene forma est&aacute; muerto y aporta sobre The Lords of Salem, ya tenemos Van Helsing en Dracula 3D, concept art de Superman Flyby y nada m&aacute;s&#8230;"},"content":{"rendered":"<p>Bienvenidos a un lunes de relax. Tras unos d&iacute;as bastante entretenidos repletos de noticias interesantes es momento de optar por una jornada m&aacute;s tranquilita e ideal para hablar tambi&eacute;n de otras cosas. Antes de nada avisaros que entramos en la semana de los Oscar. En la madrugada del domingo que viene al lunes pr&oacute;ximo, al menos en Espa&ntilde;a, se desvelar&aacute;n los triunfadores de los premios de la <strong>Academia del Cine USA<\/strong> de este a&ntilde;o. La cosa no puede estar m&aacute;s re&ntilde;ida y por mi parte he podido ver la gran mayor&iacute;a de pel&iacute;culas de este a&ntilde;o y solo puedo decir que no lo tengo nada claro. Me siento muy atra&iacute;do por <a href=\"http:\/\/www.imdb.es\/title\/tt1375666\/\" target=\"_blank\">Origen<\/a> (<em>Inception<\/em>, 2010) de <a href=\"http:\/\/www.imdb.es\/name\/nm0634240\/\" target=\"_blank\">Christopher Nolan<\/a>, con sus 8 candidaturas y que estoy seguro rascar&aacute; algo m&aacute;s que premios t&eacute;cnicos. Pero claro, <a href=\"http:\/\/www.imdb.es\/title\/tt1285016\/\" target=\"_blank\">La red social<\/a> (<em>The Social Network<\/em>, 2010) de <a href=\"http:\/\/www.imdb.es\/name\/nm0000399\/\" target=\"_blank\">David Fincher<\/a> que tambi&eacute;n me ha molado un rato largo. Esta tambi&eacute;n atesora 8 candidaturas pero lo suyo ir&aacute; m&aacute;s apuntando a los grandes premios a los que optan su realizador, guionista, etc. Pero claro, recientemente he podido ver en los cines <a href=\"http:\/\/www.imdb.es\/title\/tt1542344\/\" target=\"_blank\">127 horas<\/a> (<em>127 Hours<\/em>, 2010) de <a href=\"http:\/\/www.imdb.es\/name\/nm0000965\/\" target=\"_blank\">Danny Boyle<\/a>, 6 candidaturas, <a href=\"http:\/\/www.imdb.es\/title\/tt1403865\/\" target=\"_blank\">Valor de ley<\/a> (<em>True Grit<\/em>, 2010) de <a href=\"http:\/\/www.imdb.es\/name\/nm0001054\/\" target=\"_blank\">Joel<\/a> y <a href=\"http:\/\/www.imdb.es\/name\/nm0001053\/\" target=\"_blank\">Ethan Coen<\/a>, 10 posibles premios, <a href=\"http:\/\/www.imdb.es\/title\/tt0964517\/\" target=\"_blank\">The Fighter<\/a> (2010) de <a href=\"http:\/\/www.imdb.es\/name\/nm0751102\/\" target=\"_blank\">David O. Russell<\/a>, 7 nominaciones, y este mismo fin de semana la magistral <a href=\"http:\/\/www.imdb.es\/title\/tt0947798\/\" target=\"_blank\">Cisne negro<\/a> (<em>Black Swan<\/em>, 2010) de <a href=\"http:\/\/www.imdb.es\/name\/nm0004716\/\" target=\"_blank\">Darren Aronofsky<\/a>, oportunidad de rascar 5 figuritas de oro. Y la verdad, a cada cual me ha ido gustando m&aacute;s y m&aacute;s. Se presenta un a&ntilde;o claramente complicado&#8230; y todav&iacute;a tengo pendiente <a href=\"http:\/\/www.imdb.es\/title\/tt1504320\/\" target=\"_blank\">El discurso del rey<\/a> (<em>The King&#8217;s Speech<\/em>,2010) de <a href=\"http:\/\/www.imdb.es\/name\/nm0393799\/\" target=\"_blank\">Tom Hooper<\/a>, sus 12 posibles premios la hace partir como la gran favorita&#8230; y m&aacute;s si tenems en cuenta la de sorpresas que hay ultimamente.<\/p>\n<p class=\"centrado\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2011-1\/20110221-superman-concept-art.jpg\" alt=\"Concept Art del Superman que pudo dirigir McG\" width=\"450\" height=\"576\" \/><br \/>\n<em>Concept Art del Superman que pudo dirigir McG (<a href=\"http:\/\/brohawk.deviantart.com\/art\/Mc-G-s-Superman-Movie-Suit-41370119?q=gallery%3Abrohawk\/20409497&amp;qo=187\" target=\"_blank\">v&iacute;a DevianArt<\/a>) <\/em><\/p>\n<p>Vayamos ahora con las pocas novedades de la jornada. Comencemos con un posible bombazo de &uacute;ltima hora. <a href=\"http:\/\/www.deadline.com\/2011\/02\/kevin-costner-up-up-and-away-for-superman-role\/\" target=\"_blank\">Deadline.com anuncia<\/a> para sorpresa de todos que <a href=\"http:\/\/www.imdb.es\/name\/nm0000126\/\" target=\"_blank\">Kevin Costner<\/a> podr&iacute;a estar negociando con <strong>Warner Bros.<\/strong>, <strong>Legendary Pictures<\/strong> y <a href=\"http:\/\/www.imdb.es\/name\/nm0634240\/\" target=\"_blank\">Christopher Nolan<\/a> para unirse al reparto de <a href=\"http:\/\/www.imdb.es\/title\/tt0770828\/\" target=\"_blank\">Superman: Man of Steel<\/a> (2012) de <a href=\"http:\/\/www.imdb.es\/name\/nm0811583\/\" target=\"_blank\">Zack Snyder<\/a> encarnando a un personaje no desvelado pero crucial para la nueva historia del nuevo <strong>Clark Kent<\/strong> (<a href=\"http:\/\/www.imdb.es\/name\/nm0147147\/\" target=\"_blank\">Henry Cavill<\/a>). <strong>Costner<\/strong>, figura importante en el <strong>Hollywood<\/strong> de la pasada d&eacute;cada y ahora situado en papeles de proyectos de corte no <em>blockbuster<\/em>, podr&iacute;a encajar como anillo al dedo en el proyecto y dar este toque de veteran&iacute;a que siempre es necesario. Aunque queda ver para qu&eacute; papel podr&iacute;a valer&#8230; &iquest;os lo imagin&aacute;is como un <strong>Zod<\/strong> gran villano?, &iquest;o m&aacute;s encarnando a <strong>Pa Kent<\/strong>?, y si no os encaja&#8230; &iquest;alguna otra propuesta? Ahora os dejo con un nuevo spot de 30 segundos de <a href=\"http:\/\/www.imdb.es\/title\/tt1399103\/\" target=\"_blank\">Transformers: Dark of the Moon<\/a> (2011) de <a href=\"http:\/\/www.imdb.es\/name\/nm0000881\/\" target=\"_blank\">Michael Bay<\/a> que ha sido emitido en el transcurso de la carrera <strong>Nascar<\/strong> de las <strong>500 millas de Daytona<\/strong> que se ha celebrado este pasado fin de semana. El spot <a href=\"https:\/\/uruloki.org\/felipeblog\/cine-de-ciencia-ficcin\/super-bowl-xlv-clips-de-super-8-y-transformers-dark-of-the-moon\">no se diferencia mucho del visto en la Super Bowl XLV<\/a>, pero aun confirma que nos espera un despiporre de efectos especiales y destrucci&oacute;n masiva all&aacute; donde los <strong>Autobots<\/strong> y los <strong>Decepticons<\/strong> decidan partirse la cara&#8230; crucemos los dedos porque podr&iacute;a molar.<\/p>\n<div class=\"video\"><object type=\"application\/x-shockwave-flash\" data=\"http:\/\/www.youtube.com\/v\/B1cc4NAbPpg?fs=1&amp;hl=es_ES\" height=\"380\" width=\"625\"><param name=\"movie\" value=\"http:\/\/www.youtube.com\/v\/B1cc4NAbPpg?fs=1&amp;hl=es_ES\" \/><param name=\"allowFullScreen\" value=\"true\" \/><\/object><\/div>\n<p>Sigamos con m&aacute;s noticias de esas de andar por casa. <a href=\"http:\/\/twitchfilm.com\/news\/2011\/02\/rutger-hauer-is-van-helsing-in-dario-argentos-dracula-3d.php\" target=\"_blank\">Twitch Films nos adelanta<\/a> que el <a href=\"http:\/\/www.imdb.es\/title\/tt1441944\/\" target=\"_blank\">Dracula 3D<\/a> (&iquest;?) que prepara <a href=\"http:\/\/www.imdb.es\/name\/nm0000783\/\" target=\"_blank\">Dario Argento<\/a> con producci&oacute;n de <a href=\"http:\/\/www.imdb.es\/name\/nm0148554\/\" target=\"_blank\">Enrique Cerezo<\/a> y que ser&aacute; rodado en Italia con alg&uacute;n que otro actor espa&ntilde;ol tiene ya su profesor <strong>Abraham Van Helsing<\/strong>. El elegido  es el veterano <a href=\"http:\/\/www.imdb.es\/name\/nm0000442\/\" target=\"_blank\">Rutger Hauer<\/a>, ahora en boca de todos en USA por su violento papel en la serie  Z que es <a href=\"http:\/\/www.imdb.es\/title\/tt1640459\/\" target=\"_blank\">Hobo with a Shotgun<\/a> (2011). El rodaje arranca en mayo de este a&ntilde;o, seguro que tarde o temprano tenemos nuevas incorporaciones. <a href=\"http:\/\/www.empireonline.com\/news\/feed.asp?NID=30225\" target=\"_blank\">Otro portal que tambi&eacute;n aporta luz sobre futuros proyectos es Empire<\/a>. Charlando con <a href=\"http:\/\/www.imdb.es\/name\/nm0957772\/\" target=\"_blank\">Rob Zombie<\/a> la web obtiene en primicia dos importantes datos. Primero que el <em>remake<\/em> de <a href=\"http:\/\/www.imdb.es\/title\/tt0094761\/\" target=\"_blank\">El terror no tiene forma<\/a> (<em>The Blob<\/em>, 1988) de <a href=\"http:\/\/www.imdb.es\/name\/nm0751080\/\" target=\"_blank\">Chuck Russell<\/a> ha muerto, o por lo menos el proyecto que <strong>Zombie<\/strong> ten&iacute;a sobre  la mesa. Comenta el bueno de <strong>Rob<\/strong> que ha decidido abandonar el mundo <em>remake<\/em> por la complejidad que tiene dejar contento a todo el mundo. Reconoce que con <a href=\"http:\/\/www.imdb.es\/title\/tt1311067\/\" target=\"_blank\">Halloween II<\/a> (2009) lo pas&oacute; mal ya que o se pasaba de <em>remake<\/em>, copiando demasiado, o en otros casos se quedaba corto, con las consiguientes cr&iacute;ticas sobre los aspectos no explotados. Luego aprovecha para hablar sobre <a href=\"http:\/\/www.imdb.es\/title\/tt1731697\/\" target=\"_blank\">The Lords of Salem<\/a> (2012), casi seguro su pr&oacute;ximo proyecto, al que espera que siga <strong>Tyrannosaurus Rex<\/strong> (&iquest;?).   La historia de <strong>The Lords of Salem<\/strong> contar&aacute; como de las 20 personas que fueron ajusticiadas en los juicios de <strong>Salem<\/strong> por brujer&iacute;a, supuestamente todas inocentes, cuatro fueron brujas de verdad. En el presente los esp&iacute;ritus de estas brujas se tomar&aacute;n venganza. En cuanto al estilo del film, <strong>Rob Zombie<\/strong> habla de una alejamiento del extremo estilo visto en <a href=\"http:\/\/www.imdb.es\/title\/tt0251736\/\" target=\"_blank\">La casa de los 1000 cad&aacute;veres<\/a> (<em>House of 1000 Corpses<\/em>, 2003) y que esta vez apostar&aacute; por hacer un film serio pero sombr&iacute;o y siniestro.<\/p>\n<p><strong class=\"nota\">&nbsp;NOTA&nbsp;<\/strong> El dise&ntilde;o del traje de <strong>Superman<\/strong> que riega el post pertenece al proyecto que <a href=\"http:\/\/www.imdb.es\/name\/nm0629334\/\" target=\"_blank\">McG<\/a> tuvo entre manos hace unos cuantos a&ntilde;os, que se iba a titular  <strong>Superman Flyby<\/strong> y que contaba con un gui&oacute;n escrito por J.J. Abrams. <a href=\"https:\/\/uruloki.org\/felipeblog\/cine-de-ciencia-ficcin\/el-superman-vs-doomsday-que-pudo-ser-y-no-fue-neill-blomkamp-y-sharlto-copley-juntos-de-nuevo-en-elysium-iron-man-3-ser-una-secuela-en-la-lnea-temporal-de-thor-captain-america-the\">Hace un par de meses<\/a> pudimos ver algunos dibujos realizados por <a href=\"http:\/\/www.imdb.es\/name\/nm0426272\/\" target=\"_blank\">Steve Johnson<\/a> y <strong>Edge FX<\/strong> para este y la no nata secuela de <a href=\"http:\/\/www.imdb.es\/title\/tt0348150\/\" target=\"_blank\">Superman Returns<\/a> (2006). <a href=\"http:\/\/twitter.com\/#!\/DNMRULES\/statuses\/39527142509383680\" target=\"_blank\">Gracias a @DMNRULES por el aviso<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bienvenidos a un lunes de relax. Tras unos d&iacute;as bastante entretenidos repletos de noticias interesantes es momento de optar por una jornada m&aacute;s tranquilita e ideal para hablar tambi&eacute;n de otras cosas. Antes de nada avisaros que entramos en la semana de los Oscar. En la madrugada del domingo que viene al lunes pr&oacute;ximo, al [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,8,9,14],"tags":[1329,240,1029,1474,1583],"class_list":["post-5335","post","type-post","status-publish","format-standard","hentry","category-cine-de-comics","category-cine-de-ciencia-ficcion","category-cine-de-terror","category-arte-conceptual","tag-dracula-3d","tag-superman-man-of-steel","tag-the-blob","tag-the-lords-of-salem","tag-transformers-dark-of-the-moon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kevin Costner podr&iacute;a incorporarse a Superman: Man of Steel, nuevo din&aacute;mico spot de Transformers: Dark of the Moon, Rob Zombie deja claro que el remake de El terror no tiene forma est&aacute; muerto y aporta sobre The Lords of Salem, ya tenemos Van Helsing en Dracula 3D, concept art de Superman Flyby y nada m&aacute;s... - Uruloki :: Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kevin Costner podr&iacute;a incorporarse a Superman: Man of Steel, nuevo din&aacute;mico spot de Transformers: Dark of the Moon, Rob Zombie deja claro que el remake de El terror no tiene forma est&aacute; muerto y aporta sobre The Lords of Salem, ya tenemos Van Helsing en Dracula 3D, concept art de Superman Flyby y nada m&aacute;s... - Uruloki :: Blog\" \/>\n<meta property=\"og:description\" content=\"Bienvenidos a un lunes de relax. Tras unos d&iacute;as bastante entretenidos repletos de noticias interesantes es momento de optar por una jornada m&aacute;s tranquilita e ideal para hablar tambi&eacute;n de otras cosas. Antes de nada avisaros que entramos en la semana de los Oscar. En la madrugada del domingo que viene al lunes pr&oacute;ximo, al [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac\" \/>\n<meta property=\"og:site_name\" content=\"Uruloki :: Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uruloki.org\" \/>\n<meta property=\"article:published_time\" content=\"2011-02-21T21:56:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uruloki.org\/felipeblog\/images2011-1\/20110221-superman-concept-art.jpg\" \/>\n<meta name=\"author\" content=\"Uruloki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uruloki\" \/>\n<meta name=\"twitter:site\" content=\"@uruloki\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Uruloki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac\"},\"author\":{\"name\":\"Uruloki\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"headline\":\"Kevin Costner podr&iacute;a incorporarse a Superman: Man of Steel, nuevo din&aacute;mico spot de Transformers: Dark of the Moon, Rob Zombie deja claro que el remake de El terror no tiene forma est&aacute; muerto y aporta sobre The Lords of Salem, ya tenemos Van Helsing en Dracula 3D, concept art de Superman Flyby y nada m&aacute;s&#8230;\",\"datePublished\":\"2011-02-21T21:56:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac\"},\"wordCount\":1066,\"commentCount\":15,\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2011-1\\\/20110221-superman-concept-art.jpg\",\"keywords\":[\"Dracula 3D\",\"Superman: Man of Steel\",\"The Blob\",\"The Lords of Salem\",\"Transformers: Dark of the Moon\"],\"articleSection\":[\"Cine de C\u00f3mics\",\"Cine de Ciencia Ficci\u00f3n\",\"Cine de Terror\",\"Concept Art\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac\",\"name\":\"Kevin Costner podr&iacute;a incorporarse a Superman: Man of Steel, nuevo din&aacute;mico spot de Transformers: Dark of the Moon, Rob Zombie deja claro que el remake de El terror no tiene forma est&aacute; muerto y aporta sobre The Lords of Salem, ya tenemos Van Helsing en Dracula 3D, concept art de Superman Flyby y nada m&aacute;s... - Uruloki :: Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2011-1\\\/20110221-superman-concept-art.jpg\",\"datePublished\":\"2011-02-21T21:56:28+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac#primaryimage\",\"url\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2011-1\\\/20110221-superman-concept-art.jpg\",\"contentUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2011-1\\\/20110221-superman-concept-art.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kevin Costner podr&iacute;a incorporarse a Superman: Man of Steel, nuevo din&aacute;mico spot de Transformers: Dark of the Moon, Rob Zombie deja claro que el remake de El terror no tiene forma est&aacute; muerto y aporta sobre The Lords of Salem, ya tenemos Van Helsing en Dracula 3D, concept art de Superman Flyby y nada m&aacute;s&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/\",\"name\":\"Uruloki :: Blog\",\"description\":\"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\",\"name\":\"Uruloki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"caption\":\"Uruloki\"},\"sameAs\":[\"https:\\\/\\\/uruloki.org\"],\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/author\\\/admin-2-2-2\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kevin Costner podr&iacute;a incorporarse a Superman: Man of Steel, nuevo din&aacute;mico spot de Transformers: Dark of the Moon, Rob Zombie deja claro que el remake de El terror no tiene forma est&aacute; muerto y aporta sobre The Lords of Salem, ya tenemos Van Helsing en Dracula 3D, concept art de Superman Flyby y nada m&aacute;s... - Uruloki :: Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac","og_locale":"es_ES","og_type":"article","og_title":"Kevin Costner podr&iacute;a incorporarse a Superman: Man of Steel, nuevo din&aacute;mico spot de Transformers: Dark of the Moon, Rob Zombie deja claro que el remake de El terror no tiene forma est&aacute; muerto y aporta sobre The Lords of Salem, ya tenemos Van Helsing en Dracula 3D, concept art de Superman Flyby y nada m&aacute;s... - Uruloki :: Blog","og_description":"Bienvenidos a un lunes de relax. Tras unos d&iacute;as bastante entretenidos repletos de noticias interesantes es momento de optar por una jornada m&aacute;s tranquilita e ideal para hablar tambi&eacute;n de otras cosas. Antes de nada avisaros que entramos en la semana de los Oscar. En la madrugada del domingo que viene al lunes pr&oacute;ximo, al [&hellip;]","og_url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac","og_site_name":"Uruloki :: Blog","article_publisher":"https:\/\/www.facebook.com\/uruloki.org","article_published_time":"2011-02-21T21:56:28+00:00","og_image":[{"url":"https:\/\/uruloki.org\/felipeblog\/images2011-1\/20110221-superman-concept-art.jpg","type":"","width":"","height":""}],"author":"Uruloki","twitter_card":"summary_large_image","twitter_creator":"@uruloki","twitter_site":"@uruloki","twitter_misc":{"Escrito por":"Uruloki","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac#article","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac"},"author":{"name":"Uruloki","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"headline":"Kevin Costner podr&iacute;a incorporarse a Superman: Man of Steel, nuevo din&aacute;mico spot de Transformers: Dark of the Moon, Rob Zombie deja claro que el remake de El terror no tiene forma est&aacute; muerto y aporta sobre The Lords of Salem, ya tenemos Van Helsing en Dracula 3D, concept art de Superman Flyby y nada m&aacute;s&#8230;","datePublished":"2011-02-21T21:56:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac"},"wordCount":1066,"commentCount":15,"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/images2011-1\/20110221-superman-concept-art.jpg","keywords":["Dracula 3D","Superman: Man of Steel","The Blob","The Lords of Salem","Transformers: Dark of the Moon"],"articleSection":["Cine de C\u00f3mics","Cine de Ciencia Ficci\u00f3n","Cine de Terror","Concept Art"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac","url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac","name":"Kevin Costner podr&iacute;a incorporarse a Superman: Man of Steel, nuevo din&aacute;mico spot de Transformers: Dark of the Moon, Rob Zombie deja claro que el remake de El terror no tiene forma est&aacute; muerto y aporta sobre The Lords of Salem, ya tenemos Van Helsing en Dracula 3D, concept art de Superman Flyby y nada m&aacute;s... - Uruloki :: Blog","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac#primaryimage"},"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/images2011-1\/20110221-superman-concept-art.jpg","datePublished":"2011-02-21T21:56:28+00:00","author":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"breadcrumb":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac#primaryimage","url":"https:\/\/uruloki.org\/felipeblog\/images2011-1\/20110221-superman-concept-art.jpg","contentUrl":"https:\/\/uruloki.org\/felipeblog\/images2011-1\/20110221-superman-concept-art.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/kevin-costner-podra-incorporarse-a-superman-man-of-steel-nuevo-dinmico-spot-de-transformers-dark-of-the-moon-rob-zombie-deja-claro-que-el-remake-de-el-terror-no-tiene-forma-estaac#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uruloki.org\/felipeblog"},{"@type":"ListItem","position":2,"name":"Kevin Costner podr&iacute;a incorporarse a Superman: Man of Steel, nuevo din&aacute;mico spot de Transformers: Dark of the Moon, Rob Zombie deja claro que el remake de El terror no tiene forma est&aacute; muerto y aporta sobre The Lords of Salem, ya tenemos Van Helsing en Dracula 3D, concept art de Superman Flyby y nada m&aacute;s&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.uruloki.org\/felipeblog\/#website","url":"https:\/\/www.uruloki.org\/felipeblog\/","name":"Uruloki :: Blog","description":"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uruloki.org\/felipeblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3","name":"Uruloki","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","caption":"Uruloki"},"sameAs":["https:\/\/uruloki.org"],"url":"https:\/\/www.uruloki.org\/felipeblog\/author\/admin-2-2-2"}]}},"_links":{"self":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/5335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/comments?post=5335"}],"version-history":[{"count":1,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/5335\/revisions"}],"predecessor-version":[{"id":5336,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/5335\/revisions\/5336"}],"wp:attachment":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/media?parent=5335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/categories?post=5335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/tags?post=5335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}