{"id":3591,"date":"2010-01-22T19:27:06","date_gmt":"2010-01-22T18:27:06","guid":{"rendered":"https:\/\/uruloki.org\/felipeblog\/?p=3591"},"modified":"2010-01-22T20:40:43","modified_gmt":"2010-01-22T19:40:43","slug":"jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin","status":"publish","type":"post","link":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin","title":{"rendered":"Jason Momoa ser&aacute; Conan de Cimmeria y &iquest;Mickey Rourke su padre Corin?, m&aacute;s incorporaciones interesantes para Burke and Hare, The Graveyard Book de Neil Gaiman muere y resucita, im&aacute;genes de secuencias en la Tierra de Avatar&#8230;"},"content":{"rendered":"<p>Al fin es viernes. Despu&eacute;s de una semana de infarto en todos los aspectos, l&uacute;dicos y laborales, toca un fin de semana donde habr&aacute; que hacer, lo quiera o no, de todo un poco. Entre esta tareas hay que publicar cosillas en el blog. Comencemos con el bombazo de la jornada. A primera hora de la ma&ntilde;ana <a href=\"http:\/\/www.deadline.com\/hollywood\/toldja-conan-the-barbarian-hires-momoa\/\" target=\"_blank\">Deadline Hollywood sorprend&iacute;a a todos<\/a> lanzando una primicia que <a href=\"http:\/\/www.heatvisionblog.com\/2010\/01\/jason-momoa-playing-conan-the-barbarian.html\" target=\"_blank\">no tardar&iacute;a en confirmarse<\/a>. <strong>Nu Image<\/strong> \/ <strong>Millenium Films<\/strong> y <strong>Lionsgate<\/strong> ya hab&iacute;an decidido qui&eacute;n iba a ser el actor que interpretar&iacute;a a <strong>Conan<\/strong> de <strong>Cimmeria<\/strong> en <a href=\"http:\/\/www.imdb.es\/title\/tt0816462\/\" target=\"_blank\">Conan<\/a> (2011) de <a href=\"http:\/\/www.imdb.es\/name\/nm1197971\/\" target=\"_blank\">Marcus Nispel<\/a>. Como recordar&eacute;is la cosa estaba entre <a href=\"http:\/\/www.imdb.es\/name\/nm1553725\/\" target=\"_blank\">Kellan Luz<\/a>, <a href=\"http:\/\/www.imdb.es\/name\/nm0597388\/\" target=\"_blank\">Jason Momoa<\/a> y, supuestamente <a href=\"http:\/\/www.imdb.es\/name\/nm0655585\/\" target=\"_blank\">Jared Padalecki<\/a>. Pues nada, finalmente el que se hace con el rol, o por lo menos el que tiene sobre la mesa un contrato para lograrlo, es <strong>Jason Momoa<\/strong>, un hawaiiano de 1,93 metros desconocido para muchos pero un fijo en series como <a href=\"http:\/\/www.imdb.es\/title\/tt0374455\/\" target=\"_blank\">&quot;Stargate: Atlantis&quot;<\/a> (2005-2009), donde interpretaba a <strong>Ronon Dex<\/strong>. Parece ser que el golpe final de <strong>Momoa<\/strong> se produjo en los test de rodaje, en ese momento, y mientras bland&iacute;a una espada de dimensiones sobrehumanas, <strong>Nispel<\/strong> descubri&oacute; en el actor reminiscencias de <a href=\"http:\/\/www.imdb.es\/name\/nm0000216\/\" target=\"_blank\">Arnold Schwarzenegger<\/a>. El rodaje arrancar&aacute; el <strong>15 de marzo<\/strong> en diversos sets de <strong>Bulgaria<\/strong>. Como extra indicar que <a href=\"http:\/\/www.latinoreview.com\/news\/conan-has-been-cast-exclusive-extra-conan-s-father-could-be-a-wrestler-9032\" target=\"_blank\">LatinoReview.com asegura<\/a> que los productores le han propuesto a <a href=\"http:\/\/www.imdb.es\/name\/nm0000620\/\" target=\"_blank\">Mickey Rourke<\/a> participar en el film interpretando a <strong>Corin<\/strong>, el padre de <strong>Conan<\/strong>.<\/p>\n<p class=\"centrado\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2010\/20100122-jason-momoa-conan.jpg\" alt=\"Saludad a Conan, tambi&eacute;n conocido como Jason Momoa\" width=\"323\" height=\"500\" border=\"1\" \/><br \/>\n<em>Saludad a Conan, tambi&eacute;n conocido como Jason Momoa<\/em><\/p>\n<p>Sigamos ahora con otras noticias de este viernes. <a href=\"http:\/\/latimesblogs.latimes.com\/herocomplex\/2010\/01\/neil-gaiman-graveyard-book-movie.html\">Neil Gaiman ha estado charlando con Hero Complex<\/a> de <strong>Los Angeles Times<\/strong> y les ha confirmado que la adaptaci&oacute;n cinematogr&aacute;fica de <strong>&quot;The Graveyard Book&quot;<\/strong>, <a href=\"https:\/\/uruloki.org\/felipeblog\/cine-de-ciencia-ficcin\/bombazos-para-iron-man-2-y-the-avengers-christian-bale-como-el-doctor-strange-the-graveyard-book-de-neil-gaiman-al-cine-nuevas-imgenes-de-star-trek-y-drag-me-to-hell-y-a-ridley-sco\">anunciada en octubre del 2008<\/a>, est&aacute; ahora mismo muerta. Ojo, <strong>Gaiman<\/strong> avisa que su desarrollo en <strong>Miramax<\/strong> se ha estancado definitivamente pero que puede continuar en cualquier otro sitio. Fue <a href=\"https:\/\/uruloki.org\/felipeblog\/cine-de-ciencia-ficcin\/nuevos-psters-de-gi-joe-the-rise-of-cobra-piranha-3-d-se-retrasa-hasta-el-2010-nuevo-vdeo-de-street-fighter-the-legend-of-chun-li-novedades-de-dead-of-night-astro-boy-se-podra\">a finales de enero del a&ntilde;o pasado<\/a> cuando <strong>Gaiman<\/strong> anunci&oacute; que <a href=\"http:\/\/www.imdb.es\/name\/nm0001403\/\">Neil Jordan<\/a> hab&iacute;a sido el elegido para adaptar y dirigir <a href=\"http:\/\/www.imdb.es\/title\/tt1315950\/\">The Graveyard Book<\/a> (&iquest;?). La relaci&oacute;n de <strong>Jordan<\/strong> con la compa&ntilde;&iacute;a era perfecta pero el paso del tiempo llev&oacute; al proyecto a formar parte de ese cl&aacute;sico mont&oacute;n de papeles que amarillean en una estanter&iacute;a. Eso si, el escritor asegura que el cierre con <strong>Miramax<\/strong> ha sido lo mejor ya que ahora est&aacute;n cerca de cerrar con un nuevo estudio, un nuevo distribuidor y llevar de nuevo la adaptaci&oacute;n a donde debe ser&#8230; a las salas de cine.<\/p>\n<p class=\"centrado\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2010\/20100122-avatar-tierra-2.jpg\" alt=\"Imagen de las escenas eliminadas de Avatar\" width=\"498\" height=\"280\" border=\"1\" \/><br \/>\n<em>Imagen de las escenas eliminadas de Avatar<\/em><\/p>\n<p>Si <a href=\"https:\/\/uruloki.org\/felipeblog\/cine-de-ciencia-ficcin\/podra-david-tennant-irse-de-paseo-a-la-tierra-media-cambios-en-el-reparto-de-bruke-and-hare-cartel-de-tron-legacy-amc-da-luz-verde-a-la-serie-de-los-muertos-vivientes\">ayer se filtraba<\/a> sin querer que <a href=\"http:\/\/www.imdb.es\/name\/nm0855039\/\">David Tennant<\/a> se ca&iacute;a  de <a href=\"http:\/\/www.imdb.es\/title\/tt1320239\/\">Burke and Hare<\/a> (2010), esa pel&iacute;cula de <a href=\"http:\/\/www.imdb.es\/name\/nm0000484\/\">John Landis<\/a> que contar&aacute; la ver&iacute;dica historia de <strong>William Burke<\/strong> y <strong>William Hare<\/strong>, dos inmigrantes irlandeses que fueron acusados de asesinar a 17 personas en Edimburgo entre los a&ntilde;os 1827 y 1828, para luego vender los cad&aacute;veres frescos a la Facultad de Medicina y as&iacute; hacer estas sus pr&aacute;cticas, y que <a href=\"http:\/\/www.imdb.es\/name\/nm0785227\/\">Andy Serkis<\/a> se sub&iacute;a al carro en su lugar para acompa&ntilde;ar a <a href=\"http:\/\/www.imdb.es\/name\/nm0670408\/\">Simon Pegg<\/a>, <a href=\"http:\/\/www.heatvisionblog.com\/2010\/01\/isla-fisher-andy-serkis-tom-wilkinson-in-burke-and-hare-.html\">hoy Heat Vision a&ntilde;ade<\/a> a  <a href=\"http:\/\/www.imdb.es\/name\/nm0279545\/\">Isla Fisher<\/a> y <a href=\"http:\/\/www.imdb.es\/name\/nm0929489\/\">Tom Wilkinson<\/a>. La <strong>Fisher<\/strong> ser&aacute; la novia de <strong>Burke<\/strong> (<strong>Simon Pegg<\/strong>), mientras que <strong>Wilkinson<\/strong> interpretar&aacute; a uno de los profesores que trabajan en la facultad y compran cuerpos. Junto a ellos recordemos que tambi&eacute;n est&aacute;n <a href=\"http:\/\/www.imdb.es\/name\/nm0000092\/\">John Cleese<\/a>, <a href=\"http:\/\/www.imdb.es\/name\/nm0000101\/\">Dan Aykroyd<\/a> y <a href=\"http:\/\/www.imdb.es\/name\/nm0631490\/\">Bill Nighy<\/a>. El rodaje arranca el 31 de enero entre <strong>Edimburgo<\/strong> y <strong>Londres<\/strong>.<\/p>\n<p class=\"centrado\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2010\/20100122-avatar-tierra-1.jpg\" alt=\"Imagen de las escenas eliminadas de Avatar\" width=\"498\" height=\"333\" border=\"1\" \/><br \/>\n<em>Imagen de las escenas eliminadas de Avatar<\/em><\/p>\n<p>Decorando el post os dejo con dos im&aacute;genes de <a href=\"http:\/\/www.imdb.es\/title\/tt0499549\/\">Avatar<\/a> (2009) de <a href=\"http:\/\/www.imdb.es\/name\/nm0000116\/\">James Cameron<\/a>. &iquest;Dos im&aacute;genes m&aacute;s? os preguntar&eacute;is. Pues si, se tratan de dos im&aacute;genes de dos escenas que no hemos visto en los cines pero que si podremos ver en las ediciones de cine en casa. Se trata de dos secuencias que nos llevar&aacute;n a la <strong>Tierra<\/strong> antes de que <strong>Jake Sully<\/strong> (<a href=\"http:\/\/www.imdb.es\/name\/nm0941777\/\">Sam Worthington<\/a>) se embarque en la aventura que le lleva a <strong>Pandora<\/strong>. <a href=\"http:\/\/www.buf.fr\/visual_effects.php?display=text&amp;id=946\">Las im&aacute;genes salen de BUF<\/a>, un estudio de efectos especiales de <strong>Francia<\/strong> que ha trabajado en el film. <strong>BUF<\/strong> describe por encima las escenas pero por ah&iacute; se deja ver que el aspecto de la <strong>Tierra<\/strong> recordar&aacute; al mostrado en <a href=\"http:\/\/www.imdb.es\/title\/tt0083658\/\">Blade Runner<\/a> (1982)&#8230; anuncios luminosos por todas partes, trenes que se desplazan por el aire, etc.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Al fin es viernes. Despu&eacute;s de una semana de infarto en todos los aspectos, l&uacute;dicos y laborales, toca un fin de semana donde habr&aacute; que hacer, lo quiera o no, de todo un poco. Entre esta tareas hay que publicar cosillas en el blog. Comencemos con el bombazo de la jornada. A primera hora de [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,12,9],"tags":[405,1024,44,674],"class_list":["post-3591","post","type-post","status-publish","format-standard","hentry","category-cine-de-ciencia-ficcion","category-cine-de-fantasia","category-cine-de-terror","tag-avatar","tag-burke-and-hare","tag-conan","tag-the-graveyard-book"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jason Momoa ser&aacute; Conan de Cimmeria y &iquest;Mickey Rourke su padre Corin?, m&aacute;s incorporaciones interesantes para Burke and Hare, The Graveyard Book de Neil Gaiman muere y resucita, im&aacute;genes de secuencias en la Tierra de Avatar... - Uruloki :: Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jason Momoa ser&aacute; Conan de Cimmeria y &iquest;Mickey Rourke su padre Corin?, m&aacute;s incorporaciones interesantes para Burke and Hare, The Graveyard Book de Neil Gaiman muere y resucita, im&aacute;genes de secuencias en la Tierra de Avatar... - Uruloki :: Blog\" \/>\n<meta property=\"og:description\" content=\"Al fin es viernes. Despu&eacute;s de una semana de infarto en todos los aspectos, l&uacute;dicos y laborales, toca un fin de semana donde habr&aacute; que hacer, lo quiera o no, de todo un poco. Entre esta tareas hay que publicar cosillas en el blog. Comencemos con el bombazo de la jornada. A primera hora de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin\" \/>\n<meta property=\"og:site_name\" content=\"Uruloki :: Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uruloki.org\" \/>\n<meta property=\"article:published_time\" content=\"2010-01-22T18:27:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2010-01-22T19:40:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uruloki.org\/felipeblog\/images2010\/20100122-jason-momoa-conan.jpg\" \/>\n<meta name=\"author\" content=\"Uruloki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uruloki\" \/>\n<meta name=\"twitter:site\" content=\"@uruloki\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Uruloki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin\"},\"author\":{\"name\":\"Uruloki\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"headline\":\"Jason Momoa ser&aacute; Conan de Cimmeria y &iquest;Mickey Rourke su padre Corin?, m&aacute;s incorporaciones interesantes para Burke and Hare, The Graveyard Book de Neil Gaiman muere y resucita, im&aacute;genes de secuencias en la Tierra de Avatar&#8230;\",\"datePublished\":\"2010-01-22T18:27:06+00:00\",\"dateModified\":\"2010-01-22T19:40:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin\"},\"wordCount\":823,\"commentCount\":15,\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2010\\\/20100122-jason-momoa-conan.jpg\",\"keywords\":[\"Avatar\",\"Burke and Hare\",\"Conan\",\"The Graveyard Book\"],\"articleSection\":[\"Cine de Ciencia Ficci\u00f3n\",\"Cine de Fantas\u00eda\",\"Cine de Terror\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin\",\"name\":\"Jason Momoa ser&aacute; Conan de Cimmeria y &iquest;Mickey Rourke su padre Corin?, m&aacute;s incorporaciones interesantes para Burke and Hare, The Graveyard Book de Neil Gaiman muere y resucita, im&aacute;genes de secuencias en la Tierra de Avatar... - Uruloki :: Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2010\\\/20100122-jason-momoa-conan.jpg\",\"datePublished\":\"2010-01-22T18:27:06+00:00\",\"dateModified\":\"2010-01-22T19:40:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin#primaryimage\",\"url\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2010\\\/20100122-jason-momoa-conan.jpg\",\"contentUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2010\\\/20100122-jason-momoa-conan.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jason Momoa ser&aacute; Conan de Cimmeria y &iquest;Mickey Rourke su padre Corin?, m&aacute;s incorporaciones interesantes para Burke and Hare, The Graveyard Book de Neil Gaiman muere y resucita, im&aacute;genes de secuencias en la Tierra de Avatar&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/\",\"name\":\"Uruloki :: Blog\",\"description\":\"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\",\"name\":\"Uruloki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"caption\":\"Uruloki\"},\"sameAs\":[\"https:\\\/\\\/uruloki.org\"],\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/author\\\/admin-2-2-2\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jason Momoa ser&aacute; Conan de Cimmeria y &iquest;Mickey Rourke su padre Corin?, m&aacute;s incorporaciones interesantes para Burke and Hare, The Graveyard Book de Neil Gaiman muere y resucita, im&aacute;genes de secuencias en la Tierra de Avatar... - Uruloki :: Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin","og_locale":"es_ES","og_type":"article","og_title":"Jason Momoa ser&aacute; Conan de Cimmeria y &iquest;Mickey Rourke su padre Corin?, m&aacute;s incorporaciones interesantes para Burke and Hare, The Graveyard Book de Neil Gaiman muere y resucita, im&aacute;genes de secuencias en la Tierra de Avatar... - Uruloki :: Blog","og_description":"Al fin es viernes. Despu&eacute;s de una semana de infarto en todos los aspectos, l&uacute;dicos y laborales, toca un fin de semana donde habr&aacute; que hacer, lo quiera o no, de todo un poco. Entre esta tareas hay que publicar cosillas en el blog. Comencemos con el bombazo de la jornada. A primera hora de [&hellip;]","og_url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin","og_site_name":"Uruloki :: Blog","article_publisher":"https:\/\/www.facebook.com\/uruloki.org","article_published_time":"2010-01-22T18:27:06+00:00","article_modified_time":"2010-01-22T19:40:43+00:00","og_image":[{"url":"https:\/\/uruloki.org\/felipeblog\/images2010\/20100122-jason-momoa-conan.jpg","type":"","width":"","height":""}],"author":"Uruloki","twitter_card":"summary_large_image","twitter_creator":"@uruloki","twitter_site":"@uruloki","twitter_misc":{"Escrito por":"Uruloki","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin#article","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin"},"author":{"name":"Uruloki","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"headline":"Jason Momoa ser&aacute; Conan de Cimmeria y &iquest;Mickey Rourke su padre Corin?, m&aacute;s incorporaciones interesantes para Burke and Hare, The Graveyard Book de Neil Gaiman muere y resucita, im&aacute;genes de secuencias en la Tierra de Avatar&#8230;","datePublished":"2010-01-22T18:27:06+00:00","dateModified":"2010-01-22T19:40:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin"},"wordCount":823,"commentCount":15,"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/images2010\/20100122-jason-momoa-conan.jpg","keywords":["Avatar","Burke and Hare","Conan","The Graveyard Book"],"articleSection":["Cine de Ciencia Ficci\u00f3n","Cine de Fantas\u00eda","Cine de Terror"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin","url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin","name":"Jason Momoa ser&aacute; Conan de Cimmeria y &iquest;Mickey Rourke su padre Corin?, m&aacute;s incorporaciones interesantes para Burke and Hare, The Graveyard Book de Neil Gaiman muere y resucita, im&aacute;genes de secuencias en la Tierra de Avatar... - Uruloki :: Blog","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin#primaryimage"},"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/images2010\/20100122-jason-momoa-conan.jpg","datePublished":"2010-01-22T18:27:06+00:00","dateModified":"2010-01-22T19:40:43+00:00","author":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"breadcrumb":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin#primaryimage","url":"https:\/\/uruloki.org\/felipeblog\/images2010\/20100122-jason-momoa-conan.jpg","contentUrl":"https:\/\/uruloki.org\/felipeblog\/images2010\/20100122-jason-momoa-conan.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/jason-momoa-ser-conan-de-cimmeria-y-mickey-rourke-su-padre-corin#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uruloki.org\/felipeblog"},{"@type":"ListItem","position":2,"name":"Jason Momoa ser&aacute; Conan de Cimmeria y &iquest;Mickey Rourke su padre Corin?, m&aacute;s incorporaciones interesantes para Burke and Hare, The Graveyard Book de Neil Gaiman muere y resucita, im&aacute;genes de secuencias en la Tierra de Avatar&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.uruloki.org\/felipeblog\/#website","url":"https:\/\/www.uruloki.org\/felipeblog\/","name":"Uruloki :: Blog","description":"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uruloki.org\/felipeblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3","name":"Uruloki","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","caption":"Uruloki"},"sameAs":["https:\/\/uruloki.org"],"url":"https:\/\/www.uruloki.org\/felipeblog\/author\/admin-2-2-2"}]}},"_links":{"self":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/3591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/comments?post=3591"}],"version-history":[{"count":3,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/3591\/revisions"}],"predecessor-version":[{"id":3593,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/3591\/revisions\/3593"}],"wp:attachment":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/media?parent=3591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/categories?post=3591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/tags?post=3591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}