{"id":2917,"date":"2009-07-26T17:48:42","date_gmt":"2009-07-26T16:48:42","guid":{"rendered":"https:\/\/uruloki.org\/felipeblog\/?p=2917"},"modified":"2009-07-26T17:48:42","modified_gmt":"2009-07-26T16:48:42","slug":"comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin","status":"publish","type":"post","link":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin","title":{"rendered":"Comic-Con 2009: Los rostros de Avatar, Peter Jackson habla de las secuelas de Tint&iacute;n, Dark Horse y Universal adaptar&aacute;n dos mangas, ya hay guionista para adaptar &quot;La Fundaci&oacute;n&quot;, primer vistazo al logo de Sucker Punch y el estado de Gears of War&#8230;"},"content":{"rendered":"<p>Bueno, tras <a href=\"https:\/\/uruloki.org\/felipeblog\/cine-de-cmics\/comic-con-2009-marvel-studios-arrasa-con-iron-man-2-the-avengers-the-first-avenger-captain-america-war-machine-whiplash-black-widow-y-el-desmadre\">el panel de Marvel Studios y las fotos filtradas de Whiplash y War Machine<\/a>, se acerca poco a poco el final de la <strong>Comic-Con de San Diego<\/strong> y es momento de ir recopilando otras noticias que se han producido y que debido al incansable flujo de novedades no he podido recuperar antes. El post viene decorado con una curiosa imagen. Son los rostros de <a href=\"http:\/\/spanish.imdb.com\/title\/tt0499549\/\" target=\"_blank\">Avatar<\/a> (2009). &iquest;Los rostros? Pues si, resulta que el p&oacute;ster visto en la charla de <a href=\"http:\/\/spanish.imdb.com\/name\/nm0000116\/\" target=\"_blank\">James Cameron<\/a> no es el mismo que el expuesto en las calles de <strong>San Diego<\/strong>. Se trata de los rostros de una y un <strong>Na&#8217;vi<\/strong>. El segundo se parece bastante a <a href=\"http:\/\/spanish.imdb.com\/name\/nm0941777\/\" target=\"_blank\">Sam Worthington<\/a>, por eso la sorpresa del metraje visto donde se descubri&oacute; que los humanos se transformaban al montarse en las m&aacute;quinas <strong>Avatar<\/strong> en los habitantes del planeta <strong>Pandora<\/strong>. Os dejo con las im&aacute;genes para que pod&aacute;is comentar.<\/p>\n<p class=\"centrado\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/imagesflickr6\/20090726-SDCC2009-los-rostros-de-avatar.jpg\" alt=\"Avatar: ella y el\" width=\"498\" height=\"574\" border=\"1\" \/><br \/>\n<em>Avatar: ella y el<\/em><\/p>\n<p><a href=\"http:\/\/www.comingsoon.net\/news\/movienews.php?id=57501\" target=\"_blank\">Coming Soon ha charlado en exclusiva con Peter Jackson<\/a> tras el panel de <a href=\"http:\/\/spanish.imdb.com\/title\/tt1136608\/\" target=\"_blank\">District 9<\/a> (2009) de <a href=\"http:\/\/spanish.imdb.com\/name\/nm0088955\/\" target=\"_blank\">Neill Blomkamp<\/a> y ha dejado caer posibles intenciones futuras para las aventuras de <strong>Tint&iacute;n<\/strong>. Con <a href=\"http:\/\/spanish.imdb.com\/title\/tt0983193\/\" target=\"_blank\">Las aventuras de Tint&iacute;n: El secreto del Unicornio<\/a> (2011) en plena post-producci&oacute;n y con fecha de estreno decidida, <strong>Jackson<\/strong> habla del futuro y que vendr&aacute; despu&eacute;s. &quot;<em>Tengo varias favoritas,<\/em>&quot; dice <strong>Jackson<\/strong>, &quot;<em>me gusta &#8216;Las siete bolas de cristal&#8217; y  &#8216;El templo del Sol&#8217;. Tambi&eacute;n me encantan  &#8216;La isla negra&#8217; y &#8216;El asunto Tornasol&#8217;. Aunque la verdad es que todav&iacute;a no he tomado la decisi&oacute;n final<\/em>&quot;. Aunque confirma que no se decidir&aacute; hasta que termine las tareas de escritura de gui&oacute;n para la adaptaci&oacute;n de <strong>&quot;El Hobbit&quot;<\/strong>, <a href=\"http:\/\/spanish.imdb.com\/name\/nm0001392\/\" target=\"_blank\">Peter Jackson<\/a> muestra parte de sus cartas  e indica que tras la primera secuela tiene bastante claro que le gustar&iacute;a ver a <strong>Tint&iacute;n<\/strong> en la <strong>Luna<\/strong>. Se ve claramente que en cada pel&iacute;cula tienen en mente condensar los episodios doble&#8230; primero <strong>&quot;El tesoro de Rachman el Rojo&quot;<\/strong> y <strong>&quot;El Secreto del Unicornio&quot;<\/strong>, y para el tercero <strong>&quot;Objetivo la Luna&quot;<\/strong> y <strong>&quot;Aterrizaje en la Luna&quot;<\/strong>. &iquest;Y el segundo episodio? Pues podr&iacute;a ser <strong>&quot;Las siente bolas de cristal&quot;<\/strong> y <strong>&quot;El templo del Sol&quot;<\/strong>. &quot;<em>No habr&aacute; Luna en el segundo film, pero creo que ser&aacute; fabuloso poder ir a ella en le tercer o cuarto film<\/em>&quot;&#8230; &iquest;cuarto film de <strong>Tint&iacute;n<\/strong>? Ah&iacute; queda eso!<\/p>\n<p><a href=\"http:\/\/www.latinoreview.com\/news\/dark-horse-comics-announces-two-manga-adaptations-7509\" target=\"_blank\">Latino Review nos avisa<\/a> que <strong>Dark Horse Entertainment<\/strong> y <strong>Universal Studios<\/strong> han anunciado dos nueva adaptaciones al cine de productos publicados en USA por la primera. Se trata de dos mangas: <strong>The Kurosagi Corpse Delivery Service<\/strong> y <strong>MPD-Psycho<\/strong>. El primero  es un manga de corte policiaco d&oacute;nde se mezclan retazos de comedia, drama, acci&oacute;n, suspense y  terror psicol&oacute;gico. De <strong>MPD-Psycho<\/strong> ya tenemos <a href=\"http:\/\/spanish.imdb.com\/title\/tt0257885\/\" target=\"_blank\">una serie de televisi&oacute;n<\/a> dirigida hace unos a&ntilde;os por <a href=\"http:\/\/spanish.imdb.com\/name\/nm0586281\/\" target=\"_blank\">Takashi Miike<\/a>, aqu&iacute; <a href=\"http:\/\/www.youtube.com\/watch?v=PSn8A-oz4LM\" target=\"_blank\">el tremendamente extra&ntilde;o trailer<\/a>. <a href=\"http:\/\/www.comingsoon.net\/news\/movienews.php?id=57499\" target=\"_blank\">Coming Soon tambi&eacute;n anunci&oacute; en exclusiva<\/a> que la adaptaci&oacute;n de <strong>&quot;La Fundaci&oacute;n&quot;<\/strong> de <strong>Isaac Asimov<\/strong> preparada por <a href=\"http:\/\/spanish.imdb.com\/name\/nm0000386\/\" target=\"_blank\">Roland Emmerich<\/a> ya tiene guionista&#8230; <a href=\"http:\/\/spanish.imdb.com\/name\/nm0734441\/\" target=\"_blank\">Robert Rodat<\/a>, el responsable de cosas como <a href=\"http:\/\/spanish.imdb.com\/title\/tt0120815\/\" target=\"_blank\">Salvar al soldado Ryan<\/a> (1998) o <a href=\"http:\/\/spanish.imdb.com\/title\/tt0187393\/\" target=\"_blank\">El patriota<\/a> (2000). Desde ese a&ntilde;o no ha completado nada nuevo. <a href=\"http:\/\/www.deadlinehollywooddaily.com\/2009-comic-con-zachs-suckerpunch-art\/\" target=\"_blank\">En Nikki Finke&#8217;s Deadline Hollywood Daily<\/a> pod&eacute;is echar un vistazo a una de las camisetas que circulan por la <strong>Comic-Con de San Diego<\/strong>&#8230; la de <a href=\"http:\/\/spanish.imdb.com\/title\/tt0978764\/\" target=\"_blank\">Sucker Punch<\/a> (2011) de <a href=\"http:\/\/spanish.imdb.com\/name\/nm0811583\/\" target=\"_blank\">Zack Snyder<\/a>. <a href=\"http:\/\/movies.ign.com\/articles\/100\/1007578p1.html\" target=\"_blank\">IGN acudi&oacute; al panel de Gears of Wars<\/a> y pudo anotar los comentarios dados por <a href=\"http:\/\/spanish.imdb.com\/name\/nm0936482\/\" target=\"_blank\">Len Wiseman<\/a>, director, y <a href=\"http:\/\/spanish.imdb.com\/name\/nm0604555\/\" target=\"_blank\">Chris Morgan<\/a>, guionista, sobre la futura adaptaci&oacute;n cinematogr&aacute;fica del famoso juego. En primer lugar se apuraron a desmentir cualquier rumor de casting que haya aparecido por la red&#8230; todo falso. Luego <strong>Wiseman<\/strong> no dud&oacute; en reconocer que recomendar&iacute;a a su esposa <a href=\"http:\/\/spanish.imdb.com\/name\/nm0000295\/\" target=\"_blank\">Kate Beckinsale<\/a> interpretar a la esposa del segundo al mando <strong>Dominic Santiago<\/strong>. Para rematar <strong>Morgan<\/strong> avis&oacute; que el film adapta el juego, su mitolog&iacute;a, su trasfondo estar&aacute;n presentes, pero necesitan hacer una  versi&oacute;n cinematogr&aacute;fica y por eso no se adaptar&aacute; el videojuego tal cual. Lo que hace pensar que la cosa va para largo es que ni un p&oacute;ster, ni un detalle conceptual ni una fecha para <a href=\"http:\/\/spanish.imdb.com\/title\/tt0990406\/\" target=\"_blank\">Gears of War<\/a> (&iquest;?).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bueno, tras el panel de Marvel Studios y las fotos filtradas de Whiplash y War Machine, se acerca poco a poco el final de la Comic-Con de San Diego y es momento de ir recopilando otras noticias que se han producido y que debido al incansable flujo de novedades no he podido recuperar antes. El [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,8,944],"tags":[405,460,858,786],"class_list":["post-2917","post","type-post","status-publish","format-standard","hentry","category-cine-de-comics","category-cine-de-ciencia-ficcion","category-comic-con-2009","tag-avatar","tag-gears-of-war","tag-las-aventuras-de-tintin-el-secreto-del-unicornio","tag-sucker-punch"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comic-Con 2009: Los rostros de Avatar, Peter Jackson habla de las secuelas de Tint&iacute;n, Dark Horse y Universal adaptar&aacute;n dos mangas, ya hay guionista para adaptar &quot;La Fundaci&oacute;n&quot;, primer vistazo al logo de Sucker Punch y el estado de Gears of War... - Uruloki :: Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comic-Con 2009: Los rostros de Avatar, Peter Jackson habla de las secuelas de Tint&iacute;n, Dark Horse y Universal adaptar&aacute;n dos mangas, ya hay guionista para adaptar &quot;La Fundaci&oacute;n&quot;, primer vistazo al logo de Sucker Punch y el estado de Gears of War... - Uruloki :: Blog\" \/>\n<meta property=\"og:description\" content=\"Bueno, tras el panel de Marvel Studios y las fotos filtradas de Whiplash y War Machine, se acerca poco a poco el final de la Comic-Con de San Diego y es momento de ir recopilando otras noticias que se han producido y que debido al incansable flujo de novedades no he podido recuperar antes. El [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin\" \/>\n<meta property=\"og:site_name\" content=\"Uruloki :: Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uruloki.org\" \/>\n<meta property=\"article:published_time\" content=\"2009-07-26T16:48:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uruloki.org\/felipeblog\/imagesflickr6\/20090726-SDCC2009-los-rostros-de-avatar.jpg\" \/>\n<meta name=\"author\" content=\"Uruloki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uruloki\" \/>\n<meta name=\"twitter:site\" content=\"@uruloki\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Uruloki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin\"},\"author\":{\"name\":\"Uruloki\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"headline\":\"Comic-Con 2009: Los rostros de Avatar, Peter Jackson habla de las secuelas de Tint&iacute;n, Dark Horse y Universal adaptar&aacute;n dos mangas, ya hay guionista para adaptar &quot;La Fundaci&oacute;n&quot;, primer vistazo al logo de Sucker Punch y el estado de Gears of War&#8230;\",\"datePublished\":\"2009-07-26T16:48:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin\"},\"wordCount\":823,\"commentCount\":7,\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagesflickr6\\\/20090726-SDCC2009-los-rostros-de-avatar.jpg\",\"keywords\":[\"Avatar\",\"Gears of War\",\"Las Aventuras de Tint\u00edn: El Secreto del Unicornio\",\"Sucker Punch\"],\"articleSection\":[\"Cine de C\u00f3mics\",\"Cine de Ciencia Ficci\u00f3n\",\"Comic-Con 2009\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin\",\"name\":\"Comic-Con 2009: Los rostros de Avatar, Peter Jackson habla de las secuelas de Tint&iacute;n, Dark Horse y Universal adaptar&aacute;n dos mangas, ya hay guionista para adaptar &quot;La Fundaci&oacute;n&quot;, primer vistazo al logo de Sucker Punch y el estado de Gears of War... - Uruloki :: Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagesflickr6\\\/20090726-SDCC2009-los-rostros-de-avatar.jpg\",\"datePublished\":\"2009-07-26T16:48:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin#primaryimage\",\"url\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagesflickr6\\\/20090726-SDCC2009-los-rostros-de-avatar.jpg\",\"contentUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagesflickr6\\\/20090726-SDCC2009-los-rostros-de-avatar.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comic-Con 2009: Los rostros de Avatar, Peter Jackson habla de las secuelas de Tint&iacute;n, Dark Horse y Universal adaptar&aacute;n dos mangas, ya hay guionista para adaptar &quot;La Fundaci&oacute;n&quot;, primer vistazo al logo de Sucker Punch y el estado de Gears of War&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/\",\"name\":\"Uruloki :: Blog\",\"description\":\"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\",\"name\":\"Uruloki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"caption\":\"Uruloki\"},\"sameAs\":[\"https:\\\/\\\/uruloki.org\"],\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/author\\\/admin-2-2-2\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comic-Con 2009: Los rostros de Avatar, Peter Jackson habla de las secuelas de Tint&iacute;n, Dark Horse y Universal adaptar&aacute;n dos mangas, ya hay guionista para adaptar &quot;La Fundaci&oacute;n&quot;, primer vistazo al logo de Sucker Punch y el estado de Gears of War... - Uruloki :: Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin","og_locale":"es_ES","og_type":"article","og_title":"Comic-Con 2009: Los rostros de Avatar, Peter Jackson habla de las secuelas de Tint&iacute;n, Dark Horse y Universal adaptar&aacute;n dos mangas, ya hay guionista para adaptar &quot;La Fundaci&oacute;n&quot;, primer vistazo al logo de Sucker Punch y el estado de Gears of War... - Uruloki :: Blog","og_description":"Bueno, tras el panel de Marvel Studios y las fotos filtradas de Whiplash y War Machine, se acerca poco a poco el final de la Comic-Con de San Diego y es momento de ir recopilando otras noticias que se han producido y que debido al incansable flujo de novedades no he podido recuperar antes. El [&hellip;]","og_url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin","og_site_name":"Uruloki :: Blog","article_publisher":"https:\/\/www.facebook.com\/uruloki.org","article_published_time":"2009-07-26T16:48:42+00:00","og_image":[{"url":"https:\/\/uruloki.org\/felipeblog\/imagesflickr6\/20090726-SDCC2009-los-rostros-de-avatar.jpg","type":"","width":"","height":""}],"author":"Uruloki","twitter_card":"summary_large_image","twitter_creator":"@uruloki","twitter_site":"@uruloki","twitter_misc":{"Escrito por":"Uruloki","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin#article","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin"},"author":{"name":"Uruloki","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"headline":"Comic-Con 2009: Los rostros de Avatar, Peter Jackson habla de las secuelas de Tint&iacute;n, Dark Horse y Universal adaptar&aacute;n dos mangas, ya hay guionista para adaptar &quot;La Fundaci&oacute;n&quot;, primer vistazo al logo de Sucker Punch y el estado de Gears of War&#8230;","datePublished":"2009-07-26T16:48:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin"},"wordCount":823,"commentCount":7,"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/imagesflickr6\/20090726-SDCC2009-los-rostros-de-avatar.jpg","keywords":["Avatar","Gears of War","Las Aventuras de Tint\u00edn: El Secreto del Unicornio","Sucker Punch"],"articleSection":["Cine de C\u00f3mics","Cine de Ciencia Ficci\u00f3n","Comic-Con 2009"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin","url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin","name":"Comic-Con 2009: Los rostros de Avatar, Peter Jackson habla de las secuelas de Tint&iacute;n, Dark Horse y Universal adaptar&aacute;n dos mangas, ya hay guionista para adaptar &quot;La Fundaci&oacute;n&quot;, primer vistazo al logo de Sucker Punch y el estado de Gears of War... - Uruloki :: Blog","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin#primaryimage"},"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/imagesflickr6\/20090726-SDCC2009-los-rostros-de-avatar.jpg","datePublished":"2009-07-26T16:48:42+00:00","author":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"breadcrumb":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin#primaryimage","url":"https:\/\/uruloki.org\/felipeblog\/imagesflickr6\/20090726-SDCC2009-los-rostros-de-avatar.jpg","contentUrl":"https:\/\/uruloki.org\/felipeblog\/imagesflickr6\/20090726-SDCC2009-los-rostros-de-avatar.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/comic-con-2009-los-rostros-de-avatar-peter-jackson-habla-de-las-secuelas-de-tintn-dark-horse-y-universal-adaptarn-dos-mangas-ya-hay-guionista-para-adaptar-la-fundacin#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uruloki.org\/felipeblog"},{"@type":"ListItem","position":2,"name":"Comic-Con 2009: Los rostros de Avatar, Peter Jackson habla de las secuelas de Tint&iacute;n, Dark Horse y Universal adaptar&aacute;n dos mangas, ya hay guionista para adaptar &quot;La Fundaci&oacute;n&quot;, primer vistazo al logo de Sucker Punch y el estado de Gears of War&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.uruloki.org\/felipeblog\/#website","url":"https:\/\/www.uruloki.org\/felipeblog\/","name":"Uruloki :: Blog","description":"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uruloki.org\/felipeblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3","name":"Uruloki","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","caption":"Uruloki"},"sameAs":["https:\/\/uruloki.org"],"url":"https:\/\/www.uruloki.org\/felipeblog\/author\/admin-2-2-2"}]}},"_links":{"self":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/2917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/comments?post=2917"}],"version-history":[{"count":1,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/2917\/revisions"}],"predecessor-version":[{"id":2918,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/2917\/revisions\/2918"}],"wp:attachment":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/media?parent=2917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/categories?post=2917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/tags?post=2917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}