{"id":174,"date":"2004-07-28T20:28:17","date_gmt":"2004-07-29T04:28:17","guid":{"rendered":"https:\/\/uruloki.org\/felipeblog\/?p=174"},"modified":"2004-07-28T20:28:17","modified_gmt":"2004-07-29T04:28:17","slug":"como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria","status":"publish","type":"post","link":"https:\/\/www.uruloki.org\/felipeblog\/curiosidades\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria","title":{"rendered":"Como dec&iacute;a Andy Warhol, todos tenemos nuestros 15 minutos de gloria&#8230;"},"content":{"rendered":"<p>Y en mi caso son 15 d&iacute;as, que es el tiempo que me piro de vacaciones a tierras m&aacute;s c&aacute;lidas, menos h&uacute;medas y con playa y descanso, amen de buena vista&#8230; Andaluc&iacute;a, M&aacute;laga, Fuengirola.<\/p>\n<p>Despu&eacute;s de <strong>8 meses<\/strong> continuos de trabajo, ya llegan mis primeros 15 d&iacute;as y vienen que ni pintados. Estoy con ganas de pirarme y cortar un poco con el tema inform&aacute;tico, aunque creo que me llevar&eacute; el port&aacute;til por eso de ver alguna peliculilla, descargar las fotos de la c&aacute;mara digital y escuchar m&uacute;sica.<\/p>\n<p>Hoy encontr&eacute; en la red esta web que permitir&aacute; <a href=\"http:\/\/webexhibits.org\/colorart\/marilyns.html\" title=\"Seamos creativos\" target=\"_blank\">crear vuestros propios cuadros de Marilyn a lo Andy Warhol<\/a> y disfrutar del &eacute;xito pop que tuvo este autor americano.<\/p>\n<p><a href=\"https:\/\/uruloki.org\/felipeblog\/imagenes\/MarilyByUruloki.html\" onclick=\"window.open('https:\/\/uruloki.org\/felipeblog\/imagenes\/MarilyByUruloki.html','popup','width=474,height=471,scrollbars=no,resizable=no,toolbar=no,directories=no,location=no,menubar=no,status=no,left=0,top=0'); return false\" title=\"Ampliar Marily By Uruloki\"><img loading=\"lazy\" decoding=\"async\" alt=\"Marily By Uruloki\" src=\"https:\/\/uruloki.org\/felipeblog\/imagenes\/thmb_MarilyByUruloki.jpg\" width=\"200\" height=\"199\" border=\"1\" \/><\/a><\/p>\n<p>Las pr&oacute;ximas vacaciones en noviembre, no se que hacer, pero a lo mejor me planteo un viaje a la tierra del Croissant, Torre Eifel, Rococ&oacute;, Canap&eacute; y Caf&eacute; Ol&eacute;&#8230; a ver a parte de la familia.<\/p>\n<p>Chao.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Y en mi caso son 15 d&iacute;as, que es el tiempo que me piro de vacaciones a tierras m&aacute;s c&aacute;lidas, menos h&uacute;medas y con playa y descanso, amen de buena vista&#8230; Andaluc&iacute;a, M&aacute;laga, Fuengirola. Despu&eacute;s de 8 meses continuos de trabajo, ya llegan mis primeros 15 d&iacute;as y vienen que ni pintados. Estoy con ganas [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-174","post","type-post","status-publish","format-standard","hentry","category-curiosidades"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Como dec&iacute;a Andy Warhol, todos tenemos nuestros 15 minutos de gloria... - Uruloki :: Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uruloki.org\/felipeblog\/curiosidades\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Como dec&iacute;a Andy Warhol, todos tenemos nuestros 15 minutos de gloria... - Uruloki :: Blog\" \/>\n<meta property=\"og:description\" content=\"Y en mi caso son 15 d&iacute;as, que es el tiempo que me piro de vacaciones a tierras m&aacute;s c&aacute;lidas, menos h&uacute;medas y con playa y descanso, amen de buena vista&#8230; Andaluc&iacute;a, M&aacute;laga, Fuengirola. Despu&eacute;s de 8 meses continuos de trabajo, ya llegan mis primeros 15 d&iacute;as y vienen que ni pintados. Estoy con ganas [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uruloki.org\/felipeblog\/curiosidades\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria\" \/>\n<meta property=\"og:site_name\" content=\"Uruloki :: Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uruloki.org\" \/>\n<meta property=\"article:published_time\" content=\"2004-07-29T04:28:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uruloki.org\/felipeblog\/imagenes\/thmb_MarilyByUruloki.jpg\" \/>\n<meta name=\"author\" content=\"Uruloki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uruloki\" \/>\n<meta name=\"twitter:site\" content=\"@uruloki\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Uruloki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/curiosidades\\\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/curiosidades\\\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria\"},\"author\":{\"name\":\"Uruloki\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"headline\":\"Como dec&iacute;a Andy Warhol, todos tenemos nuestros 15 minutos de gloria&#8230;\",\"datePublished\":\"2004-07-29T04:28:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/curiosidades\\\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria\"},\"wordCount\":197,\"commentCount\":1,\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/curiosidades\\\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagenes\\\/thmb_MarilyByUruloki.jpg\",\"articleSection\":[\"Curiosidades\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/curiosidades\\\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/curiosidades\\\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/curiosidades\\\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria\",\"name\":\"Como dec&iacute;a Andy Warhol, todos tenemos nuestros 15 minutos de gloria... - Uruloki :: Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/curiosidades\\\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/curiosidades\\\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagenes\\\/thmb_MarilyByUruloki.jpg\",\"datePublished\":\"2004-07-29T04:28:17+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/curiosidades\\\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/curiosidades\\\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/curiosidades\\\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria#primaryimage\",\"url\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagenes\\\/thmb_MarilyByUruloki.jpg\",\"contentUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagenes\\\/thmb_MarilyByUruloki.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/curiosidades\\\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Como dec&iacute;a Andy Warhol, todos tenemos nuestros 15 minutos de gloria&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/\",\"name\":\"Uruloki :: Blog\",\"description\":\"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\",\"name\":\"Uruloki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"caption\":\"Uruloki\"},\"sameAs\":[\"https:\\\/\\\/uruloki.org\"],\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/author\\\/admin-2-2-2\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Como dec&iacute;a Andy Warhol, todos tenemos nuestros 15 minutos de gloria... - Uruloki :: Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uruloki.org\/felipeblog\/curiosidades\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria","og_locale":"es_ES","og_type":"article","og_title":"Como dec&iacute;a Andy Warhol, todos tenemos nuestros 15 minutos de gloria... - Uruloki :: Blog","og_description":"Y en mi caso son 15 d&iacute;as, que es el tiempo que me piro de vacaciones a tierras m&aacute;s c&aacute;lidas, menos h&uacute;medas y con playa y descanso, amen de buena vista&#8230; Andaluc&iacute;a, M&aacute;laga, Fuengirola. Despu&eacute;s de 8 meses continuos de trabajo, ya llegan mis primeros 15 d&iacute;as y vienen que ni pintados. Estoy con ganas [&hellip;]","og_url":"https:\/\/www.uruloki.org\/felipeblog\/curiosidades\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria","og_site_name":"Uruloki :: Blog","article_publisher":"https:\/\/www.facebook.com\/uruloki.org","article_published_time":"2004-07-29T04:28:17+00:00","og_image":[{"url":"https:\/\/uruloki.org\/felipeblog\/imagenes\/thmb_MarilyByUruloki.jpg","type":"","width":"","height":""}],"author":"Uruloki","twitter_card":"summary_large_image","twitter_creator":"@uruloki","twitter_site":"@uruloki","twitter_misc":{"Escrito por":"Uruloki","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uruloki.org\/felipeblog\/curiosidades\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria#article","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/curiosidades\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria"},"author":{"name":"Uruloki","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"headline":"Como dec&iacute;a Andy Warhol, todos tenemos nuestros 15 minutos de gloria&#8230;","datePublished":"2004-07-29T04:28:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/curiosidades\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria"},"wordCount":197,"commentCount":1,"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/curiosidades\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/imagenes\/thmb_MarilyByUruloki.jpg","articleSection":["Curiosidades"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uruloki.org\/felipeblog\/curiosidades\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uruloki.org\/felipeblog\/curiosidades\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria","url":"https:\/\/www.uruloki.org\/felipeblog\/curiosidades\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria","name":"Como dec&iacute;a Andy Warhol, todos tenemos nuestros 15 minutos de gloria... - Uruloki :: Blog","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/curiosidades\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria#primaryimage"},"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/curiosidades\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/imagenes\/thmb_MarilyByUruloki.jpg","datePublished":"2004-07-29T04:28:17+00:00","author":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"breadcrumb":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/curiosidades\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uruloki.org\/felipeblog\/curiosidades\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uruloki.org\/felipeblog\/curiosidades\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria#primaryimage","url":"https:\/\/uruloki.org\/felipeblog\/imagenes\/thmb_MarilyByUruloki.jpg","contentUrl":"https:\/\/uruloki.org\/felipeblog\/imagenes\/thmb_MarilyByUruloki.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uruloki.org\/felipeblog\/curiosidades\/como-deca-andy-warhol-todos-tenemos-nuestros-15-minutos-de-gloria#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uruloki.org\/felipeblog"},{"@type":"ListItem","position":2,"name":"Como dec&iacute;a Andy Warhol, todos tenemos nuestros 15 minutos de gloria&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.uruloki.org\/felipeblog\/#website","url":"https:\/\/www.uruloki.org\/felipeblog\/","name":"Uruloki :: Blog","description":"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uruloki.org\/felipeblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3","name":"Uruloki","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","caption":"Uruloki"},"sameAs":["https:\/\/uruloki.org"],"url":"https:\/\/www.uruloki.org\/felipeblog\/author\/admin-2-2-2"}]}},"_links":{"self":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/174","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/comments?post=174"}],"version-history":[{"count":0,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/174\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/media?parent=174"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/categories?post=174"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/tags?post=174"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}