{"id":16854,"date":"2017-06-28T22:55:02","date_gmt":"2017-06-28T20:55:02","guid":{"rendered":"https:\/\/uruloki.org\/felipeblog\/?p=16854"},"modified":"2017-06-28T22:55:02","modified_gmt":"2017-06-28T20:55:02","slug":"deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los","status":"publish","type":"post","link":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los","title":{"rendered":"Deadpool 2 incorpora al hilarante Julian Dennison en sabe dios qu\u00e9 papel, Matt Reeves habla del tono noir-detectivesco que tendr\u00e1 su The Batman, Michael Beach se suma a Aquaman como un \u00abpirata\u00bb de los de parche en el ojo, Kevin Feige deja caer que Blade volver\u00e1 pero en un futuro tan incierto como el final de las fases que ahora labra el CEO de Marvel Studios, y mucho ojo al extra\u00f1o y flipante corto \u00abFirebase\u00bb de Oats Studios&#8230;"},"content":{"rendered":"<p>Venga, entrada rapitida que hoy el d&iacute;a se me est&aacute; quedando corto. Por lo pronto tenemos nueva incorporaci&oacute;n graciosa en <strong>Deadpool 2<\/strong> (2018) de <strong>David Leitch<\/strong>. <strong>Julian Dennison<\/strong>, el simp&aacute;tico e hilarante chaval de <strong>Hunt for the Wilderpeople<\/strong> de <strong>Taika Waititi<\/strong>, es el &uacute;ltimo en sumarse al proyecto comiquero. La mejor forma de presentarlo ha sido a lomos de <em>Deadpool<\/em> (<strong>Ryan Reynolds<\/strong>). La duda ahora es saber el papel que le tocar&aacute; al joven actor, por lo general rechonchete, y ya un grande de la comedia entre arbustos. &iquest;Mutante?, &iquest;Alivio c&oacute;mico a lo <strong>T. J. Miller<\/strong>? Sea lo que se deber&iacute;a valer.<\/p>\n<div class=\"twittercentrado\">\n<blockquote class=\"twitter-tweet\" data-lang=\"es\">\n<p lang=\"en\" dir=\"ltr\">Never in my wilderpeoplest dreams would I have imagined this picture existing. But&#8230;. Yessss. <a href=\"https:\/\/twitter.com\/JulianDennison\" target=\"_blank\">@JulianDennison<\/a> <a href=\"https:\/\/twitter.com\/VancityReynolds\" target=\"_blank\">@VancityReynolds<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/SkuxLife?src=hash\" target=\"_blank\">#SkuxLife<\/a> <a href=\"https:\/\/t.co\/7KUifBrdxg\" target=\"_blank\">pic.twitter.com\/7KUifBrdxg<\/a><\/p>\n<p>&mdash; Taika Waititi (@TaikaWaititi) <a href=\"https:\/\/twitter.com\/TaikaWaititi\/status\/879957239653580800\" target=\"_blank\">28 de junio de 2017<\/a><\/p><\/blockquote>\n<p><script async src=\"\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/div>\n<p>Por otro lado tenemos a <a href=\"http:\/\/www.comingsoon.net\/movies\/news\/862949-matt-reeves-talks-his-noir-driven-detective-version-of-batman?utm_source=rss&amp;utm_medium=rss&amp;utm_campaign=matt-reeves-talks-his-noir-driven-detective-version-of-batman#\/slide\/1\" target=\"_blank\"><strong>Matt Reeves<\/strong> hablando de <strong>The Batman<\/strong> (2019) y sobre el estilo de pel&iacute;cula que nos espera<\/a>. Cuenta <strong>Reeves<\/strong> que siempre ha sentido por <em>Batman<\/em> lo mismo que sent&iacute;a por <em>Caesar<\/em> y que fue lo que le llev&oacute; a esforzarse por la renovada saga del <em>Planeta de los Simios<\/em>. <em>Batman<\/em> y <em>Caesar<\/em> son, en palabras de <strong>Reeves<\/strong>, seres atormentados que buscan hacer lo correcto en un mundo imperfecto y corrupto. Esa es la emotividad que le mueve. Esto le lleva adem&aacute;s a hacer sus pel&iacute;culas de alguna forma en sentido <em>hitchcockianas<\/em>, usando la c&aacute;mara y la narraci&oacute;n de forma que el espectador sea un personaje m&aacute;s. Por lo tanto, ve en <strong>The Batman<\/strong> una buena forma de contar una historia a lo cine negro, una versi&oacute;n m&aacute;s detectivesca que acabar&aacute; llevando al espectador a colarse en la mente del personaje y en su sentimientos. Interesante enfoque. Y hablando del mundo DC, <a href=\"http:\/\/variety.com\/2017\/film\/news\/michael-beach-jason-momoa-aquaman-1202476335\/\" target=\"_blank\"><strong>Michael Beach<\/strong> se une a <strong>Jason Momoa<\/strong> en <strong>Aquaman<\/strong> (2018) de <strong>James Wan<\/strong><\/a>. <strong>Beach<\/strong> ser&aacute; <em>Jesse Kane<\/em>,  miembro de un grupo de secuestradores en alta mar que tendr&aacute; un no muy agradable encuentro con <em>Aquaman<\/em>. &iquest;Papel de relleno o villano de medio pelo? Todo es posible.<\/p>\n<p>Y hablando de cine de c&oacute;mics, Joblo habla con <strong>Kevin Feige<\/strong> y este dice que <a href=\"http:\/\/www.joblo.com\/horror-movies\/news\/exclusive-marvel-s-kevin-feige-says-blade-will-return-someday-323\" target=\"_blank\"><strong>Blade<\/strong> puede que vuelva alg&uacute;n d&iacute;a al cine de la mano de <strong>Marvel Studios<\/strong><\/a>, pero que desde luego no est&aacute;n trabajando ahora en este plan&#8230; por lo tanto: nada nuevo en el horizonte. Eso s&iacute;, reconoce que es un personaje potente, que funcion&oacute; muy bien en su momento (aunque muchos espectadores no sab&iacute;an que era factor&iacute;a <strong>Marvel<\/strong>), y que si bien la clasificaci&oacute;n R no es algo que se contemple ahora mismo en el estudio, es algo que est&aacute; sobre la mesa como posible tema a tratar en un momento incierto. Os dejo ahora con el segundo corto de <strong>Oats Studios<\/strong>&#8230; <strong>&quot;Firebase&quot;<\/strong> se titula. Alucinante. Durante la Guerra de Vietnam un soldado de los USA acaba atrapado en una red de ciencia ficci&oacute;n y locura. La f&aacute;brica del espacio tiempo comienza, literalmente, a doblarse a su alrededor.<\/p>\n<div class=\"video\"><iframe loading=\"lazy\" width=\"100%\" height=\"360\" src=\"https:\/\/www.youtube.com\/embed\/Tm0V24IEHao\" allowfullscreen=\"true\"><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Venga, entrada rapitida que hoy el d&iacute;a se me est&aacute; quedando corto. Por lo pronto tenemos nueva incorporaci&oacute;n graciosa en Deadpool 2 (2018) de David Leitch. Julian Dennison, el simp&aacute;tico e hilarante chaval de Hunt for the Wilderpeople de Taika Waititi, es el &uacute;ltimo en sumarse al proyecto comiquero. La mejor forma de presentarlo ha [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[967,2533,3601,3788,3775,3049],"class_list":["post-16854","post","type-post","status-publish","format-standard","hentry","category-cine-de-comics","tag-aquaman","tag-blade","tag-deadpool-2","tag-firebase","tag-oats-studios","tag-the-batman"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Deadpool 2 incorpora al hilarante Julian Dennison en sabe dios qu\u00e9 papel<\/title>\n<meta name=\"description\" content=\"Tenemos nueva incorporaci\u00f3n graciosa en Deadpool 2 de David Leitch. Julian Dennison, el simp\u00e1tico e hilarante chaval de Hunt for the Wilderpeople, llega.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deadpool 2 incorpora al hilarante Julian Dennison en sabe dios qu\u00e9 papel\" \/>\n<meta property=\"og:description\" content=\"Tenemos nueva incorporaci\u00f3n graciosa en Deadpool 2 de David Leitch. Julian Dennison, el simp\u00e1tico e hilarante chaval de Hunt for the Wilderpeople, llega.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los\" \/>\n<meta property=\"og:site_name\" content=\"Uruloki :: Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uruloki.org\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-28T20:55:02+00:00\" \/>\n<meta name=\"author\" content=\"Uruloki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uruloki\" \/>\n<meta name=\"twitter:site\" content=\"@uruloki\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Uruloki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los\"},\"author\":{\"name\":\"Uruloki\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"headline\":\"Deadpool 2 incorpora al hilarante Julian Dennison en sabe dios qu\u00e9 papel, Matt Reeves habla del tono noir-detectivesco que tendr\u00e1 su The Batman, Michael Beach se suma a Aquaman como un \u00abpirata\u00bb de los de parche en el ojo, Kevin Feige deja caer que Blade volver\u00e1 pero en un futuro tan incierto como el final de las fases que ahora labra el CEO de Marvel Studios, y mucho ojo al extra\u00f1o y flipante corto \u00abFirebase\u00bb de Oats Studios&#8230;\",\"datePublished\":\"2017-06-28T20:55:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los\"},\"wordCount\":618,\"commentCount\":0,\"keywords\":[\"Aquaman\",\"Blade\",\"Deadpool 2\",\"Firebase\",\"Oats Studios\",\"The Batman\"],\"articleSection\":[\"Cine de C\u00f3mics\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los\",\"name\":\"Deadpool 2 incorpora al hilarante Julian Dennison en sabe dios qu\u00e9 papel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\"},\"datePublished\":\"2017-06-28T20:55:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"description\":\"Tenemos nueva incorporaci\u00f3n graciosa en Deadpool 2 de David Leitch. Julian Dennison, el simp\u00e1tico e hilarante chaval de Hunt for the Wilderpeople, llega.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deadpool 2 incorpora al hilarante Julian Dennison en sabe dios qu\u00e9 papel, Matt Reeves habla del tono noir-detectivesco que tendr\u00e1 su The Batman, Michael Beach se suma a Aquaman como un \u00abpirata\u00bb de los de parche en el ojo, Kevin Feige deja caer que Blade volver\u00e1 pero en un futuro tan incierto como el final de las fases que ahora labra el CEO de Marvel Studios, y mucho ojo al extra\u00f1o y flipante corto \u00abFirebase\u00bb de Oats Studios&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/\",\"name\":\"Uruloki :: Blog\",\"description\":\"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\",\"name\":\"Uruloki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"caption\":\"Uruloki\"},\"sameAs\":[\"https:\\\/\\\/uruloki.org\"],\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/author\\\/admin-2-2-2\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Deadpool 2 incorpora al hilarante Julian Dennison en sabe dios qu\u00e9 papel","description":"Tenemos nueva incorporaci\u00f3n graciosa en Deadpool 2 de David Leitch. Julian Dennison, el simp\u00e1tico e hilarante chaval de Hunt for the Wilderpeople, llega.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los","og_locale":"es_ES","og_type":"article","og_title":"Deadpool 2 incorpora al hilarante Julian Dennison en sabe dios qu\u00e9 papel","og_description":"Tenemos nueva incorporaci\u00f3n graciosa en Deadpool 2 de David Leitch. Julian Dennison, el simp\u00e1tico e hilarante chaval de Hunt for the Wilderpeople, llega.","og_url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los","og_site_name":"Uruloki :: Blog","article_publisher":"https:\/\/www.facebook.com\/uruloki.org","article_published_time":"2017-06-28T20:55:02+00:00","author":"Uruloki","twitter_card":"summary_large_image","twitter_creator":"@uruloki","twitter_site":"@uruloki","twitter_misc":{"Escrito por":"Uruloki","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los#article","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los"},"author":{"name":"Uruloki","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"headline":"Deadpool 2 incorpora al hilarante Julian Dennison en sabe dios qu\u00e9 papel, Matt Reeves habla del tono noir-detectivesco que tendr\u00e1 su The Batman, Michael Beach se suma a Aquaman como un \u00abpirata\u00bb de los de parche en el ojo, Kevin Feige deja caer que Blade volver\u00e1 pero en un futuro tan incierto como el final de las fases que ahora labra el CEO de Marvel Studios, y mucho ojo al extra\u00f1o y flipante corto \u00abFirebase\u00bb de Oats Studios&#8230;","datePublished":"2017-06-28T20:55:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los"},"wordCount":618,"commentCount":0,"keywords":["Aquaman","Blade","Deadpool 2","Firebase","Oats Studios","The Batman"],"articleSection":["Cine de C\u00f3mics"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los","url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los","name":"Deadpool 2 incorpora al hilarante Julian Dennison en sabe dios qu\u00e9 papel","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#website"},"datePublished":"2017-06-28T20:55:02+00:00","author":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"description":"Tenemos nueva incorporaci\u00f3n graciosa en Deadpool 2 de David Leitch. Julian Dennison, el simp\u00e1tico e hilarante chaval de Hunt for the Wilderpeople, llega.","breadcrumb":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/deadpool-2-incorpora-al-hilarante-julian-dennison-sabe-dios-papel-matt-reeves-habla-del-tono-noir-detectivesco-tendra-the-batman-michael-beach-se-suma-aquaman-pirata-los#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uruloki.org\/felipeblog"},{"@type":"ListItem","position":2,"name":"Deadpool 2 incorpora al hilarante Julian Dennison en sabe dios qu\u00e9 papel, Matt Reeves habla del tono noir-detectivesco que tendr\u00e1 su The Batman, Michael Beach se suma a Aquaman como un \u00abpirata\u00bb de los de parche en el ojo, Kevin Feige deja caer que Blade volver\u00e1 pero en un futuro tan incierto como el final de las fases que ahora labra el CEO de Marvel Studios, y mucho ojo al extra\u00f1o y flipante corto \u00abFirebase\u00bb de Oats Studios&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.uruloki.org\/felipeblog\/#website","url":"https:\/\/www.uruloki.org\/felipeblog\/","name":"Uruloki :: Blog","description":"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uruloki.org\/felipeblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3","name":"Uruloki","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","caption":"Uruloki"},"sameAs":["https:\/\/uruloki.org"],"url":"https:\/\/www.uruloki.org\/felipeblog\/author\/admin-2-2-2"}]}},"_links":{"self":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/16854","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/comments?post=16854"}],"version-history":[{"count":1,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/16854\/revisions"}],"predecessor-version":[{"id":16855,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/16854\/revisions\/16855"}],"wp:attachment":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/media?parent=16854"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/categories?post=16854"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/tags?post=16854"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}