{"id":15703,"date":"2016-06-24T12:32:08","date_gmt":"2016-06-24T10:32:08","guid":{"rendered":"https:\/\/uruloki.org\/felipeblog\/?p=15703"},"modified":"2016-06-24T12:47:59","modified_gmt":"2016-06-24T10:47:59","slug":"mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia","status":"publish","type":"post","link":"https:\/\/www.uruloki.org\/felipeblog\/star-wars\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia","title":{"rendered":"M\u00e1s material la mar de interesante de Rogue One: Una Historia de Star Wars, fotos, James Earl Jones y m\u00e1s historia&#8230;"},"content":{"rendered":"<p>Vamos con un nuevo desembarco, <a href=\"https:\/\/uruloki.org\/felipeblog\/star-wars\/desembarco-rogue-one-una-historia-star-wars-todos-los-personajes-protagonistas-ya-sabemos-quien-forest-witaker-darth-vader-regresa-forma-oficial\">segundo en poco m&aacute;s de 24 horas, de <strong>Rogue One: Una Historia de Star Wars<\/strong> (<em>Rogue One: A Star Wars Story<\/em>, 2016)<\/a>. EW sigue publicando <a href=\"http:\/\/www.ew.com\/gallery\/rogue-one-first-look-photos\/\" target=\"_blank\">material para su especial de la nueva pel&iacute;cula de la grandiosa saga de <strong>La Guerra de las Galaxias<\/strong><\/a>. En esta ocasi&oacute;n vemos nuevas im&aacute;genes del film de <strong>Gareth Edwards<\/strong>, nueve, y una de un momento del rodaje donde el director habla con la parte Rebelde del film. Poco m&aacute;s se puede decir con respecto a lo adelantado de ayer, el art&iacute;culo de EW trae una breve charla con el director y la productora y presidenta de <strong>Lucasfilm Kathleen Kennedy<\/strong>. <\/p>\n<p>La primera imagen de todas es importante, en ella vemos a la nueva unidad de <strong>Stormtroopers<\/strong> hasta ahora no conocida, los <strong>Deathtroopers<\/strong>, encargados de destruir lo que queda de la rebeli&oacute;n al precio que sea. Luego comentarios sobre <strong>Jyn Erso<\/strong> (<em>Felicity Jones<\/em>), una especie de Juana de Arco seg&uacute;n la <strong>Kennedy<\/strong>, el <strong>Director Orson Krennic<\/strong> (<em>Ben Mendelshon<\/em>), el encargado de vigilar la seguridad de la <strong>Estrella de la Muerte<\/strong> y un redomado manipulador&#8230; hasta el Imperio deber&iacute;a tener cuidado con &eacute;l y con lo que puede llegar a hacer por lo que cuentan. Nada que ver con el enfoque fiel y servidor del <strong>Grand Moff Tarkin<\/strong> (<em>Peter Cushing<\/em>), <strong>Krennic<\/strong> apunta a peligroso, impredecible y vol&aacute;til. Ah, y <strong>James Earl Jones<\/strong> regresa en la versi\u00f3n original como la voz de <strong>Darth Vader<\/strong>, una grand\u00edsima pena que <strong>Constantino Romero<\/strong> no pueda hacer lo mismo&#8230; :_(<\/p>\n<p class=\"centrado\"><img decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2016\/20160624-rogueone-1.jpg\" alt=\"Nueva imagen de Rogue One: Una Historia de Star Wars\" \/><\/p>\n<p class=\"centrado\"><img decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2016\/20160624-rogueone-2.jpg\" alt=\"Nueva imagen de Rogue One: Una Historia de Star Wars\" \/><\/p>\n<p class=\"centrado\"><img decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2016\/20160624-rogueone-3.jpg\" alt=\"Nueva imagen de Rogue One: Una Historia de Star Wars\" \/><\/p>\n<p class=\"centrado\"><img decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2016\/20160624-rogueone-4.jpg\" alt=\"Nueva imagen de Rogue One: Una Historia de Star Wars\" \/><\/p>\n<p class=\"centrado\"><img decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2016\/20160624-rogueone-5.jpg\" alt=\"Nueva imagen de Rogue One: Una Historia de Star Wars\" \/><\/p>\n<p class=\"centrado\"><img decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2016\/20160624-rogueone-6.jpg\" alt=\"Nueva imagen de Rogue One: Una Historia de Star Wars\" \/><\/p>\n<p class=\"centrado\"><img decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2016\/20160624-rogueone-7.jpg\" alt=\"Nueva imagen de Rogue One: Una Historia de Star Wars\" \/><\/p>\n<p class=\"centrado\"><img decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2016\/20160624-rogueone-9.jpg\" alt=\"Nueva imagen de Rogue One: Una Historia de Star Wars\" \/><\/p>\n<p class=\"centrado\"><img decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2016\/20160624-rogueone-10.jpg\" alt=\"Nueva imagen de Rogue One: Una Historia de Star Wars\" \/><\/p>\n<p class=\"centrado\"><img decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2016\/20160624-rogueone-8.jpg\" alt=\"Nueva imagen de Rogue One: Una Historia de Star Wars\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vamos con un nuevo desembarco, segundo en poco m&aacute;s de 24 horas, de Rogue One: Una Historia de Star Wars (Rogue One: A Star Wars Story, 2016). EW sigue publicando material para su especial de la nueva pel&iacute;cula de la grandiosa saga de La Guerra de las Galaxias. En esta ocasi&oacute;n vemos nuevas im&aacute;genes del [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,15],"tags":[3463],"class_list":["post-15703","post","type-post","status-publish","format-standard","hentry","category-cine-de-ciencia-ficcion","category-star-wars","tag-rogue-one-a-star-wars-story"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s material interesante de Rogue One: Una Historia de Star Wars<\/title>\n<meta name=\"description\" content=\"Vamos con un nuevo desembarco, segundo en poco m\u00e1s de 24 horas, de Rogue One: Una Historia de Star Wars (Rogue One: A Star Wars Story, 2016). Esto no para!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uruloki.org\/felipeblog\/star-wars\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s material interesante de Rogue One: Una Historia de Star Wars\" \/>\n<meta property=\"og:description\" content=\"Vamos con un nuevo desembarco, segundo en poco m\u00e1s de 24 horas, de Rogue One: Una Historia de Star Wars (Rogue One: A Star Wars Story, 2016). Esto no para!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uruloki.org\/felipeblog\/star-wars\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia\" \/>\n<meta property=\"og:site_name\" content=\"Uruloki :: Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uruloki.org\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-24T10:32:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-06-24T10:47:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uruloki.org\/felipeblog\/images2016\/20160624-rogueone-1.jpg\" \/>\n<meta name=\"author\" content=\"Uruloki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uruloki\" \/>\n<meta name=\"twitter:site\" content=\"@uruloki\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Uruloki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/star-wars\\\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/star-wars\\\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia\"},\"author\":{\"name\":\"Uruloki\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"headline\":\"M\u00e1s material la mar de interesante de Rogue One: Una Historia de Star Wars, fotos, James Earl Jones y m\u00e1s historia&#8230;\",\"datePublished\":\"2016-06-24T10:32:08+00:00\",\"dateModified\":\"2016-06-24T10:47:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/star-wars\\\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia\"},\"wordCount\":295,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/star-wars\\\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2016\\\/20160624-rogueone-1.jpg\",\"keywords\":[\"Rogue One: A Star Wars Story\"],\"articleSection\":[\"Cine de Ciencia Ficci\u00f3n\",\"Star Wars\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/star-wars\\\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/star-wars\\\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/star-wars\\\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia\",\"name\":\"M\u00e1s material interesante de Rogue One: Una Historia de Star Wars\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/star-wars\\\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/star-wars\\\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2016\\\/20160624-rogueone-1.jpg\",\"datePublished\":\"2016-06-24T10:32:08+00:00\",\"dateModified\":\"2016-06-24T10:47:59+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"description\":\"Vamos con un nuevo desembarco, segundo en poco m\u00e1s de 24 horas, de Rogue One: Una Historia de Star Wars (Rogue One: A Star Wars Story, 2016). Esto no para!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/star-wars\\\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/star-wars\\\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/star-wars\\\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia#primaryimage\",\"url\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2016\\\/20160624-rogueone-1.jpg\",\"contentUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2016\\\/20160624-rogueone-1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/star-wars\\\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s material la mar de interesante de Rogue One: Una Historia de Star Wars, fotos, James Earl Jones y m\u00e1s historia&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/\",\"name\":\"Uruloki :: Blog\",\"description\":\"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\",\"name\":\"Uruloki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"caption\":\"Uruloki\"},\"sameAs\":[\"https:\\\/\\\/uruloki.org\"],\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/author\\\/admin-2-2-2\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s material interesante de Rogue One: Una Historia de Star Wars","description":"Vamos con un nuevo desembarco, segundo en poco m\u00e1s de 24 horas, de Rogue One: Una Historia de Star Wars (Rogue One: A Star Wars Story, 2016). Esto no para!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uruloki.org\/felipeblog\/star-wars\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia","og_locale":"es_ES","og_type":"article","og_title":"M\u00e1s material interesante de Rogue One: Una Historia de Star Wars","og_description":"Vamos con un nuevo desembarco, segundo en poco m\u00e1s de 24 horas, de Rogue One: Una Historia de Star Wars (Rogue One: A Star Wars Story, 2016). Esto no para!","og_url":"https:\/\/www.uruloki.org\/felipeblog\/star-wars\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia","og_site_name":"Uruloki :: Blog","article_publisher":"https:\/\/www.facebook.com\/uruloki.org","article_published_time":"2016-06-24T10:32:08+00:00","article_modified_time":"2016-06-24T10:47:59+00:00","og_image":[{"url":"https:\/\/uruloki.org\/felipeblog\/images2016\/20160624-rogueone-1.jpg","type":"","width":"","height":""}],"author":"Uruloki","twitter_card":"summary_large_image","twitter_creator":"@uruloki","twitter_site":"@uruloki","twitter_misc":{"Escrito por":"Uruloki","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uruloki.org\/felipeblog\/star-wars\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia#article","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/star-wars\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia"},"author":{"name":"Uruloki","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"headline":"M\u00e1s material la mar de interesante de Rogue One: Una Historia de Star Wars, fotos, James Earl Jones y m\u00e1s historia&#8230;","datePublished":"2016-06-24T10:32:08+00:00","dateModified":"2016-06-24T10:47:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/star-wars\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia"},"wordCount":295,"commentCount":2,"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/star-wars\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/images2016\/20160624-rogueone-1.jpg","keywords":["Rogue One: A Star Wars Story"],"articleSection":["Cine de Ciencia Ficci\u00f3n","Star Wars"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uruloki.org\/felipeblog\/star-wars\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uruloki.org\/felipeblog\/star-wars\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia","url":"https:\/\/www.uruloki.org\/felipeblog\/star-wars\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia","name":"M\u00e1s material interesante de Rogue One: Una Historia de Star Wars","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/star-wars\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia#primaryimage"},"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/star-wars\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/images2016\/20160624-rogueone-1.jpg","datePublished":"2016-06-24T10:32:08+00:00","dateModified":"2016-06-24T10:47:59+00:00","author":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"description":"Vamos con un nuevo desembarco, segundo en poco m\u00e1s de 24 horas, de Rogue One: Una Historia de Star Wars (Rogue One: A Star Wars Story, 2016). Esto no para!","breadcrumb":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/star-wars\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uruloki.org\/felipeblog\/star-wars\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uruloki.org\/felipeblog\/star-wars\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia#primaryimage","url":"https:\/\/uruloki.org\/felipeblog\/images2016\/20160624-rogueone-1.jpg","contentUrl":"https:\/\/uruloki.org\/felipeblog\/images2016\/20160624-rogueone-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uruloki.org\/felipeblog\/star-wars\/mas-material-la-mar-interesante-rogue-one-una-historia-star-wars-fotos-mas-historia#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uruloki.org\/felipeblog"},{"@type":"ListItem","position":2,"name":"M\u00e1s material la mar de interesante de Rogue One: Una Historia de Star Wars, fotos, James Earl Jones y m\u00e1s historia&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.uruloki.org\/felipeblog\/#website","url":"https:\/\/www.uruloki.org\/felipeblog\/","name":"Uruloki :: Blog","description":"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uruloki.org\/felipeblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3","name":"Uruloki","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","caption":"Uruloki"},"sameAs":["https:\/\/uruloki.org"],"url":"https:\/\/www.uruloki.org\/felipeblog\/author\/admin-2-2-2"}]}},"_links":{"self":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/15703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/comments?post=15703"}],"version-history":[{"count":2,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/15703\/revisions"}],"predecessor-version":[{"id":15705,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/15703\/revisions\/15705"}],"wp:attachment":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/media?parent=15703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/categories?post=15703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/tags?post=15703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}