{"id":1485,"date":"2008-06-21T18:54:18","date_gmt":"2008-06-21T17:54:18","guid":{"rendered":"https:\/\/uruloki.org\/felipeblog\/cine-de-ciencia-ficcin\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir"},"modified":"2008-06-21T22:48:49","modified_gmt":"2008-06-21T21:48:49","slug":"spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir","status":"publish","type":"post","link":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir","title":{"rendered":"Spiderman 4 se estrenar&aacute; en el 2011! Kick-Ass arranca en agosto! As&iacute; ser&aacute; el teaser trailer de Terminator Salvation: The Future Begins! Tres nuevos juguetones carteles de The Spirit y mucha m&aacute;s madera&#8230;"},"content":{"rendered":"<p>Despu&eacute;s de <a href=\"https:\/\/uruloki.org\/felipeblog\/cine-de-cmics\/el-increble-hulk-opinin\">la merecida y obligada opini&oacute;n<\/a> para <a href=\"http:\/\/spanish.imdb.com\/title\/tt0800080\/\" target=\"_blank\">The Incredible Hulk \/ El Incre&iacute;ble Hulk<\/a> (2008) de <a href=\"http:\/\/spanish.imdb.com\/name\/nm0504642\/\" target=\"_blank\">Louis Leterrier<\/a> hay que recuperar las importantes noticias que se han producido a lo largo de las &uacute;ltimas horas, que son una locura! En primer lugar, y llev&aacute;ndose casi todo el protagonismo de la jornada, tenemos el <a href=\"http:\/\/latimesblogs.latimes.com\/entertainmentnewsbuzz\/2008\/06\/spider-man-4-ai.html\" target=\"_blank\">anuncio aparecido hoy en LA Times<\/a> donde la productora  <a href=\"http:\/\/spanish.imdb.com\/name\/nm0957205\/\" target=\"_blank\">Laura Ziskin<\/a> anuncia que <strong>Sony Pictures<\/strong> espera poder estrenar <a href=\"http:\/\/spanish.imdb.com\/title\/tt0948470\/\" target=\"_blank\">Spiderman 4<\/a> (2011) en el mes de mayo del <strong>2011<\/strong>! El pasado jueves en una charla con los medios apunt&oacute; que aunque el gui&oacute;n no est&aacute; en estos momentos terminado, <a href=\"http:\/\/spanish.imdb.com\/name\/nm0888743\/\" target=\"_blank\">James Vanderbilt<\/a> al frente, conf&iacute;a que en tres a&ntilde;os puedan completar el nuevo episodio en la saga ar&aacute;cnida. Con respecto a si <a href=\"http:\/\/spanish.imdb.com\/name\/nm0001497\/\" target=\"_blank\">Tobey Maguire<\/a> o <a href=\"http:\/\/spanish.imdb.com\/name\/nm0000600\/\" target=\"_blank\">Sam Raimi<\/a> estar&aacute;n involucrados en el proyecto no hay nada de nada, lo &uacute;nico cierto es que <strong>Spiderman 4<\/strong> ser&aacute; una realidad ya que <strong>Sony<\/strong> ha renovado los derechos sobre el personaje con <strong>Marvel<\/strong> para los pr&oacute;ximos a&ntilde;os. Si este <em>planning<\/em> se cumple tendremos un <em>preverano<\/em> del 2011 de aut&eacute;ntico infarto con <strong>Spiderman 4<\/strong>, <a href=\"http:\/\/spanish.imdb.com\/title\/tt0458339\/\" target=\"_blank\">The First Avenger: Captain America<\/a> (2011) y <a href=\"http:\/\/spanish.imdb.com\/title\/tt1201607\/\" target=\"_blank\">Harry Potter y las Reliquias de la Muerte: Parte 2<\/a> (2011).<\/p>\n<p style=\"text-align:center;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/imagesflickr3\/20080621_thespirit_giantlorelei1.jpg\" alt=\"Jaime King es Lorelei en The Spirit\" width=\"473\" height=\"700\" border=\"1\" \/><\/p>\n<p>Otro film comiquero que comienza a levantar pasiones y crear bastante inter&eacute;s es la adaptaci&oacute;n cinematogr&aacute;fica del c&oacute;mic de <strong>Mark Millar<\/strong> y <strong>John Romita Jr.<\/strong> &quot;<strong>Kick-Ass<\/strong>&quot;. Tras el anuncio de que <a href=\"http:\/\/spanish.imdb.com\/name\/nm0891216\/\" target=\"_blank\">Matthew Vaughn<\/a> se iba a hacer cargo de la direcci&oacute;n hoy <a href=\"http:\/\/www.comicbookresources.com\/?page=article&amp;id=16892\" target=\"_blank\">Millar ha charlado con la gente de Comic Book Resources<\/a> y les ha desvelado que todo se pondr&aacute; en marcha en nada ya que el <em>casting<\/em> de actores ya est&aacute; cerrado! Aunque no ha querido dar nombres, indica que <strong>Variety<\/strong> tiene la exclusiva del anuncio, reconoce que hay dos grandes fichajes para los papeles protagonistas del film. Como <strong>Millar<\/strong> act&uacute;a  como productor del mismo su participaci&oacute;n en toda la fase de pre-producci&oacute;n ha sido total. Gracias a esto ha contado que el acuerdo con la productora que financia el film se realiz&oacute; el pasado mes de diciembre, que el gui&oacute;n se complet&oacute; hace ya seis meses y que el rodaje comenzar&aacute; este pr&oacute;ximo mes de agosto en localizaciones de <strong>New York<\/strong>!<\/p>\n<p>Tercer pelotazo de la jornada. <a href=\"http:\/\/www.aintitcool.com\/node\/37157\" target=\"_blank\">Ain&#8217;t It Cool News public&oacute; ayer una supuesta descripci&oacute;n<\/a> del teaser trailer de <a href=\"http:\/\/spanish.imdb.com\/title\/tt0438488\/\" target=\"_blank\">Terminator Salvation: The Future Begins<\/a> (2009) de <a href=\"http:\/\/spanish.imdb.com\/name\/nm0629334\/\" target=\"_blank\">McG<\/a> que acompa&ntilde;ar&aacute; como producto <strong>Warner Bros.<\/strong> al estreno el pr&oacute;ximo 18 de julio de <a href=\"http:\/\/spanish.imdb.com\/title\/tt0468569\/\" target=\"_blank\">The Dark Knight \/ El caballero oscuro<\/a> (2008) de <a href=\"http:\/\/spanish.imdb.com\/name\/nm0634240\/\" target=\"_blank\">Christopher Nolan<\/a>. A las pocas horas de saltar la noticia esta fue corroborada y por lo tanto oficializada! He traducido la descripci&oacute;n, as&iacute; que, <a href=\"#\" target=\"_blank\" onclick=\"document.getElementById('textoocultoterminator').style.display=''; return false;\">si quieres saber que podremos ver en el teaser trailer pulsa sobre este enlace<\/a>.<\/p>\n<blockquote style=\"display:none;\" id=\"textoocultoterminator\"><p>Comienza con im&aacute;genes de gente en un t&iacute;pico d&iacute;a como el que todos solemos tener. Una voz en off, <strong>John Connor<\/strong> (<a href=\"http:\/\/spanish.imdb.com\/name\/nm0000288\/\" target=\"_blank\">Christian Bale<\/a>), narra: &quot;<em>Siempre supe que pasar&iacute;a<\/em>&quot;, &quot;<em>me dijeron que podr&iacute;a pararlo<\/em>&quot;, &quot;<em>que podr&iacute;a salvarnos<\/em>&quot;&#8230; &quot;<em>estaban equivocados<\/em>&quot;&#8230; fundido en negro y comienza la famosa m&uacute;sica de <strong>terminator<\/strong>. Vemos una soleada zona des&eacute;rtica y <strong>John Connor<\/strong> firme con un traje de comando militar delante de un bunker  repleto de armas. Un primer mensaje con fondo negro que reza &quot;<em>La lucha por el futuro<\/em>&quot;, una escena dentro el bunker similar a la vista en <a href=\"http:\/\/spanish.imdb.com\/title\/tt0088247\/\" target=\"_blank\">Terminator<\/a> (1984) cuando <strong>Kyle Reese<\/strong> cuenta como viv&iacute;an hacinados, &quot;<em>comienza<\/em>&quot;. Acto seguido un cami&oacute;n a toda velocidad por el desierto, tomas de un helic&oacute;ptero volando y <strong>John Connor<\/strong> gritando &quot;<em>Ya vienen!<\/em>&quot;. Todo se para y aparece una gran <strong>T<\/strong> que se transforma en un <strong>4<\/strong>. Para rematar la escena gorda del avance&#8230; <strong>John Connor<\/strong> y una chica en una moto a toda velocidad  y primer vistazo a un imponente <strong>Terminator<\/strong> que, tras atravesar una pared, los atrapa!<\/p><\/blockquote>\n<p style=\"text-align:center;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/imagesflickr3\/20080621_thespirit_giantellen1.jpg\" alt=\"Sarah Paulson es Ellen Dolan en The Spirit\" width=\"473\" height=\"700\" border=\"1\" \/><\/p>\n<p>Ahora unas cuantas breves de esas que cumplen sobradamente. Primero avisar que <a href=\"http:\/\/movies.yahoo.com\/feature\/thespirit_slideshow.html\" target=\"_blank\">Yahoo! ha sacado a la luz dos nuevos carteles<\/a> y <a href=\"http:\/\/movies.yahoo.com\/feature\/thespirit_flash.html\" target=\"_blank\">un curioso p&oacute;ster con audio<\/a> de <a href=\"http:\/\/spanish.imdb.com\/title\/tt0831887\/\" target=\"_blank\">The Spirit<\/a> (2008) de <a href=\"http:\/\/spanish.imdb.com\/name\/nm0588340\/\" target=\"_blank\">Frank Miller<\/a>. Si, est&aacute;is leyendo bien. Resulta que el p&oacute;ster con audio, en formato <em>flash<\/em>, ofrece una frase de 4 de los personajes femeninos protagonistas tan pronto como pasamos el rat&oacute;n por encima de su rostro. Digamos que no me convence mucho la idea, prefiero ver los carteles en alta calidad, el de <a href=\"http:\/\/spanish.imdb.com\/name\/nm0454809\/\" target=\"_blank\">Jaime King<\/a> como <strong>Lorelei<\/strong> y el de <a href=\"http:\/\/spanish.imdb.com\/name\/nm0005299\/\" target=\"_blank\">Sarah Paulson<\/a> como <strong>Ellen Dolan<\/strong>. <a href=\"http:\/\/www.spielbergnews.com\/spielberg-news.php?id_news=147\" target=\"_blank\">El portal franc&eacute;s SpielbergNews<\/a>, no se que decir, ha sacado a luz un dudoso rumor que sorprendentemente  est&aacute; causando furor y discusi&oacute;n al otro lado del charco. Prometen  en esta web que una fuente cercana a la producci&oacute;n les ha confirmado que <a href=\"http:\/\/spanish.imdb.com\/name\/nm0000982\/\" target=\"_blank\">Josh Brolin<\/a> ser&aacute; el actor que interprete finalmente a <strong>Snake Plissken<\/strong> en el <em>remake<\/em> que se planea hacer de <a href=\"http:\/\/spanish.imdb.com\/title\/tt0082340\/\" target=\"_blank\">1997, rescate en New York<\/a> (<del datetime=\"2008-06-21T21:48:15+00:00\">1997<\/del>1981) de <a href=\"http:\/\/spanish.imdb.com\/name\/nm0000118\/\" target=\"_blank\">John Carpenter<\/a>. Habr&aacute; que estar atentos aunque no ser&iacute;a una mala idea.<\/p>\n<p>Como despedida indicar que <strong>el pr&oacute;ximo viernes 27 de junio a las 8 de la tarde<\/strong> se iniciar&aacute; el <strong>Octavo Concurso Uruloki<\/strong>! Atenci&oacute;n al premio, una peque&ntilde;a joya para nost&aacute;lgicos y vicioso de las series de ciencia ficci&oacute;n de nuestra infancia&#8230; <strong>V + V: La Batalla Final<\/strong>! Un <strong>pack de 5 DVDs<\/strong> del ala con <strong>m&aacute;s de siete horas de lagartos y resistencia humana<\/strong> que caer&aacute;n en las manos del que m&aacute;s r&aacute;pido se mueva por los entresijos de internet. Id calentado motores!<\/p>\n<p><strong style=\"color:#FFFFFF; background-color:#FF0000;\">&nbsp;NOTA&nbsp;<\/strong> El arte conceptual que os debo intentar&eacute; sacarlo a al luz ma&ntilde;ana.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Despu&eacute;s de la merecida y obligada opini&oacute;n para The Incredible Hulk \/ El Incre&iacute;ble Hulk (2008) de Louis Leterrier hay que recuperar las importantes noticias que se han producido a lo largo de las &uacute;ltimas horas, que son una locura! En primer lugar, y llev&aacute;ndose casi todo el protagonismo de la jornada, tenemos el anuncio [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,8],"tags":[294,393,165,158],"class_list":["post-1485","post","type-post","status-publish","format-standard","hentry","category-cine-de-comics","category-cine-de-ciencia-ficcion","tag-kick-ass","tag-spiderman-4","tag-terminator-salvation-the-future-begins","tag-the-spirit"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Spiderman 4 se estrenar&aacute; en el 2011! Kick-Ass arranca en agosto! As&iacute; ser&aacute; el teaser trailer de Terminator Salvation: The Future Begins! Tres nuevos juguetones carteles de The Spirit y mucha m&aacute;s madera... - Uruloki :: Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Spiderman 4 se estrenar&aacute; en el 2011! Kick-Ass arranca en agosto! As&iacute; ser&aacute; el teaser trailer de Terminator Salvation: The Future Begins! Tres nuevos juguetones carteles de The Spirit y mucha m&aacute;s madera... - Uruloki :: Blog\" \/>\n<meta property=\"og:description\" content=\"Despu&eacute;s de la merecida y obligada opini&oacute;n para The Incredible Hulk \/ El Incre&iacute;ble Hulk (2008) de Louis Leterrier hay que recuperar las importantes noticias que se han producido a lo largo de las &uacute;ltimas horas, que son una locura! En primer lugar, y llev&aacute;ndose casi todo el protagonismo de la jornada, tenemos el anuncio [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir\" \/>\n<meta property=\"og:site_name\" content=\"Uruloki :: Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uruloki.org\" \/>\n<meta property=\"article:published_time\" content=\"2008-06-21T17:54:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2008-06-21T21:48:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uruloki.org\/felipeblog\/imagesflickr3\/20080621_thespirit_giantlorelei1.jpg\" \/>\n<meta name=\"author\" content=\"Uruloki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uruloki\" \/>\n<meta name=\"twitter:site\" content=\"@uruloki\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Uruloki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir\"},\"author\":{\"name\":\"Uruloki\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"headline\":\"Spiderman 4 se estrenar&aacute; en el 2011! Kick-Ass arranca en agosto! As&iacute; ser&aacute; el teaser trailer de Terminator Salvation: The Future Begins! Tres nuevos juguetones carteles de The Spirit y mucha m&aacute;s madera&#8230;\",\"datePublished\":\"2008-06-21T17:54:18+00:00\",\"dateModified\":\"2008-06-21T21:48:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir\"},\"wordCount\":1050,\"commentCount\":3,\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagesflickr3\\\/20080621_thespirit_giantlorelei1.jpg\",\"keywords\":[\"Kick-Ass\",\"Spiderman 4\",\"Terminator Salvation: The Future Begins\",\"The Spirit\"],\"articleSection\":[\"Cine de C\u00f3mics\",\"Cine de Ciencia Ficci\u00f3n\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir\",\"name\":\"Spiderman 4 se estrenar&aacute; en el 2011! Kick-Ass arranca en agosto! As&iacute; ser&aacute; el teaser trailer de Terminator Salvation: The Future Begins! Tres nuevos juguetones carteles de The Spirit y mucha m&aacute;s madera... - Uruloki :: Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagesflickr3\\\/20080621_thespirit_giantlorelei1.jpg\",\"datePublished\":\"2008-06-21T17:54:18+00:00\",\"dateModified\":\"2008-06-21T21:48:49+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir#primaryimage\",\"url\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagesflickr3\\\/20080621_thespirit_giantlorelei1.jpg\",\"contentUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagesflickr3\\\/20080621_thespirit_giantlorelei1.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Spiderman 4 se estrenar&aacute; en el 2011! Kick-Ass arranca en agosto! As&iacute; ser&aacute; el teaser trailer de Terminator Salvation: The Future Begins! Tres nuevos juguetones carteles de The Spirit y mucha m&aacute;s madera&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/\",\"name\":\"Uruloki :: Blog\",\"description\":\"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\",\"name\":\"Uruloki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"caption\":\"Uruloki\"},\"sameAs\":[\"https:\\\/\\\/uruloki.org\"],\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/author\\\/admin-2-2-2\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Spiderman 4 se estrenar&aacute; en el 2011! Kick-Ass arranca en agosto! As&iacute; ser&aacute; el teaser trailer de Terminator Salvation: The Future Begins! Tres nuevos juguetones carteles de The Spirit y mucha m&aacute;s madera... - Uruloki :: Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir","og_locale":"es_ES","og_type":"article","og_title":"Spiderman 4 se estrenar&aacute; en el 2011! Kick-Ass arranca en agosto! As&iacute; ser&aacute; el teaser trailer de Terminator Salvation: The Future Begins! Tres nuevos juguetones carteles de The Spirit y mucha m&aacute;s madera... - Uruloki :: Blog","og_description":"Despu&eacute;s de la merecida y obligada opini&oacute;n para The Incredible Hulk \/ El Incre&iacute;ble Hulk (2008) de Louis Leterrier hay que recuperar las importantes noticias que se han producido a lo largo de las &uacute;ltimas horas, que son una locura! En primer lugar, y llev&aacute;ndose casi todo el protagonismo de la jornada, tenemos el anuncio [&hellip;]","og_url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir","og_site_name":"Uruloki :: Blog","article_publisher":"https:\/\/www.facebook.com\/uruloki.org","article_published_time":"2008-06-21T17:54:18+00:00","article_modified_time":"2008-06-21T21:48:49+00:00","og_image":[{"url":"https:\/\/uruloki.org\/felipeblog\/imagesflickr3\/20080621_thespirit_giantlorelei1.jpg","type":"","width":"","height":""}],"author":"Uruloki","twitter_card":"summary_large_image","twitter_creator":"@uruloki","twitter_site":"@uruloki","twitter_misc":{"Escrito por":"Uruloki","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir#article","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir"},"author":{"name":"Uruloki","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"headline":"Spiderman 4 se estrenar&aacute; en el 2011! Kick-Ass arranca en agosto! As&iacute; ser&aacute; el teaser trailer de Terminator Salvation: The Future Begins! Tres nuevos juguetones carteles de The Spirit y mucha m&aacute;s madera&#8230;","datePublished":"2008-06-21T17:54:18+00:00","dateModified":"2008-06-21T21:48:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir"},"wordCount":1050,"commentCount":3,"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/imagesflickr3\/20080621_thespirit_giantlorelei1.jpg","keywords":["Kick-Ass","Spiderman 4","Terminator Salvation: The Future Begins","The Spirit"],"articleSection":["Cine de C\u00f3mics","Cine de Ciencia Ficci\u00f3n"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir","url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir","name":"Spiderman 4 se estrenar&aacute; en el 2011! Kick-Ass arranca en agosto! As&iacute; ser&aacute; el teaser trailer de Terminator Salvation: The Future Begins! Tres nuevos juguetones carteles de The Spirit y mucha m&aacute;s madera... - Uruloki :: Blog","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir#primaryimage"},"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/imagesflickr3\/20080621_thespirit_giantlorelei1.jpg","datePublished":"2008-06-21T17:54:18+00:00","dateModified":"2008-06-21T21:48:49+00:00","author":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"breadcrumb":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir#primaryimage","url":"https:\/\/uruloki.org\/felipeblog\/imagesflickr3\/20080621_thespirit_giantlorelei1.jpg","contentUrl":"https:\/\/uruloki.org\/felipeblog\/imagesflickr3\/20080621_thespirit_giantlorelei1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/spiderman-4-se-estrenar-en-el-2011-kick-ass-arranca-en-agosto-as-ser-el-teaser-trailer-de-terminator-salvation-the-future-begins-tres-nuevos-juguetones-carteles-de-the-spir#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uruloki.org\/felipeblog"},{"@type":"ListItem","position":2,"name":"Spiderman 4 se estrenar&aacute; en el 2011! Kick-Ass arranca en agosto! As&iacute; ser&aacute; el teaser trailer de Terminator Salvation: The Future Begins! Tres nuevos juguetones carteles de The Spirit y mucha m&aacute;s madera&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.uruloki.org\/felipeblog\/#website","url":"https:\/\/www.uruloki.org\/felipeblog\/","name":"Uruloki :: Blog","description":"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uruloki.org\/felipeblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3","name":"Uruloki","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","caption":"Uruloki"},"sameAs":["https:\/\/uruloki.org"],"url":"https:\/\/www.uruloki.org\/felipeblog\/author\/admin-2-2-2"}]}},"_links":{"self":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/1485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/comments?post=1485"}],"version-history":[{"count":0,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/1485\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/media?parent=1485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/categories?post=1485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/tags?post=1485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}