{"id":148,"date":"2004-06-17T21:52:19","date_gmt":"2004-06-18T05:52:19","guid":{"rendered":"https:\/\/uruloki.org\/felipeblog\/?p=148"},"modified":"2004-06-17T21:52:19","modified_gmt":"2004-06-18T05:52:19","slug":"los-4-fantsticos-ya-son-ms-que-un-proyecto","status":"publish","type":"post","link":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/los-4-fantsticos-ya-son-ms-que-un-proyecto","title":{"rendered":"Los 4 Fant&aacute;sticos ya son m&aacute;s que un proyecto&#8230;"},"content":{"rendered":"<p>Pues si se&ntilde;ores, despu&eacute;s de buscar un poco por aqu&iacute; y otro poco por all&iacute; pongo un par de im&aacute;genes para dar fe de que el megaproyecto llevado a cabo por el se&ntilde;or <a href=\"https:\/\/uruloki.org\/felipeblog\/archives\/000108.html#000108\" title=\"Saber m&aacute;s sobre Avi Arad\">Avi Arad<\/a> sigue su curso.<br \/>\nEsta vez ya tenemos p&oacute;ster de los 4F y una posible primera maqueta de lo que sea Ben Grimm &quot;La Cosa&quot;.<\/p>\n<p><a href=\"https:\/\/uruloki.org\/felipeblog\/imagenes\/fantastic_four.html\" onclick=\"window.open('https:\/\/uruloki.org\/felipeblog\/imagenes\/fantastic_four.html','popup','width=580,height=755,scrollbars=no,resizable=no,toolbar=no,directories=no,location=no,menubar=no,status=no,left=0,top=0'); return false\" title=\"Ampliar Poster de los 4F\"><img loading=\"lazy\" decoding=\"async\" alt=\"Poster de los 4F\" src=\"https:\/\/uruloki.org\/felipeblog\/imagenes\/thmb_fantastic_four.jpg\" width=\"153\" height=\"200\" border=\"1\" \/><\/a>&nbsp;<a href=\"https:\/\/uruloki.org\/felipeblog\/imagenes\/thing.html\" onclick=\"window.open('https:\/\/uruloki.org\/felipeblog\/imagenes\/thing.html','popup','width=514,height=759,scrollbars=no,resizable=no,toolbar=no,directories=no,location=no,menubar=no,status=no,left=0,top=0'); return false\" title=\"Ampliar La Cosa\"><img loading=\"lazy\" decoding=\"async\" alt=\"La Cosa\" src=\"https:\/\/uruloki.org\/felipeblog\/imagenes\/thmb_thing.jpg\" width=\"135\" height=\"200\" border=\"1\" \/><\/a><\/p>\n<p>Bueno, vayamos por partes&#8230; el <strong>Ben Grimm<\/strong> <acronym title=\"Also Known As\">a.k.a.<\/acronym> <strong>La Cosa<\/strong> es una foto sacada en una reciente reuni&oacute;n de artistas del maquillaje y los <acronym title=\"Efectos Especiales\">FX<\/acronym> en Pasadena (<acronym title=\"United States of America\">U.S.A.<\/acronym>), se comenta por ah&iacute; que un tal <a href=\"http:\/\/us.imdb.com\/name\/nm0004821\/\" target=\"_blank\" title=\"Saber m&aacute;s sobre este actor\">Michael Chiklis<\/a> podr&iacute;a hacerse cargo del papel&#8230; el tipo da la talla por las fotos que he visto, pero es calvo y <strong>Ben Grimm<\/strong> no, aunque si <strong>Kingpin<\/strong> fue negro pues&#8230; todo vale.<br \/>\nEl otro es un escaneo de un p&oacute;ster de una revista americana. As&iacute; empiezan y luego ya se sabe que todo acaba siendo realidad. Puede estar bien encontrarnos con Reed Richards y toda su banda.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" alt=\"Laboratorio del Doctor Doom en el espacio\" title=\"Laboratorio del Doctor Doom en el espacio\" src=\"https:\/\/uruloki.org\/felipeblog\/imagenes\/doctorDoomlab.jpg\" width=\"400\" height=\"263\" border=\"1\" \/><\/p>\n<p>En la siguiente web pod&eacute;is ver bocetos del dise&ntilde;o de producci&oacute;n de este film: <a href=\"http:\/\/www.productionillustration.com\/fantastic%20four.html\" title=\"Dise&ntilde;o de producci&oacute;n\" target=\"_blank\">www.productionillustration.com<\/a>. Es arte conceptual, y viene a reflejar lo que se desear&iacute;a hacer, de todas formas casi confirma que el Doctor Doom ser&aacute; el enemigo a batir!!!<\/p>\n<p>Otros nombres que se manejan por internet y por revistas del ramo del cine de la ciencia ficci&oacute;n (Cinescape) son <em>Tim Robbins<\/em> como <strong>Doctor Doom<\/strong> y <em>Christina Millian<\/em> (Torque) como <strong>Sue Storm \/ La Mujer Invisible<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pues si se&ntilde;ores, despu&eacute;s de buscar un poco por aqu&iacute; y otro poco por all&iacute; pongo un par de im&aacute;genes para dar fe de que el megaproyecto llevado a cabo por el se&ntilde;or Avi Arad sigue su curso. Esta vez ya tenemos p&oacute;ster de los 4F y una posible primera maqueta de lo que sea [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,14],"tags":[],"class_list":["post-148","post","type-post","status-publish","format-standard","hentry","category-cine-de-comics","category-arte-conceptual"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los 4 Fant&aacute;sticos ya son m&aacute;s que un proyecto... - Uruloki :: Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/los-4-fantsticos-ya-son-ms-que-un-proyecto\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los 4 Fant&aacute;sticos ya son m&aacute;s que un proyecto... - Uruloki :: Blog\" \/>\n<meta property=\"og:description\" content=\"Pues si se&ntilde;ores, despu&eacute;s de buscar un poco por aqu&iacute; y otro poco por all&iacute; pongo un par de im&aacute;genes para dar fe de que el megaproyecto llevado a cabo por el se&ntilde;or Avi Arad sigue su curso. Esta vez ya tenemos p&oacute;ster de los 4F y una posible primera maqueta de lo que sea [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/los-4-fantsticos-ya-son-ms-que-un-proyecto\" \/>\n<meta property=\"og:site_name\" content=\"Uruloki :: Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uruloki.org\" \/>\n<meta property=\"article:published_time\" content=\"2004-06-18T05:52:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uruloki.org\/felipeblog\/imagenes\/thmb_fantastic_four.jpg\" \/>\n<meta name=\"author\" content=\"Uruloki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uruloki\" \/>\n<meta name=\"twitter:site\" content=\"@uruloki\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Uruloki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/los-4-fantsticos-ya-son-ms-que-un-proyecto#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/los-4-fantsticos-ya-son-ms-que-un-proyecto\"},\"author\":{\"name\":\"Uruloki\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"headline\":\"Los 4 Fant&aacute;sticos ya son m&aacute;s que un proyecto&#8230;\",\"datePublished\":\"2004-06-18T05:52:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/los-4-fantsticos-ya-son-ms-que-un-proyecto\"},\"wordCount\":290,\"commentCount\":3,\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/los-4-fantsticos-ya-son-ms-que-un-proyecto#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagenes\\\/thmb_fantastic_four.jpg\",\"articleSection\":[\"Cine de C\u00f3mics\",\"Concept Art\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/los-4-fantsticos-ya-son-ms-que-un-proyecto#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/los-4-fantsticos-ya-son-ms-que-un-proyecto\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/los-4-fantsticos-ya-son-ms-que-un-proyecto\",\"name\":\"Los 4 Fant&aacute;sticos ya son m&aacute;s que un proyecto... - Uruloki :: Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/los-4-fantsticos-ya-son-ms-que-un-proyecto#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/los-4-fantsticos-ya-son-ms-que-un-proyecto#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagenes\\\/thmb_fantastic_four.jpg\",\"datePublished\":\"2004-06-18T05:52:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/los-4-fantsticos-ya-son-ms-que-un-proyecto#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/los-4-fantsticos-ya-son-ms-que-un-proyecto\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/los-4-fantsticos-ya-son-ms-que-un-proyecto#primaryimage\",\"url\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagenes\\\/thmb_fantastic_four.jpg\",\"contentUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagenes\\\/thmb_fantastic_four.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-comics\\\/los-4-fantsticos-ya-son-ms-que-un-proyecto#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los 4 Fant&aacute;sticos ya son m&aacute;s que un proyecto&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/\",\"name\":\"Uruloki :: Blog\",\"description\":\"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\",\"name\":\"Uruloki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"caption\":\"Uruloki\"},\"sameAs\":[\"https:\\\/\\\/uruloki.org\"],\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/author\\\/admin-2-2-2\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los 4 Fant&aacute;sticos ya son m&aacute;s que un proyecto... - Uruloki :: Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/los-4-fantsticos-ya-son-ms-que-un-proyecto","og_locale":"es_ES","og_type":"article","og_title":"Los 4 Fant&aacute;sticos ya son m&aacute;s que un proyecto... - Uruloki :: Blog","og_description":"Pues si se&ntilde;ores, despu&eacute;s de buscar un poco por aqu&iacute; y otro poco por all&iacute; pongo un par de im&aacute;genes para dar fe de que el megaproyecto llevado a cabo por el se&ntilde;or Avi Arad sigue su curso. Esta vez ya tenemos p&oacute;ster de los 4F y una posible primera maqueta de lo que sea [&hellip;]","og_url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/los-4-fantsticos-ya-son-ms-que-un-proyecto","og_site_name":"Uruloki :: Blog","article_publisher":"https:\/\/www.facebook.com\/uruloki.org","article_published_time":"2004-06-18T05:52:19+00:00","og_image":[{"url":"https:\/\/uruloki.org\/felipeblog\/imagenes\/thmb_fantastic_four.jpg","type":"","width":"","height":""}],"author":"Uruloki","twitter_card":"summary_large_image","twitter_creator":"@uruloki","twitter_site":"@uruloki","twitter_misc":{"Escrito por":"Uruloki","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/los-4-fantsticos-ya-son-ms-que-un-proyecto#article","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/los-4-fantsticos-ya-son-ms-que-un-proyecto"},"author":{"name":"Uruloki","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"headline":"Los 4 Fant&aacute;sticos ya son m&aacute;s que un proyecto&#8230;","datePublished":"2004-06-18T05:52:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/los-4-fantsticos-ya-son-ms-que-un-proyecto"},"wordCount":290,"commentCount":3,"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/los-4-fantsticos-ya-son-ms-que-un-proyecto#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/imagenes\/thmb_fantastic_four.jpg","articleSection":["Cine de C\u00f3mics","Concept Art"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/los-4-fantsticos-ya-son-ms-que-un-proyecto#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/los-4-fantsticos-ya-son-ms-que-un-proyecto","url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/los-4-fantsticos-ya-son-ms-que-un-proyecto","name":"Los 4 Fant&aacute;sticos ya son m&aacute;s que un proyecto... - Uruloki :: Blog","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/los-4-fantsticos-ya-son-ms-que-un-proyecto#primaryimage"},"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/los-4-fantsticos-ya-son-ms-que-un-proyecto#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/imagenes\/thmb_fantastic_four.jpg","datePublished":"2004-06-18T05:52:19+00:00","author":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"breadcrumb":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/los-4-fantsticos-ya-son-ms-que-un-proyecto#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/los-4-fantsticos-ya-son-ms-que-un-proyecto"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/los-4-fantsticos-ya-son-ms-que-un-proyecto#primaryimage","url":"https:\/\/uruloki.org\/felipeblog\/imagenes\/thmb_fantastic_four.jpg","contentUrl":"https:\/\/uruloki.org\/felipeblog\/imagenes\/thmb_fantastic_four.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-comics\/los-4-fantsticos-ya-son-ms-que-un-proyecto#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uruloki.org\/felipeblog"},{"@type":"ListItem","position":2,"name":"Los 4 Fant&aacute;sticos ya son m&aacute;s que un proyecto&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.uruloki.org\/felipeblog\/#website","url":"https:\/\/www.uruloki.org\/felipeblog\/","name":"Uruloki :: Blog","description":"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uruloki.org\/felipeblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3","name":"Uruloki","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","caption":"Uruloki"},"sameAs":["https:\/\/uruloki.org"],"url":"https:\/\/www.uruloki.org\/felipeblog\/author\/admin-2-2-2"}]}},"_links":{"self":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/comments?post=148"}],"version-history":[{"count":0,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/148\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/media?parent=148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/categories?post=148"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/tags?post=148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}