{"id":1337,"date":"2008-02-15T23:45:58","date_gmt":"2008-02-15T22:45:58","guid":{"rendered":"https:\/\/uruloki.org\/felipeblog\/cine-de-ciencia-ficcin\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra"},"modified":"2008-05-02T19:07:45","modified_gmt":"2008-05-02T18:07:45","slug":"the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra","status":"publish","type":"post","link":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra","title":{"rendered":"The Happening, &iquest;sustitutos para el Dr. Parnassus?, a Justice League of America le ha mirado un tuerto, primera imagen de G.I. Joe y otras noticias extra&#8230;"},"content":{"rendered":"<p>Bienvenidos a un nuevo viernes plagadito de noticias para que uno no pueda descansar ni un m&iacute;sero minuto. Para comenzar bien avisar que <a href=\"http:\/\/video.cineplex.com\/?fr_story=c72ed1e5eef326a6bac15ef22b83eb418ac9524f&amp;rf=bm\" target=\"_blank\">desde la web Cineplex Entertainment<\/a> nos llega un nuevo trailer de <a href=\"http:\/\/www.imdb.com\/title\/tt0949731\/\" target=\"_blank\" title=\"Info de The Happening\">The Happening<\/a> (2008) de <a href=\"http:\/\/www.imdb.com\/name\/nm0796117\/\" target=\"_blank\" title=\"Filmograf&iacute;a de M. Night Shyamalan\">M. Night Shyamalan<\/a>. Completamente diferente al anterior visto, otra vez todo es un gran desconcierto ante la que se avecina cuando a la gente m&aacute;s normal le da por cometer suicidio en cualquier lado y sin raz&oacute;n alguna aparente. Bastante psicosis colectiva, todos escapando de las grandes ciudades, caos ante el riesgo de un ataque terrorista con armas qu&iacute;micas, etc. &iquest;Qu&eacute; esconde esta vez <strong>Shyamalan<\/strong> entre las manos? Por ahora para ver el avance <a href=\"http:\/\/video.cineplex.com\/?fr_story=c72ed1e5eef326a6bac15ef22b83eb418ac9524f&amp;rf=bm\" target=\"_blank\">hay que pasarse por Cineplex<\/a> ya que lo han colocado en un formato que no hay quien lo utilice. <\/p>\n<p>Por otro lado, y sorprendiendo al personal por la magnitud de la noticia, <a href=\"http:\/\/www.aintitcool.com\/node\/35623\" target=\"_blank\">Ain&#8217;t It Cool News ha publicado<\/a> hoy que <a href=\"http:\/\/www.imdb.com\/name\/nm0000416\/\" target=\"_blank\" title=\"Filmograf&iacute;a de Terry Gilliam\">Terry Gilliam<\/a> podr&iacute;a ya tener apalabrados a los sustitutos encergados de reinterpretar el papel de Heath Ledger para cuando este pase por los deferentes universos en los viajes del <strong>Dr. Parnassus<\/strong>. Atenci&oacute;n al pelotazo, el film <a href=\"http:\/\/www.imdb.com\/title\/tt1054606\/\" target=\"_blank\" title=\"Info de The Imaginarium of Doctor Parnassus\">The Imaginarium of Doctor Parnassus<\/a> (2009) incorporar&iacute;a a <a href=\"http:\/\/www.imdb.com\/name\/nm0000136\/\" target=\"_blank\" title=\"Filmograf&iacute;a de Johnny Depp\">Johnny Depp<\/a>, <a href=\"http:\/\/www.imdb.com\/name\/nm0000179\/\" target=\"_blank\" title=\"Filmograf&iacute;a de Jude Law\">Jude Law<\/a> y <a href=\"http:\/\/www.imdb.com\/name\/nm0268199\/\" target=\"_blank\">Colin Farrel<\/a> a modo homenaje al futuro <strong>Joker<\/strong>. No se yo, pero el cach&eacute; de estos tres actores supera con creces al montante aportado por el propio <strong>Ledger<\/strong>. &iquest;Actuar&aacute;n por una cifra m&oacute;dica o habr&aacute; visto la productora el tesoro que tiene entre manos en estos momentos? En fin, si se cumplen los fichajes el film del <strong>Dr. Parnassus<\/strong> puede ser la repera.<\/p>\n<p style=\"text-align:center;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/imagesflickr2\/20080215_quaidgijoe.jpg\" alt=\"Dennis Quaid en G.I. Joe\" title=\"Dennis Quaid en G.I. Joe\" width=\"400\" height=\"400\" border=\"1\" \/><\/p>\n<p> Noticias locas son las que <a href=\"http:\/\/movies.ign.com\/articles\/852\/852171p1.html?RSSwhen2008-02-14_184700&amp;RSSid=852171\" target=\"_blank\">llegan desde IGN<\/a> aunque <a href=\"http:\/\/www.moviehole.net\/news\/20080214_star_trek_and_justice_league_p.html\" target=\"_blank\">citan a Moviehole.net<\/a>. Primero, parece ser que <a href=\"http:\/\/www.imdb.com\/title\/tt0974015\/\" target=\"_blank\" title=\"Info de Justice League of America\">Justice League of America<\/a> (&iquest;?) de <a href=\"http:\/\/www.imdb.com\/name\/nm0004306\/\" target=\"_blank\" title=\"Filmgraf&iacute;a de George Miller\">George Miller<\/a> no levantar&aacute; cabeza durante mucho tiempo. Desde estas webs nos avisan que un diario australiano llamado <strong>Herald-Sun<\/strong>, tiene toda la pinta de ser un pel&iacute;n sensacionalista, avisa que el film del equipo de superh&eacute;roes no arrancar&aacute; hasta bien avanzado el <strong>2010<\/strong>. Aunque la raz&oacute;n no me convenza del todo parece ser que <strong>Warner Bros.<\/strong> se ha encontrado con lo l&oacute;gico, la mitad de los actores est&aacute;n comprometidos con otros proyectos. Segundo, y quiz&aacute;s m&aacute;s sorprendente y por ello menos cre&iacute;ble, es el aviso que indica que el film dejar&aacute; de tratar sobre la <strong>Liga de la Justicia<\/strong> de <strong>Superman<\/strong>, <strong>Batman<\/strong>, <strong>Green Lantern<\/strong>, <strong>Wonder Woman<\/strong>, <strong>Aquaman<\/strong> y <strong>The Flash<\/strong> para pasar a ser el grupo formado por <strong>Green Lantern<\/strong>, <strong>Wonder Woman<\/strong>, <strong>Green Arrow<\/strong>, <strong>Aquaman<\/strong> y <strong>The Flash<\/strong>&#8230; &iquest;y <strong>Batman<\/strong> y <strong>Superman<\/strong>? El primero expulsado de la <strong>JLA<\/strong> y el segundo carne de ca&ntilde;&oacute;n a manos de <strong>Doomsday<\/strong>. En fin, no me lo creo!<\/p>\n<p style=\"text-align:center;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/imagesflickr2\/20080215_gw1.jpg\" alt=\"Una foto de Gallowwalker\" title=\"Una foto de Gallowwalker\" width=\"498\" height=\"275\" border=\"1\" \/><\/p>\n<p>Ahora un par de noticias comiqueras m&aacute;s. Una de las fotos que acompa&ntilde;an al post es la primera imagen de <a href=\"http:\/\/www.imdb.com\/title\/tt1046173\/\" target=\"_blank\" title=\"Info de G.I. Joe\">G.I. Joe<\/a> (2009) de <a href=\"http:\/\/www.imdb.com\/name\/nm0814085\/\" title=\"Filmograf&iacute;a de este creador de Stephen Sommers\" target=\"_blank\">Stephen Sommers<\/a> que han publicado en primicia <a href=\"http:\/\/www.iesb.net\/index.php?option=com_content&amp;task=view&amp;id=4319&amp;Itemid=99\" target=\"_blank\">los chicos de IESB.net<\/a>. En ella podemos ver a <a href=\"http:\/\/www.imdb.com\/name\/nm0000598\/\" target=\"_blank\" title=\"Filmograf&iacute;a de Dennis Quaid\">Dennis Quaid<\/a> vestido como el General Hawk. No es que sea algo sorprendente ni que te deje con los ojos como platos, pero al ser la primera imagen augura que con el paso de los d&iacute;as iremos teniendo m&aacute;s material similar: <strong>Snake Eyes<\/strong> a.k.a. <strong>Ojos de serpiente<\/strong>, <strong>Destro<\/strong>, la <strong>Baronesa Cobra<\/strong>, etc. La otra noticia de g&eacute;nero afecta a <a href=\"http:\/\/www.imdb.com\/title\/tt0800080\/\" target=\"_blank\" title=\"Info de The Incredible Hulk\">The Incredible Hulk<\/a> (2008) de <a href=\"http:\/\/www.imdb.com\/name\/nm0504642\/\" target=\"_blank\" title=\"Filmograf&iacute;a de Louis Leterrier\">Louis Leterrier<\/a> y concierne al anuncio del compositor contratado para realizar el score que acompa&ntilde;ar&aacute; al film. El elegido, <a href=\"http:\/\/www.superherohype.com\/news\/topnews.php?id=6797\" target=\"_blank\">cuenta en Superherohype<\/a>, es <a href=\"http:\/\/www.imdb.com\/name\/nm0035661\/\" target=\"_blank\">Craig Armstrong<\/a>, conocido por su trabajo musical en <a href=\"http:\/\/www.imdb.com\/title\/tt0203009\/\">Moulin Rouge!<\/a> (2001). <strong>Armstrong<\/strong> tendr&aacute; que dar el do de pecho en esta nueva incursi&oacute;n en la vida del gigante verde de la <strong>Marvel<\/strong> y superar la buena m&uacute;sica compuesta por <a href=\"http:\/\/www.imdb.com\/name\/nm0000384\/\" target=\"_blank\" title=\"Composiciones de Danny Elfman\">Danny Elfman<\/a> para el <a href=\"http:\/\/www.imdb.com\/title\/tt0286716\/\" target=\"_blank\" title=\"Info de Hulk\">Hulk<\/a> (2003) de <a href=\"http:\/\/www.imdb.com\/name\/nm0000487\/\" target=\"_blank\" title=\"Filmograf&iacute;a de Ang Lee\">Ang Lee<\/a>. <\/p>\n<p style=\"text-align:center;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/imagesflickr2\/20080215_gw2.jpg\" alt=\"Una foto de Gallowwalker\" title=\"Una foto de Gallowwalker\" width=\"498\" height=\"332\" border=\"1\" \/><\/p>\n<p>Me despido por hoy con un par de anuncios. Primero el realizado por <strong>Variety<\/strong> y que pone voces a los personajes de <a href=\"http:\/\/www.imdb.com\/title\/tt0762125\/\" target=\"_blank\" title=\"Info de Planet 51\">Planet 51<\/a> (2009), un film <strong>3D<\/strong> producido por <a href=\"http:\/\/www.ilion.com\/\" target=\"_blank\" title=\"Web de Ilion Animation Studios\">Ilion Animation Studios<\/a> de <strong>Madrid<\/strong> y dirigido por <a href=\"http:\/\/www.imdb.com\/name\/nm0087278\/\" target=\"_blank\" title=\"Filmograf&iacute;a de Jorge Blanco\">Jorge Blanco<\/a> adem&aacute;s de ser escrito por <a href=\"http:\/\/www.imdb.com\/name\/nm0830294\/\" target=\"_blank\" title=\"Filmograf&iacute;a de Joe Stillman\">Joe Stillman<\/a>. La producci&oacute;n con base espa&ntilde;ola contar&aacute; al otro lado del charco con <a href=\"http:\/\/www.imdb.com\/name\/nm0425005\/\" target=\"_blank\" title=\"Filmograf&iacute;a de The Rock\">Dwayne &quot;The Rock&quot; Johnson<\/a>, <a href=\"http:\/\/www.imdb.com\/name\/nm0004754\/\" target=\"_blank\" title=\"Filmograf&iacute;a de Jessica Biel\">Jessica Biel<\/a>, <a href=\"http:\/\/www.imdb.com\/name\/nm0519043\/\" target=\"_blank\">Justin Long<\/a> y <a href=\"http:\/\/www.imdb.com\/name\/nm0005405\/\" target=\"_blank\" title=\"Filmograf&iacute;a de Seann William Scott\">Seann William Scott<\/a>. Segundo y final el <a href=\"http:\/\/www.hollywoodreporter.com\/hr\/content_display\/film\/news\/e3ib77125d96b22e860b14b889b10defb59\" target=\"_blank\">descubrimiento por parte de The Hollywood Reporter<\/a> de que <strong>Toshiba<\/strong> est&aacute; pensando seriamente en abandonar al <strong>HD-DVD<\/strong>&#8230; esto es el golpe definitivo.<\/p>\n<p><strong style=\"color:#FFFFFF; background-color:#FF0000;\">&nbsp;NOTA&nbsp;<\/strong> El resto de <a href=\"http:\/\/www.bloody-disgusting.com\/news\/11201\" target=\"_blank\">fotos que acompa&ntilde;an al post<\/a> son de <a href=\"http:\/\/www.imdb.com\/title\/tt0829176\/\" target=\"_blank\" title=\"Info de Gallowwalker\">Gallowwalker<\/a> (2007). Un <em>western<\/em> de terror protagonizado por <a href=\"http:\/\/www.imdb.com\/name\/nm0000648\/\" target=\"_blank\" title=\"Filmograf&iacute;a de Wesley Snipes\">Wesley Snipes<\/a> que pinta raro raro. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bienvenidos a un nuevo viernes plagadito de noticias para que uno no pueda descansar ni un m&iacute;sero minuto. Para comenzar bien avisar que desde la web Cineplex Entertainment nos llega un nuevo trailer de The Happening (2008) de M. Night Shyamalan. Completamente diferente al anterior visto, otra vez todo es un gran desconcierto ante la [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,8,12,9],"tags":[169,38,39,143,168,29],"class_list":["post-1337","post","type-post","status-publish","format-standard","hentry","category-cine-de-comics","category-cine-de-ciencia-ficcion","category-cine-de-fantasia","category-cine-de-terror","tag-dr-parnassus","tag-gi-joe","tag-justice-league-of-america","tag-the-happening","tag-the-imaginarium","tag-the-incredible-hulk"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Happening, &iquest;sustitutos para el Dr. Parnassus?, a Justice League of America le ha mirado un tuerto, primera imagen de G.I. Joe y otras noticias extra... - Uruloki :: Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Happening, &iquest;sustitutos para el Dr. Parnassus?, a Justice League of America le ha mirado un tuerto, primera imagen de G.I. Joe y otras noticias extra... - Uruloki :: Blog\" \/>\n<meta property=\"og:description\" content=\"Bienvenidos a un nuevo viernes plagadito de noticias para que uno no pueda descansar ni un m&iacute;sero minuto. Para comenzar bien avisar que desde la web Cineplex Entertainment nos llega un nuevo trailer de The Happening (2008) de M. Night Shyamalan. Completamente diferente al anterior visto, otra vez todo es un gran desconcierto ante la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra\" \/>\n<meta property=\"og:site_name\" content=\"Uruloki :: Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uruloki.org\" \/>\n<meta property=\"article:published_time\" content=\"2008-02-15T22:45:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2008-05-02T18:07:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uruloki.org\/felipeblog\/imagesflickr2\/20080215_quaidgijoe.jpg\" \/>\n<meta name=\"author\" content=\"Uruloki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uruloki\" \/>\n<meta name=\"twitter:site\" content=\"@uruloki\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Uruloki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra\"},\"author\":{\"name\":\"Uruloki\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"headline\":\"The Happening, &iquest;sustitutos para el Dr. Parnassus?, a Justice League of America le ha mirado un tuerto, primera imagen de G.I. Joe y otras noticias extra&#8230;\",\"datePublished\":\"2008-02-15T22:45:58+00:00\",\"dateModified\":\"2008-05-02T18:07:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra\"},\"wordCount\":839,\"commentCount\":10,\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagesflickr2\\\/20080215_quaidgijoe.jpg\",\"keywords\":[\"Dr. Parnassus\",\"G.I. Joe\",\"Justice League of America\",\"The Happening\",\"The Imaginarium\",\"The Incredible Hulk\"],\"articleSection\":[\"Cine de C\u00f3mics\",\"Cine de Ciencia Ficci\u00f3n\",\"Cine de Fantas\u00eda\",\"Cine de Terror\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra\",\"name\":\"The Happening, &iquest;sustitutos para el Dr. Parnassus?, a Justice League of America le ha mirado un tuerto, primera imagen de G.I. Joe y otras noticias extra... - Uruloki :: Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagesflickr2\\\/20080215_quaidgijoe.jpg\",\"datePublished\":\"2008-02-15T22:45:58+00:00\",\"dateModified\":\"2008-05-02T18:07:45+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra#primaryimage\",\"url\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagesflickr2\\\/20080215_quaidgijoe.jpg\",\"contentUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/imagesflickr2\\\/20080215_quaidgijoe.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Happening, &iquest;sustitutos para el Dr. Parnassus?, a Justice League of America le ha mirado un tuerto, primera imagen de G.I. Joe y otras noticias extra&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/\",\"name\":\"Uruloki :: Blog\",\"description\":\"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\",\"name\":\"Uruloki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"caption\":\"Uruloki\"},\"sameAs\":[\"https:\\\/\\\/uruloki.org\"],\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/author\\\/admin-2-2-2\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Happening, &iquest;sustitutos para el Dr. Parnassus?, a Justice League of America le ha mirado un tuerto, primera imagen de G.I. Joe y otras noticias extra... - Uruloki :: Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra","og_locale":"es_ES","og_type":"article","og_title":"The Happening, &iquest;sustitutos para el Dr. Parnassus?, a Justice League of America le ha mirado un tuerto, primera imagen de G.I. Joe y otras noticias extra... - Uruloki :: Blog","og_description":"Bienvenidos a un nuevo viernes plagadito de noticias para que uno no pueda descansar ni un m&iacute;sero minuto. Para comenzar bien avisar que desde la web Cineplex Entertainment nos llega un nuevo trailer de The Happening (2008) de M. Night Shyamalan. Completamente diferente al anterior visto, otra vez todo es un gran desconcierto ante la [&hellip;]","og_url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra","og_site_name":"Uruloki :: Blog","article_publisher":"https:\/\/www.facebook.com\/uruloki.org","article_published_time":"2008-02-15T22:45:58+00:00","article_modified_time":"2008-05-02T18:07:45+00:00","og_image":[{"url":"https:\/\/uruloki.org\/felipeblog\/imagesflickr2\/20080215_quaidgijoe.jpg","type":"","width":"","height":""}],"author":"Uruloki","twitter_card":"summary_large_image","twitter_creator":"@uruloki","twitter_site":"@uruloki","twitter_misc":{"Escrito por":"Uruloki","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra#article","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra"},"author":{"name":"Uruloki","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"headline":"The Happening, &iquest;sustitutos para el Dr. Parnassus?, a Justice League of America le ha mirado un tuerto, primera imagen de G.I. Joe y otras noticias extra&#8230;","datePublished":"2008-02-15T22:45:58+00:00","dateModified":"2008-05-02T18:07:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra"},"wordCount":839,"commentCount":10,"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/imagesflickr2\/20080215_quaidgijoe.jpg","keywords":["Dr. Parnassus","G.I. Joe","Justice League of America","The Happening","The Imaginarium","The Incredible Hulk"],"articleSection":["Cine de C\u00f3mics","Cine de Ciencia Ficci\u00f3n","Cine de Fantas\u00eda","Cine de Terror"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra","url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra","name":"The Happening, &iquest;sustitutos para el Dr. Parnassus?, a Justice League of America le ha mirado un tuerto, primera imagen de G.I. Joe y otras noticias extra... - Uruloki :: Blog","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra#primaryimage"},"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/imagesflickr2\/20080215_quaidgijoe.jpg","datePublished":"2008-02-15T22:45:58+00:00","dateModified":"2008-05-02T18:07:45+00:00","author":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"breadcrumb":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra#primaryimage","url":"https:\/\/uruloki.org\/felipeblog\/imagesflickr2\/20080215_quaidgijoe.jpg","contentUrl":"https:\/\/uruloki.org\/felipeblog\/imagesflickr2\/20080215_quaidgijoe.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/the-happening-sustitutos-para-el-dr-parnassus-a-justice-league-of-america-le-ha-mirado-un-tuerto-primera-imagen-de-gi-joe-y-otras-noticias-extra#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uruloki.org\/felipeblog"},{"@type":"ListItem","position":2,"name":"The Happening, &iquest;sustitutos para el Dr. Parnassus?, a Justice League of America le ha mirado un tuerto, primera imagen de G.I. Joe y otras noticias extra&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.uruloki.org\/felipeblog\/#website","url":"https:\/\/www.uruloki.org\/felipeblog\/","name":"Uruloki :: Blog","description":"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uruloki.org\/felipeblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3","name":"Uruloki","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","caption":"Uruloki"},"sameAs":["https:\/\/uruloki.org"],"url":"https:\/\/www.uruloki.org\/felipeblog\/author\/admin-2-2-2"}]}},"_links":{"self":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/1337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/comments?post=1337"}],"version-history":[{"count":0,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/1337\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/media?parent=1337"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/categories?post=1337"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/tags?post=1337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}