{"id":12995,"date":"2014-06-24T13:28:01","date_gmt":"2014-06-24T11:28:01","guid":{"rendered":"https:\/\/uruloki.org\/felipeblog\/?p=12995"},"modified":"2014-06-24T13:28:01","modified_gmt":"2014-06-24T11:28:01","slug":"edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c","status":"publish","type":"post","link":"https:\/\/www.uruloki.org\/felipeblog\/cine\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c","title":{"rendered":"Edgar Ram&iacute;rez comienza a hablar sobre Doctor Strange y Jared Leto puede que tambi&eacute;n, un nuevo cartel de Sin City: A Dame to Kill For, &iquest;el problema Harrison Ford puede suponer un cambio de fecha de estreno de Star Wars: Episode VII? y las posibilidades sobre Rambo V  son otra vez primera plana&#8230;"},"content":{"rendered":"<\/p>\n<p>Vamos con otras noticias antes de dedicar el tiempo a cosas del trabajo que cuando estas se acumulan hay que dedicarles tiempo extra. Arranco con un par de rumores <strong>Doctor Strange<\/strong> (2016). Resulta que <strong>Edgar Ram&iacute;rez <\/strong> ha decidido desvelar a la gente que IGN que <a href=\"http:\/\/www.ign.com\/articles\/2014\/06\/23\/edgar-ramirez-is-talking-with-doctor-strange-team-about-a-role\" target=\"_blank\">ha estado hablando con su amigo <strong>Scott Derrickson<\/strong> sobre la aventura <strong>Stephen Strange<\/strong><\/a> en cines que <strong>Marvel Studios<\/strong> planea para dentro de dos a&ntilde;os. <strong>Ram&iacute;rez<\/strong>, uno de los protagonistas de <strong>L&iacute;branos del mal<\/strong> (<em>Deliver Us from Evil<\/em>, 2014) de <strong>Derrickson<\/strong>, comenta que se ha sentado con el director para hablar de papeles y qui&eacute;n sabe si algo m&aacute;s. F&iacute;sicamente el actor venezolano podr&iacute;a pasar bien por el <strong>Doctor Extra&ntilde;o<\/strong> pero incluso por alguno de sus habituales villanos como, como bien apuntan en IGN, el <strong>Bar&oacute;n Mordo<\/strong>. Ojo, esto no quiere decir nada, pero nunca se sabe, <strong>Ram&iacute;rez<\/strong> poco a poco opta a mejores papeles en Hollywood, de hecho son&oacute; para ser <strong>Khan<\/strong> en <strong>Star Trek: el la oscuridad<\/strong> (<em>Star Trek Into Darkness<\/em>, 2013) antes de que <strong>Benedict Cumberbatch<\/strong> entrara en liza. Relacionado con este mismo proyecto, en NikkiFinke.com comentan que <a href=\"http:\/\/nikkifinke.com\/jared-leto-brilliance\/\" target=\"_blank\"><strong>Jared Leto<\/strong> ha dicho no a <strong>Legendary<\/strong> y a su <strong>Brilliance<\/strong> (2015)<\/a>&#8230; &iquest;significar&aacute; esto algo?<\/p>\n<p class=\"centrado\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2014-1\/20140623-sincity.jpg\" alt=\"El nuevo cartel de Sin City: A Dame to Kill For v&iacute;a Empire\" width=\"625\" height=\"469\" \/><br \/><em>El <a href=\"http:\/\/www.empireonline.com\/news\/story.asp?NID=41361\" target=\"_blank\">nuevo cartel de Sin City: A Dame to Kill For<\/a> v&iacute;a Empire<\/em> <\/p>\n<p>Tenemos tambi&eacute;n un <a href=\"http:\/\/io9.com\/harrison-fords-injury-may-have-completely-screwed-up-ep-1594838394\" target=\"_blank\">resurgir de rumores sobre el tropiezo \/ rotura de pierna de <strong>Harrison Ford<\/strong> en el set de rodaje de <strong>Star Wars: Episode VII<\/strong> (2015)<\/a> de <strong>J.J. Abrams<\/strong>. Cuentan, esto debe ser cogido  con pinzas, que la rotura de Ford puede ser un problema mucho mas grave de lo esperado. El tema es que la fecha de estreno del nuevo episodio <strong>Star Wars<\/strong> podr&iacute;a estar ahora mismo en el aire porque dado el vital protagonismo de <strong>Han Solo<\/strong> en este film la incapacidad actual de <strong>Ford<\/strong> y las 8 semanas de par&oacute;n pueden alterar demasiado las cosas. Se habla incluso de retraso del rodaje, mayo del 2016, cosa que <strong>Disney<\/strong> no quiere ni plantearse&#8230; esas fechas estar&aacute;n sobrecargadas con productos <strong>Marvel<\/strong> y <strong>DC<\/strong>. En fin, se habla de reuni&oacute;n de emergencia, se habla de posible reescritura de gui&oacute;n, etc. Es un rumor pero huele a chamusquina. 8 semanas son 8 semanas y por mucho que ajustes el rodaje, que adelantes ahora otras cosas, etc., si la presencia de <strong>Harrison Ford<\/strong> es vital tienes un problema. Aunque bueno, la magia del cine es infinita.<\/p>\n<p>Y <a href=\"http:\/\/www.splendidmedien.com\/de\/page\/splendid-film-stellt-neue-filmeinkaeufe-vor-1723\" target=\"_blank\">m&aacute;s rumores, esta vez sobre <strong>Rambo V<\/strong> (&iquest;?)<\/a> que regresa a la palestra cuando todos pens&aacute;bamos que estaba bien muerta. El portal alem&aacute;n SplendidMedien AG, dicen que los sitios USA que 100% fiable, publica en uno de sus &uacute;ltimos art&iacute;culos el siguiente texto&#8230;<\/p>\n<blockquote><p>Con &quot;Rambo V&quot; Sylvester Stallone regresa a uno de sus papeles cruciales. Esta vez para hacer frente a un c&aacute;rtel de la droga mexicano. Stallone, que es el responsable del gui&oacute;n, describe el nuevo Rambo como su versi&oacute;n de No es pa&iacute;s para viejos (No Country for Old Men). El productor ser&aacute; como en la &uacute;ltima incursi&oacute;n del militar pasado de vueltas el bueno de Avi Lerner.<\/p><\/blockquote>\n<p>Pues en estas estamos&#8230; &iquest;<strong>Rambo V<\/strong>?, &iquest;os atrae la idea?, &iquest;s&iacute; o no?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vamos con otras noticias antes de dedicar el tiempo a cosas del trabajo que cuando estas se acumulan hay que dedicarles tiempo extra. Arranco con un par de rumores Doctor Strange (2016). Resulta que Edgar Ram&iacute;rez ha decidido desvelar a la gente que IGN que ha estado hablando con su amigo Scott Derrickson sobre la [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6,10,8,15],"tags":[668,279,1809,2358],"class_list":["post-12995","post","type-post","status-publish","format-standard","hentry","category-cine","category-cine-de-comics","category-cine-de-ciencia-ficcion","category-star-wars","tag-doctor-strange","tag-rambo-v","tag-sin-city-a-dame-to-kill-for","tag-star-wars-episode-vii"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Doctor Strange se mueve al paso de Edgar Ram\u00edrez y Jared Leto?<\/title>\n<meta name=\"description\" content=\"Vamos con otras noticias antes de dedicar el tiempo a cosas del trabajo que cuando estas se acumulan hay que dedicarles tiempo extra. Arranco con un par de rumores Doctor Strange (2016)\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uruloki.org\/felipeblog\/cine\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Doctor Strange se mueve al paso de Edgar Ram\u00edrez y Jared Leto?\" \/>\n<meta property=\"og:description\" content=\"Vamos con otras noticias antes de dedicar el tiempo a cosas del trabajo que cuando estas se acumulan hay que dedicarles tiempo extra. Arranco con un par de rumores Doctor Strange (2016)\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uruloki.org\/felipeblog\/cine\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c\" \/>\n<meta property=\"og:site_name\" content=\"Uruloki :: Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uruloki.org\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-24T11:28:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uruloki.org\/felipeblog\/images2014-1\/20140623-sincity.jpg\" \/>\n<meta name=\"author\" content=\"Uruloki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uruloki\" \/>\n<meta name=\"twitter:site\" content=\"@uruloki\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Uruloki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c\"},\"author\":{\"name\":\"Uruloki\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"headline\":\"Edgar Ram&iacute;rez comienza a hablar sobre Doctor Strange y Jared Leto puede que tambi&eacute;n, un nuevo cartel de Sin City: A Dame to Kill For, &iquest;el problema Harrison Ford puede suponer un cambio de fecha de estreno de Star Wars: Episode VII? y las posibilidades sobre Rambo V son otra vez primera plana&#8230;\",\"datePublished\":\"2014-06-24T11:28:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c\"},\"wordCount\":637,\"commentCount\":5,\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2014-1\\\/20140623-sincity.jpg\",\"keywords\":[\"Doctor Strange\",\"Rambo V\",\"Sin City: A Dame to Kill For\",\"Star Wars: Episode VII\"],\"articleSection\":[\"Cine\",\"Cine de C\u00f3mics\",\"Cine de Ciencia Ficci\u00f3n\",\"Star Wars\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c\",\"name\":\"Doctor Strange se mueve al paso de Edgar Ram\u00edrez y Jared Leto?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2014-1\\\/20140623-sincity.jpg\",\"datePublished\":\"2014-06-24T11:28:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"description\":\"Vamos con otras noticias antes de dedicar el tiempo a cosas del trabajo que cuando estas se acumulan hay que dedicarles tiempo extra. Arranco con un par de rumores Doctor Strange (2016)\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c#primaryimage\",\"url\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2014-1\\\/20140623-sincity.jpg\",\"contentUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2014-1\\\/20140623-sincity.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine\\\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Edgar Ram&iacute;rez comienza a hablar sobre Doctor Strange y Jared Leto puede que tambi&eacute;n, un nuevo cartel de Sin City: A Dame to Kill For, &iquest;el problema Harrison Ford puede suponer un cambio de fecha de estreno de Star Wars: Episode VII? y las posibilidades sobre Rambo V son otra vez primera plana&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/\",\"name\":\"Uruloki :: Blog\",\"description\":\"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\",\"name\":\"Uruloki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"caption\":\"Uruloki\"},\"sameAs\":[\"https:\\\/\\\/uruloki.org\"],\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/author\\\/admin-2-2-2\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Doctor Strange se mueve al paso de Edgar Ram\u00edrez y Jared Leto?","description":"Vamos con otras noticias antes de dedicar el tiempo a cosas del trabajo que cuando estas se acumulan hay que dedicarles tiempo extra. Arranco con un par de rumores Doctor Strange (2016)","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uruloki.org\/felipeblog\/cine\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c","og_locale":"es_ES","og_type":"article","og_title":"Doctor Strange se mueve al paso de Edgar Ram\u00edrez y Jared Leto?","og_description":"Vamos con otras noticias antes de dedicar el tiempo a cosas del trabajo que cuando estas se acumulan hay que dedicarles tiempo extra. Arranco con un par de rumores Doctor Strange (2016)","og_url":"https:\/\/www.uruloki.org\/felipeblog\/cine\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c","og_site_name":"Uruloki :: Blog","article_publisher":"https:\/\/www.facebook.com\/uruloki.org","article_published_time":"2014-06-24T11:28:01+00:00","og_image":[{"url":"https:\/\/uruloki.org\/felipeblog\/images2014-1\/20140623-sincity.jpg","type":"","width":"","height":""}],"author":"Uruloki","twitter_card":"summary_large_image","twitter_creator":"@uruloki","twitter_site":"@uruloki","twitter_misc":{"Escrito por":"Uruloki","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c#article","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c"},"author":{"name":"Uruloki","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"headline":"Edgar Ram&iacute;rez comienza a hablar sobre Doctor Strange y Jared Leto puede que tambi&eacute;n, un nuevo cartel de Sin City: A Dame to Kill For, &iquest;el problema Harrison Ford puede suponer un cambio de fecha de estreno de Star Wars: Episode VII? y las posibilidades sobre Rambo V son otra vez primera plana&#8230;","datePublished":"2014-06-24T11:28:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c"},"wordCount":637,"commentCount":5,"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/images2014-1\/20140623-sincity.jpg","keywords":["Doctor Strange","Rambo V","Sin City: A Dame to Kill For","Star Wars: Episode VII"],"articleSection":["Cine","Cine de C\u00f3mics","Cine de Ciencia Ficci\u00f3n","Star Wars"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uruloki.org\/felipeblog\/cine\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c","url":"https:\/\/www.uruloki.org\/felipeblog\/cine\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c","name":"Doctor Strange se mueve al paso de Edgar Ram\u00edrez y Jared Leto?","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c#primaryimage"},"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/images2014-1\/20140623-sincity.jpg","datePublished":"2014-06-24T11:28:01+00:00","author":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"description":"Vamos con otras noticias antes de dedicar el tiempo a cosas del trabajo que cuando estas se acumulan hay que dedicarles tiempo extra. Arranco con un par de rumores Doctor Strange (2016)","breadcrumb":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uruloki.org\/felipeblog\/cine\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c#primaryimage","url":"https:\/\/uruloki.org\/felipeblog\/images2014-1\/20140623-sincity.jpg","contentUrl":"https:\/\/uruloki.org\/felipeblog\/images2014-1\/20140623-sincity.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine\/edgar-ramrez-comienza-hablar-sobre-doctor-strange-y-jared-leto-puede-que-tambin-un-nuevo-cartel-de-sin-city-dame-kill-el-problema-harrison-ford-puede-suponer-un-c#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uruloki.org\/felipeblog"},{"@type":"ListItem","position":2,"name":"Edgar Ram&iacute;rez comienza a hablar sobre Doctor Strange y Jared Leto puede que tambi&eacute;n, un nuevo cartel de Sin City: A Dame to Kill For, &iquest;el problema Harrison Ford puede suponer un cambio de fecha de estreno de Star Wars: Episode VII? y las posibilidades sobre Rambo V son otra vez primera plana&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.uruloki.org\/felipeblog\/#website","url":"https:\/\/www.uruloki.org\/felipeblog\/","name":"Uruloki :: Blog","description":"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uruloki.org\/felipeblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3","name":"Uruloki","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","caption":"Uruloki"},"sameAs":["https:\/\/uruloki.org"],"url":"https:\/\/www.uruloki.org\/felipeblog\/author\/admin-2-2-2"}]}},"_links":{"self":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/12995","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/comments?post=12995"}],"version-history":[{"count":1,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/12995\/revisions"}],"predecessor-version":[{"id":12996,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/12995\/revisions\/12996"}],"wp:attachment":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/media?parent=12995"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/categories?post=12995"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/tags?post=12995"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}