{"id":12057,"date":"2014-01-23T22:35:11","date_gmt":"2014-01-23T21:35:11","guid":{"rendered":"https:\/\/uruloki.org\/felipeblog\/?p=12057"},"modified":"2014-01-23T22:35:11","modified_gmt":"2014-01-23T21:35:11","slug":"brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado","status":"publish","type":"post","link":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado","title":{"rendered":"Brian K. Vaughn augura la cancelaci&oacute;n de Y: The Last Man y Runaways, el primer teaser de &quot;The Strain&quot; de Guillermo del Toro y Carlton Cuse, Gal Gadot dice haber firmado por triplicado para ser Wonder Woman, Garret Hedlund podr&iacute;a ser el Capit&aacute;n Garfio en la versi&oacute;n siniestra de Peter Pan, parece ser que Daniel Espinosa es el primer candidato para dirigir Assassin&#8217;s Creed y un par de carteles de 300: el origen de un imperio y Los Juegos del Hambre: Sinsajo&#8230;"},"content":{"rendered":"<p>Con <a href=\"https:\/\/uruloki.org\/OscarsWeb2014\/\">la <strong>Quiniela de los Oscar 2014<\/strong> ya en marcha<\/a>, volver&eacute; ahora con otro ataque masivo para ver si tenemos suerte en esto de los regalos, y <a href=\"https:\/\/uruloki.org\/felipeblog\/cine-de-terror\/llega-el-primer-trailer-de-oculus-canguelus-maximus\">el primer mol&oacute;n trailer de <strong>Oculus<\/strong><\/a> hay que comentar las noticias de la jornada, una en la que lo medi&aacute;tico del f&uacute;tbol colapsa el todo.<\/p>\n<p>Vamos a comenzar con una triste noticia. <a href=\"http:\/\/www.comicbookresources.com\/?page=article&amp;id=50441\" target=\"_blank\"><strong>Brian K. Vaughan<\/strong> ha concedido una entrevista a la gente de Comic Book Resources<\/a> y de ella se han sacado dos movimientos que, la verdad, no es que nos pillen demasiado desprevenidos. El primero de ellos afecta a esa prometida adaptaci&oacute;n de la fant&aacute;stica obra de <strong>Vaughan<\/strong> y <strong>Pia Guerra &quot;Y: el &uacute;ltimo nombre&quot;<\/strong>. El proyecto, en manos de <strong>New Line Cinema<\/strong> desde mediados de la pasada d&eacute;cada y con <a href=\"https:\/\/uruloki.org\/felipeblog\/cine-de-cmics\/captulo-segundo-tenemos-para-todos-y-the-last-man-wolverine-magneto-spawn-2-iron-man-o-jonah-hex\">el equipo formado por <strong>D.J. Caruso<\/strong>, director, y <strong>Shia LaBeouf<\/strong>, actor<\/a>, como principales candidatos para llevar adelante el plan, fue perdiendo fuerza y presencia conforme pasaba el tiempo y los nombres asociados se iban diluyendo. La idea de <strong>Caruso<\/strong> era hacer una trilog&iacute;a y <a href=\"https:\/\/uruloki.org\/felipeblog\/cine-de-ciencia-ficcin\/hoffman-dice-no-al-pingino-la-fox-prepara-nuevos-spin-offs-de-x-men-un-film-de-deadpool-y-el-renacimiento-de-daredevil-devastator-estar-en-transformers-2-catherine-zeta-jones\">otras como  <strong>Alicia Keys<\/strong> surgieron con el paso de los a&ntilde;os para encarnar, en este caso, al <strong>Agente 355<\/strong><\/a>. Tras el primer gui&oacute;n del propio <strong>Vaughn<\/strong> se pas&oacute; a uno nuevo de <strong>Carl Ellsworth<\/strong> pero aunque se hizo lo posible  tampoco fue adelante la aventura. <a href=\"https:\/\/uruloki.org\/felipeblog\/cine-de-ciencia-ficcin\/bryan-singer-no-dirigir-x-men-first-class-otro-trailer-de-airbender-el-ltimo-guerrero-documento-de-predators-y-rumores-del-nivel-de-angelina-jolie-protagonista-de-malificen\">La salida de <strong>LaBeouf<\/strong> y <strong>Caruso<\/strong> deriv&oacute; en <strong>Louis Letterrier<\/strong><\/a>, que tampoco cerr&oacute; nada, y hasta <a href=\"https:\/\/uruloki.org\/felipeblog\/cine-de-ciencia-ficcin\/parece-ser-que-new-line-cinema-tiene-prisa-por-llevar-al-cine-y-el-ltimo-hombre-la-compaa-de-fx-digital-domain-fundada-por-james-cameron-scott-ross-y-stan-winsto\">un gui&oacute;n de <strong>Matthew Federman<\/strong> y <strong>Stephen Scaia<\/strong><\/a> fue solicitado en 2012 y vendido como el ahora s&iacute;. <strong>New Line<\/strong> fue incapaz de dar luz verde otra vez a la adaptaci&oacute;n. <a href=\"https:\/\/uruloki.org\/felipeblog\/cine-de-ciencia-ficcin\/christopher-nolan-y-jonathan-nolan-apuestan-por-interstellar-viajes-en-el-tiempo-dimensiones-alternativas-robopocalypse-de-steven-spielberg-se-queda-bloqueada-sine-die-aunque-el-director-asegura\"><strong>Dan Trachtenberg<\/strong> fue el &uacute;ltimo en sonar para la aventura<\/a>, pero desde que en enero fue anunciado ajo y agua. Ahora el autor advierte que a finales de a&ntilde;o los derechos sobre la obra revierte de nuevo en sus autores y <strong>New Line<\/strong> se quedar&aacute; sin <strong>Y: The Last Man<\/strong> (&iquest;?). El otro proyecto que Vaughan dar por cancelado es  <strong>Runaways<\/strong> (&iquest;?)&#8230; otro que en manos de <strong>Marvel<\/strong> ha dado muchas vueltas.<\/p>\n<p class=\"centrado\"><a href=\"https:\/\/uruloki.org\/felipeblog\/images2014-1\/20140123-300rise-otro-xl.jpg\" target=\"_blank\" onclick=\"return false\" rel=\"shadowbox\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2014-1\/20140123-300rise-otro.jpg\" width=\"625\" height=\"287\" border=\"0\" \/><\/a><br \/>\n<em>Y si, <a href=\"http:\/\/www.impawards.com\/updates\/20140122b.html\" target=\"_blank\">un cartel m&aacute;s de 300: el origen de un imperio<\/a>, mismo patr&oacute;n que el resto<\/em><\/p>\n<p>M&aacute;s cosillas. Se ve que <strong>Gal Gadot<\/strong>, en la l&iacute;nea excesiva de <strong>Marvel Studios<\/strong>, ha firmado con <strong>Warner Bros.<\/strong> <a href=\"http:\/\/batman-news.com\/2014\/01\/22\/gal-gadot-signed-3-movie-deal-wonder-woman-video\/\" target=\"_blank\">un contrato que la vincula para ser <strong>Wonder Woman<\/strong> la friolera de tres pel&iacute;culas<\/a>&#8230; que en el fondo no es nada ni comparable con las 9 de <strong>Samuel L. Jackson<\/strong> para ser <strong>Nick Fury<\/strong>. La noticia \/ rumor aparecida en Batman-news.com ha sido <a href=\"http:\/\/variety.com\/2014\/film\/news\/wonder-woman-gal-gadot-signs-three-picture-deal-with-warner-bros-1201067961\/\" target=\"_blank\">confirmada poco despu&eacute;s<\/a> por Variety. Lo curioso del dato, m&aacute;s que eso de rodar tres pelis, es que el programa israel&iacute; <strong>&quot;Good Evening with Gai Pines&quot;<\/strong> comenta que la <strong>Gadot<\/strong> cobrar&aacute; 300.000$ por pel&iacute;cula, una cantidad un pel&iacute;n p&iacute;rrica dada la dimensi&oacute;n de acuerdo. En fin, hasta el 6 de mayo del 2016 nos toca desear saber m&aacute;s sobre <strong>Batman vs. Superman<\/strong> (2016) y alguno de los siguientes movimientos futuros. Y hablando de contratos, <a href=\"http:\/\/www.hollywoodreporter.com\/heat-vision\/garrett-hedlund-offered-captain-hook-673400\" target=\"_blank\">a <strong>Garret Hedlund<\/strong> le han ofertado ser el <strong>Capit&aacute;n Garfio<\/strong><\/a> en <strong>Pan<\/strong> (2015) de <strong>Joe Wright<\/strong>. Esta versi&oacute;n m&aacute;s siniestra de la obra de <strong>J.M. Barrie<\/strong> le da una vuelta a la historia uniendo a <strong>Peter Pan<\/strong> y <strong>Garfio<\/strong> en su lucha contra <strong>Barbanegra<\/strong>, del que dicen que puede ser <strong>Hugh Jackman<\/strong>,&#8230; pero la traici&oacute;n ser&aacute; el detonante final.<\/p>\n<div class=\"video\"><iframe loading=\"lazy\" width=\"625\" height=\"352\" src=\"\/\/www.youtube.com\/embed\/bvnsZcq3Nto\"><\/iframe><\/div>\n<p>Vamos cerrando el chiringuito con otros detalles. En Twitch Film aparece el nombre de <a href=\"http:\/\/twitchfilm.com\/2014\/01\/breaking-daniel-espinosa-for-assassins-creed.html\" target=\"_blank\"><strong>Daniel Espinosa<\/strong> como el tanteado por <strong>20th Century Fox<\/strong> para hacerse cargo de la direcci&oacute;n de <strong>Assassin&#8217;s Creed<\/strong> (&iquest;?)<\/a>. Este director de origen sueco ha ido cumpliendo con creces poco a poco con films como <strong>Dinero f&aacute;cil<\/strong> (<em>Snabba Cash<\/em>, 2010), donde algunos descubrimos a <strong>Joel Kinnaman<\/strong>, y luego se pas&oacute; por <strong>Hollywood<\/strong> para hacer <strong>El invitado<\/strong> (<em>Safe House<\/em>, 2012).<\/p>\n<p class=\"centrado\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2014-1\/20140123-mockingjay.jpg\" alt=\"El primer cartel de Los Juegos del Hambre: Sinsajo - Parte 1... as always\" width=\"550\" height=\"849\" \/><br \/><em>El <a href=\"https:\/\/www.facebook.com\/photo.php?fbid=840789629271023&amp;set=a.288998967783428.89832.159746560708670\" target=\"_blank\">primer cartel de Los Juegos del Hambre: Sinsajo &#8211; Parte 1<\/a>&#8230; as always<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con la Quiniela de los Oscar 2014 ya en marcha, volver&eacute; ahora con otro ataque masivo para ver si tenemos suerte en esto de los regalos, y el primer mol&oacute;n trailer de Oculus hay que comentar las noticias de la jornada, una en la que lo medi&aacute;tico del f&uacute;tbol colapsa el todo. Vamos a comenzar [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10,8,12,9],"tags":[2271,1727,2778,39,2192,1568,407,2603,868,345,87],"class_list":["post-12057","post","type-post","status-publish","format-standard","hentry","category-cine-de-comics","category-cine-de-ciencia-ficcion","category-cine-de-fantasia","category-cine-de-terror","tag-300-rise-of-an-empire","tag-assassins-creed","tag-batman-vs-superman","tag-justice-league-of-america","tag-mockingjay","tag-pan","tag-runaways","tag-the-hunger-games-mockingjay","tag-the-strain","tag-wonder-woman","tag-y-the-last-man"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Brian K. Vaughn augura la cancelaci\u00f3n de Y: The Last Man y Runaways<\/title>\n<meta name=\"description\" content=\"Vamos a comenzar con una triste noticia. Brian K. Vaughan ha concedido una entrevista a la gente de Comic Book Resources y de ella se han sacado dos movimientos que, la verdad, no es que nos pillen demasiado desprevenidos. El primero de ellos afecta a esa prometida adaptaci\u00f3n de la fant\u00e1stica obra de Vaughan y Pia Guerra &quot;Y: The Last Man&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brian K. Vaughn augura la cancelaci\u00f3n de Y: The Last Man y Runaways\" \/>\n<meta property=\"og:description\" content=\"Vamos a comenzar con una triste noticia. Brian K. Vaughan ha concedido una entrevista a la gente de Comic Book Resources y de ella se han sacado dos movimientos que, la verdad, no es que nos pillen demasiado desprevenidos. El primero de ellos afecta a esa prometida adaptaci\u00f3n de la fant\u00e1stica obra de Vaughan y Pia Guerra &quot;Y: The Last Man&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado\" \/>\n<meta property=\"og:site_name\" content=\"Uruloki :: Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uruloki.org\" \/>\n<meta property=\"article:published_time\" content=\"2014-01-23T21:35:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uruloki.org\/felipeblog\/images2014-1\/20140123-300rise-otro.jpg\" \/>\n<meta name=\"author\" content=\"Uruloki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uruloki\" \/>\n<meta name=\"twitter:site\" content=\"@uruloki\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Uruloki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado\"},\"author\":{\"name\":\"Uruloki\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"headline\":\"Brian K. Vaughn augura la cancelaci&oacute;n de Y: The Last Man y Runaways, el primer teaser de &quot;The Strain&quot; de Guillermo del Toro y Carlton Cuse, Gal Gadot dice haber firmado por triplicado para ser Wonder Woman, Garret Hedlund podr&iacute;a ser el Capit&aacute;n Garfio en la versi&oacute;n siniestra de Peter Pan, parece ser que Daniel Espinosa es el primer candidato para dirigir Assassin&#8217;s Creed y un par de carteles de 300: el origen de un imperio y Los Juegos del Hambre: Sinsajo&#8230;\",\"datePublished\":\"2014-01-23T21:35:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado\"},\"wordCount\":794,\"commentCount\":2,\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2014-1\\\/20140123-300rise-otro.jpg\",\"keywords\":[\"300: Rise of an Empire\",\"Assassin's Creed\",\"Batman vs. Superman\",\"Justice League of America\",\"Mockingjay\",\"Pan\",\"Runaways\",\"The Hunger Games: Mockingjay\",\"The Strain\",\"Wonder Woman\",\"Y: The Last Man\"],\"articleSection\":[\"Cine de C\u00f3mics\",\"Cine de Ciencia Ficci\u00f3n\",\"Cine de Fantas\u00eda\",\"Cine de Terror\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado\",\"name\":\"Brian K. Vaughn augura la cancelaci\u00f3n de Y: The Last Man y Runaways\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2014-1\\\/20140123-300rise-otro.jpg\",\"datePublished\":\"2014-01-23T21:35:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"description\":\"Vamos a comenzar con una triste noticia. Brian K. Vaughan ha concedido una entrevista a la gente de Comic Book Resources y de ella se han sacado dos movimientos que, la verdad, no es que nos pillen demasiado desprevenidos. El primero de ellos afecta a esa prometida adaptaci\u00f3n de la fant\u00e1stica obra de Vaughan y Pia Guerra \\\"Y: The Last Man\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado#primaryimage\",\"url\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2014-1\\\/20140123-300rise-otro.jpg\",\"contentUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2014-1\\\/20140123-300rise-otro.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brian K. Vaughn augura la cancelaci&oacute;n de Y: The Last Man y Runaways, el primer teaser de &quot;The Strain&quot; de Guillermo del Toro y Carlton Cuse, Gal Gadot dice haber firmado por triplicado para ser Wonder Woman, Garret Hedlund podr&iacute;a ser el Capit&aacute;n Garfio en la versi&oacute;n siniestra de Peter Pan, parece ser que Daniel Espinosa es el primer candidato para dirigir Assassin&#8217;s Creed y un par de carteles de 300: el origen de un imperio y Los Juegos del Hambre: Sinsajo&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/\",\"name\":\"Uruloki :: Blog\",\"description\":\"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\",\"name\":\"Uruloki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"caption\":\"Uruloki\"},\"sameAs\":[\"https:\\\/\\\/uruloki.org\"],\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/author\\\/admin-2-2-2\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brian K. Vaughn augura la cancelaci\u00f3n de Y: The Last Man y Runaways","description":"Vamos a comenzar con una triste noticia. Brian K. Vaughan ha concedido una entrevista a la gente de Comic Book Resources y de ella se han sacado dos movimientos que, la verdad, no es que nos pillen demasiado desprevenidos. El primero de ellos afecta a esa prometida adaptaci\u00f3n de la fant\u00e1stica obra de Vaughan y Pia Guerra \"Y: The Last Man\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado","og_locale":"es_ES","og_type":"article","og_title":"Brian K. Vaughn augura la cancelaci\u00f3n de Y: The Last Man y Runaways","og_description":"Vamos a comenzar con una triste noticia. Brian K. Vaughan ha concedido una entrevista a la gente de Comic Book Resources y de ella se han sacado dos movimientos que, la verdad, no es que nos pillen demasiado desprevenidos. El primero de ellos afecta a esa prometida adaptaci\u00f3n de la fant\u00e1stica obra de Vaughan y Pia Guerra \"Y: The Last Man\".","og_url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado","og_site_name":"Uruloki :: Blog","article_publisher":"https:\/\/www.facebook.com\/uruloki.org","article_published_time":"2014-01-23T21:35:11+00:00","og_image":[{"url":"https:\/\/uruloki.org\/felipeblog\/images2014-1\/20140123-300rise-otro.jpg","type":"","width":"","height":""}],"author":"Uruloki","twitter_card":"summary_large_image","twitter_creator":"@uruloki","twitter_site":"@uruloki","twitter_misc":{"Escrito por":"Uruloki","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado#article","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado"},"author":{"name":"Uruloki","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"headline":"Brian K. Vaughn augura la cancelaci&oacute;n de Y: The Last Man y Runaways, el primer teaser de &quot;The Strain&quot; de Guillermo del Toro y Carlton Cuse, Gal Gadot dice haber firmado por triplicado para ser Wonder Woman, Garret Hedlund podr&iacute;a ser el Capit&aacute;n Garfio en la versi&oacute;n siniestra de Peter Pan, parece ser que Daniel Espinosa es el primer candidato para dirigir Assassin&#8217;s Creed y un par de carteles de 300: el origen de un imperio y Los Juegos del Hambre: Sinsajo&#8230;","datePublished":"2014-01-23T21:35:11+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado"},"wordCount":794,"commentCount":2,"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/images2014-1\/20140123-300rise-otro.jpg","keywords":["300: Rise of an Empire","Assassin's Creed","Batman vs. Superman","Justice League of America","Mockingjay","Pan","Runaways","The Hunger Games: Mockingjay","The Strain","Wonder Woman","Y: The Last Man"],"articleSection":["Cine de C\u00f3mics","Cine de Ciencia Ficci\u00f3n","Cine de Fantas\u00eda","Cine de Terror"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado","url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado","name":"Brian K. Vaughn augura la cancelaci\u00f3n de Y: The Last Man y Runaways","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado#primaryimage"},"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/images2014-1\/20140123-300rise-otro.jpg","datePublished":"2014-01-23T21:35:11+00:00","author":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"description":"Vamos a comenzar con una triste noticia. Brian K. Vaughan ha concedido una entrevista a la gente de Comic Book Resources y de ella se han sacado dos movimientos que, la verdad, no es que nos pillen demasiado desprevenidos. El primero de ellos afecta a esa prometida adaptaci\u00f3n de la fant\u00e1stica obra de Vaughan y Pia Guerra \"Y: The Last Man\".","breadcrumb":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado#primaryimage","url":"https:\/\/uruloki.org\/felipeblog\/images2014-1\/20140123-300rise-otro.jpg","contentUrl":"https:\/\/uruloki.org\/felipeblog\/images2014-1\/20140123-300rise-otro.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/brian-k-vaughn-augura-la-cancelacin-de-y-last-man-y-runaways-el-primer-teaser-de-strain-de-guillermo-del-toro-y-carlton-cuse-gal-gadot-dice-haber-firmado-por-triplicado#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uruloki.org\/felipeblog"},{"@type":"ListItem","position":2,"name":"Brian K. Vaughn augura la cancelaci&oacute;n de Y: The Last Man y Runaways, el primer teaser de &quot;The Strain&quot; de Guillermo del Toro y Carlton Cuse, Gal Gadot dice haber firmado por triplicado para ser Wonder Woman, Garret Hedlund podr&iacute;a ser el Capit&aacute;n Garfio en la versi&oacute;n siniestra de Peter Pan, parece ser que Daniel Espinosa es el primer candidato para dirigir Assassin&#8217;s Creed y un par de carteles de 300: el origen de un imperio y Los Juegos del Hambre: Sinsajo&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.uruloki.org\/felipeblog\/#website","url":"https:\/\/www.uruloki.org\/felipeblog\/","name":"Uruloki :: Blog","description":"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uruloki.org\/felipeblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3","name":"Uruloki","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","caption":"Uruloki"},"sameAs":["https:\/\/uruloki.org"],"url":"https:\/\/www.uruloki.org\/felipeblog\/author\/admin-2-2-2"}]}},"_links":{"self":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/12057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/comments?post=12057"}],"version-history":[{"count":1,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/12057\/revisions"}],"predecessor-version":[{"id":12058,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/12057\/revisions\/12058"}],"wp:attachment":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/media?parent=12057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/categories?post=12057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/tags?post=12057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}