{"id":10801,"date":"2013-07-19T10:57:24","date_gmt":"2013-07-19T08:57:24","guid":{"rendered":"https:\/\/uruloki.org\/felipeblog\/?p=10801"},"modified":"2013-07-19T10:57:24","modified_gmt":"2013-07-19T08:57:24","slug":"un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home","status":"publish","type":"post","link":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home","title":{"rendered":"Un par de nuevos carteles de Insidious: Chapter 2 y El s&eacute;ptimo hijo (me aburro) acompa&ntilde;an a la precuela animada de Snowpiercer de Joon-ho Bong y al primer clip de El juego de Ender (homenaje a Mazer Rackham)&#8230;"},"content":{"rendered":"<p>M&aacute;s y m&aacute;s noticias que esto es una vor&aacute;gine sin descanso. Alucinante. Como el texto comienza a ser escaso, me voy a quedar sopa, hago un recorrido r&aacute;pido por las cuatro cosas que decoran este post. Primero este nuevo cartel de <strong>Insidious: Chapter 2<\/strong> (2013) de <strong>James Wan<\/strong>, ya es hora de volver a centrarse en los fantasmas y no tanto en el aspecto familiar del film&#8230; aunque sea el aspecto m&aacute;s siniestro. Estoy convencido de que si disfrutaste del primer film en el 2010 este no defraudar&aacute;.<\/p>\n<p class=\"centrado\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2013-2\/20130718-insidious2.jpg\" alt=\"Un nuevo cartel de Insidious: Chapter 2\" width=\"550\" height=\"778\" \/><br \/><em>Un nuevo cartel de Insidious: Chapter 2 <a href=\"http:\/\/www.impawards.com\/updates\/20130718a.html\" target=\"_blank\">v&iacute;a IMPAwards<\/a><\/em><\/p>\n<p>Tambi&eacute;n tenemos un notable ejercicio de animaci&oacute;n que viene a ser la &quot;precuela&quot; o explicaci&oacute;n de todo lo que veremos que ocurre en <strong>Snowpiercer<\/strong> (2013) de <strong>Joon-ho Bong<\/strong>, ese film de ciencia ficci&oacute;n que adapta la obra comiquera <strong>&quot;El rompehielos&quot;<\/strong> de <strong>Jacques Lob<\/strong> y <strong>Jean-Marc Rochette<\/strong>. Producida por el propio <strong>Joon-ho Bong<\/strong> y <strong>Chan-wook Park<\/strong>, cuenta con un reparto tremendo con nombres como los de <strong>John Hurt<\/strong>, <strong>Chris Evans<\/strong>, Tilda<strong> Swinton<\/strong>, <strong>Kang-Ho Song<\/strong> o  <strong>Jamie Bell<\/strong>. En la pel&iacute;cula se nos contar&aacute; el destino de los &uacute;ltimos supervivientes de la raza humana se encuentran a bordo de un gigantesco tren en marcha continua. El viaje desde los vagones de cola, donde se amontonan las clases m&aacute;s bajas hasta los elitistas vagones de cabeza representa todo un trayecto por las mayores miserias del ser humano. A modo de descenso de Dante a los infiernos, cada vag&oacute;n supone una etapa en la que se representan las tropel&iacute;as que el ser humano suele realizar a sus cong&eacute;neres, profundizando cada vez m&aacute;s en las absurdas excusas que intentan justificar estos comportamientos. Este film animado precuela de casi 5 minutos sirve para explicar las razones de la degeneraci&oacute;n mostrada en <strong>Snowpiercer<\/strong>.<\/p>\n<div class=\"video\"><iframe loading=\"lazy\" width=\"625\" height=\"380\" src=\"\/\/www.youtube.com\/embed\/Wb3UQgb2ObA\"><\/iframe><\/div>\n<p>Y si, otro cartel m&aacute;s de <strong>El s&eacute;ptimo hijo<\/strong> (<em>Seventh Son<\/em>, 2013) de <strong>Sergei Bodrov<\/strong>. Ahora es el turno de la villana de la pel&iacute;cula, <strong>Julianne Moore<\/strong> como la <strong>Madre Malkin<\/strong>, la bruja piruja que le toca las narices al <strong>Maestro Gregory<\/strong> (<strong>Jeff Bridges<\/strong>) y que ser&aacute; la raz&oacute;n de que este tenga que buscar y formar en tiempo record al nuevo salvador de la humanidad.<\/p>\n<p class=\"centrado\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/uruloki.org\/felipeblog\/images2013-2\/20130718-seventhson.jpg\" alt=\"Otro cartel m&aacute;s de El s&eacute;ptimo hijo, y van mil\" width=\"550\" height=\"818\" \/><br \/><em>Otro cartel m&aacute;s de El s&eacute;ptimo hijo, y van mil <a href=\"http:\/\/www.impawards.com\/updates\/20130718b.html\" target=\"_blank\">v&iacute;a IMPAwards, para variar<\/a><\/em><\/p>\n<p>Para terminar el primer clip de <strong>El juego de Ender<\/strong> (<em>Ender&#8217;s Game<\/em>, 2014) de <strong>Gavin Hood<\/strong>. El clip nos introduce en el destino que sufre nuestro planeta tras la primera invasi&oacute;n extraterrestre y como un gran h&eacute;roe, <strong>Mazer Rackham<\/strong> (<strong>Ben Kingsley<\/strong>), fue el que sirvi&oacute; de ejemplo para dar la vuelta a lo que parec&iacute;a el fin de la humanidad. Ahora el <strong>Coronel Graff<\/strong> (<strong>Harrison Ford<\/strong>) nos da la bienvenida a la escuela de batalla.<\/p>\n<div class=\"video\"><iframe loading=\"lazy\" width=\"625\" height=\"380\" src=\"http:\/\/movies.yahoo.com\/video\/enders-game-comic-con-footage-233048909.html?format=embed&#038;player_autoplay=false\"><\/iframe><\/div>\n","protected":false},"excerpt":{"rendered":"<p>M&aacute;s y m&aacute;s noticias que esto es una vor&aacute;gine sin descanso. Alucinante. Como el texto comienza a ser escaso, me voy a quedar sopa, hago un recorrido r&aacute;pido por las cuatro cosas que decoran este post. Primero este nuevo cartel de Insidious: Chapter 2 (2013) de James Wan, ya es hora de volver a centrarse [&hellip;]<\/p>\n","protected":false},"author":28,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[8,12,9,2586],"tags":[3389,740,2371,2456,1629],"class_list":["post-10801","post","type-post","status-publish","format-standard","hentry","category-cine-de-ciencia-ficcion","category-cine-de-fantasia","category-cine-de-terror","category-comic-con-2013","tag-comic-con-2013","tag-enders-game","tag-insidious-chapter-2","tag-snowpiercer","tag-the-seventh-son"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Un par de nuevos carteles de Insidious: Chapter 2 y El s&eacute;ptimo hijo (me aburro) acompa&ntilde;an a la precuela animada de Snowpiercer de Joon-ho Bong y al primer clip de El juego de Ender (homenaje a Mazer Rackham)... - Uruloki :: Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un par de nuevos carteles de Insidious: Chapter 2 y El s&eacute;ptimo hijo (me aburro) acompa&ntilde;an a la precuela animada de Snowpiercer de Joon-ho Bong y al primer clip de El juego de Ender (homenaje a Mazer Rackham)... - Uruloki :: Blog\" \/>\n<meta property=\"og:description\" content=\"M&aacute;s y m&aacute;s noticias que esto es una vor&aacute;gine sin descanso. Alucinante. Como el texto comienza a ser escaso, me voy a quedar sopa, hago un recorrido r&aacute;pido por las cuatro cosas que decoran este post. Primero este nuevo cartel de Insidious: Chapter 2 (2013) de James Wan, ya es hora de volver a centrarse [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home\" \/>\n<meta property=\"og:site_name\" content=\"Uruloki :: Blog\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/uruloki.org\" \/>\n<meta property=\"article:published_time\" content=\"2013-07-19T08:57:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/uruloki.org\/felipeblog\/images2013-2\/20130718-insidious2.jpg\" \/>\n<meta name=\"author\" content=\"Uruloki\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@uruloki\" \/>\n<meta name=\"twitter:site\" content=\"@uruloki\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Uruloki\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home\"},\"author\":{\"name\":\"Uruloki\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"headline\":\"Un par de nuevos carteles de Insidious: Chapter 2 y El s&eacute;ptimo hijo (me aburro) acompa&ntilde;an a la precuela animada de Snowpiercer de Joon-ho Bong y al primer clip de El juego de Ender (homenaje a Mazer Rackham)&#8230;\",\"datePublished\":\"2013-07-19T08:57:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home\"},\"wordCount\":545,\"commentCount\":5,\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2013-2\\\/20130718-insidious2.jpg\",\"keywords\":[\"Comic-Con 2013\",\"Ender's Game\",\"Insidious Chapter 2\",\"Snowpiercer\",\"The Seventh Son\"],\"articleSection\":[\"Cine de Ciencia Ficci\u00f3n\",\"Cine de Fantas\u00eda\",\"Cine de Terror\",\"Comic-Con 2013\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home\",\"name\":\"Un par de nuevos carteles de Insidious: Chapter 2 y El s&eacute;ptimo hijo (me aburro) acompa&ntilde;an a la precuela animada de Snowpiercer de Joon-ho Bong y al primer clip de El juego de Ender (homenaje a Mazer Rackham)... - Uruloki :: Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2013-2\\\/20130718-insidious2.jpg\",\"datePublished\":\"2013-07-19T08:57:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home#primaryimage\",\"url\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2013-2\\\/20130718-insidious2.jpg\",\"contentUrl\":\"https:\\\/\\\/uruloki.org\\\/felipeblog\\\/images2013-2\\\/20130718-insidious2.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/cine-de-ciencia-ficcion\\\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un par de nuevos carteles de Insidious: Chapter 2 y El s&eacute;ptimo hijo (me aburro) acompa&ntilde;an a la precuela animada de Snowpiercer de Joon-ho Bong y al primer clip de El juego de Ender (homenaje a Mazer Rackham)&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#website\",\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/\",\"name\":\"Uruloki :: Blog\",\"description\":\"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/#\\\/schema\\\/person\\\/ddba06ddaa27edf0c370460d05c51bb3\",\"name\":\"Uruloki\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g\",\"caption\":\"Uruloki\"},\"sameAs\":[\"https:\\\/\\\/uruloki.org\"],\"url\":\"https:\\\/\\\/www.uruloki.org\\\/felipeblog\\\/author\\\/admin-2-2-2\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un par de nuevos carteles de Insidious: Chapter 2 y El s&eacute;ptimo hijo (me aburro) acompa&ntilde;an a la precuela animada de Snowpiercer de Joon-ho Bong y al primer clip de El juego de Ender (homenaje a Mazer Rackham)... - Uruloki :: Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home","og_locale":"es_ES","og_type":"article","og_title":"Un par de nuevos carteles de Insidious: Chapter 2 y El s&eacute;ptimo hijo (me aburro) acompa&ntilde;an a la precuela animada de Snowpiercer de Joon-ho Bong y al primer clip de El juego de Ender (homenaje a Mazer Rackham)... - Uruloki :: Blog","og_description":"M&aacute;s y m&aacute;s noticias que esto es una vor&aacute;gine sin descanso. Alucinante. Como el texto comienza a ser escaso, me voy a quedar sopa, hago un recorrido r&aacute;pido por las cuatro cosas que decoran este post. Primero este nuevo cartel de Insidious: Chapter 2 (2013) de James Wan, ya es hora de volver a centrarse [&hellip;]","og_url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home","og_site_name":"Uruloki :: Blog","article_publisher":"https:\/\/www.facebook.com\/uruloki.org","article_published_time":"2013-07-19T08:57:24+00:00","og_image":[{"url":"https:\/\/uruloki.org\/felipeblog\/images2013-2\/20130718-insidious2.jpg","type":"","width":"","height":""}],"author":"Uruloki","twitter_card":"summary_large_image","twitter_creator":"@uruloki","twitter_site":"@uruloki","twitter_misc":{"Escrito por":"Uruloki","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home#article","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home"},"author":{"name":"Uruloki","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"headline":"Un par de nuevos carteles de Insidious: Chapter 2 y El s&eacute;ptimo hijo (me aburro) acompa&ntilde;an a la precuela animada de Snowpiercer de Joon-ho Bong y al primer clip de El juego de Ender (homenaje a Mazer Rackham)&#8230;","datePublished":"2013-07-19T08:57:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home"},"wordCount":545,"commentCount":5,"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/images2013-2\/20130718-insidious2.jpg","keywords":["Comic-Con 2013","Ender's Game","Insidious Chapter 2","Snowpiercer","The Seventh Son"],"articleSection":["Cine de Ciencia Ficci\u00f3n","Cine de Fantas\u00eda","Cine de Terror","Comic-Con 2013"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home","url":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home","name":"Un par de nuevos carteles de Insidious: Chapter 2 y El s&eacute;ptimo hijo (me aburro) acompa&ntilde;an a la precuela animada de Snowpiercer de Joon-ho Bong y al primer clip de El juego de Ender (homenaje a Mazer Rackham)... - Uruloki :: Blog","isPartOf":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home#primaryimage"},"image":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home#primaryimage"},"thumbnailUrl":"https:\/\/uruloki.org\/felipeblog\/images2013-2\/20130718-insidious2.jpg","datePublished":"2013-07-19T08:57:24+00:00","author":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3"},"breadcrumb":{"@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home#primaryimage","url":"https:\/\/uruloki.org\/felipeblog\/images2013-2\/20130718-insidious2.jpg","contentUrl":"https:\/\/uruloki.org\/felipeblog\/images2013-2\/20130718-insidious2.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.uruloki.org\/felipeblog\/cine-de-ciencia-ficcion\/un-par-de-nuevos-carteles-de-insidious-chapter-2-y-el-sptimo-hijo-me-aburro-acompaan-a-la-precuela-animada-de-snowpiercer-de-joon-ho-bong-y-al-primer-clip-de-el-juego-de-ender-home#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.uruloki.org\/felipeblog"},{"@type":"ListItem","position":2,"name":"Un par de nuevos carteles de Insidious: Chapter 2 y El s&eacute;ptimo hijo (me aburro) acompa&ntilde;an a la precuela animada de Snowpiercer de Joon-ho Bong y al primer clip de El juego de Ender (homenaje a Mazer Rackham)&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/www.uruloki.org\/felipeblog\/#website","url":"https:\/\/www.uruloki.org\/felipeblog\/","name":"Uruloki :: Blog","description":"Blog de cine, terror, ciencia ficci\u00f3n, fantas\u00eda y c\u00f3mics","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uruloki.org\/felipeblog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.uruloki.org\/felipeblog\/#\/schema\/person\/ddba06ddaa27edf0c370460d05c51bb3","name":"Uruloki","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68d5301c5f52ba88fd63f02c75b8c4d1b3c3fc4b21e2998a1e98c4b3a54d9f7c?s=96&d=mm&r=g","caption":"Uruloki"},"sameAs":["https:\/\/uruloki.org"],"url":"https:\/\/www.uruloki.org\/felipeblog\/author\/admin-2-2-2"}]}},"_links":{"self":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/10801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/users\/28"}],"replies":[{"embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/comments?post=10801"}],"version-history":[{"count":2,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/10801\/revisions"}],"predecessor-version":[{"id":10805,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/posts\/10801\/revisions\/10805"}],"wp:attachment":[{"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/media?parent=10801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/categories?post=10801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.uruloki.org\/felipeblog\/wp-json\/wp\/v2\/tags?post=10801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}